{"id":3121678,"date":"2023-12-01T01:20:00","date_gmt":"2023-12-01T06:20:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/book\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\/"},"modified":"2025-10-12T01:15:45","modified_gmt":"2025-10-12T05:15:45","slug":"el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin","status":"publish","type":"fpb_book","link":"https:\/\/www.friendsjournal.org\/es\/book\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\/","title":{"rendered":"El jarr\u00f3n de Peng: un cuento popular chino Y Di la verdad, pangol\u00edn"},"content":{"rendered":"\n<h3 class=\"wp-block-heading has-text-align-center\"><strong><em>Recontado por Angus y Michael Yuen-Killick, ilustrado por Paolo Proietti. Red Comet Press, 2023. 28 p\u00e1ginas. 18,99 $\/tapa dura; 10,99 $\/eBook. Recomendado para edades de 4 a 8 a\u00f1os.    <\/em><\/strong><\/h3>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2023\/12\/Tell.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2023\/12\/Tell.jpg\" alt=\"\" class=\"wp-image-3067251\" style=\"aspect-ratio:0.998003992015968;width:268px;height:auto\" srcset=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2023\/12\/Tell.jpg 500w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2023\/12\/Tell-300x300.jpg 300w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2023\/12\/Tell-150x150.jpg 150w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2023\/12\/Tell-100x100.jpg 100w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong><em>Por Melinda Beatty, ilustrado por Paola Escobar. Anne Schwartz Books, 2022. 40 p\u00e1ginas. 18,99 $\/tapa dura; 8,99 $\/eBook. Recomendado para edades de 4 a 8 a\u00f1os.    <\/em><\/strong><\/h3>\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/bookshop.org\/lists\/friends-journal-reviews-december-2023\" target=\"_blank\" rel=\"noreferrer noopener\">Comprar en QuakerBooks<\/a><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\">Escasean los buenos libros infantiles centrados en la veracidad, pero tenemos la suerte de contar con dos muy diferentes. Ambos presentan a un personaje principal en una situaci\u00f3n en la que decir la verdad es dif\u00edcil. <\/p>\n\n<p class=\"wp-block-paragraph\">En una fiel adaptaci\u00f3n de un antiguo cuento popular chino, Peng se enfrenta a un dilema. El emperador es viejo y no tiene hijos, por lo que ha decidido elegir un sucesor entre los ni\u00f1os. Los reuni\u00f3, les dio a cada ni\u00f1o una sola semilla y les indic\u00f3 que la cultivaran durante un a\u00f1o. Despu\u00e9s de ese tiempo, deb\u00edan regresar al palacio y mostrar lo que hab\u00eda crecido. A pesar del cuidado esmerado y amoroso, la semilla de Peng ni siquiera ha germinado. Para evitar la humillaci\u00f3n p\u00fablica, les dice a sus padres que no quiere volver al palacio. Ellos le dicen a Peng que debe ir y decirle al emperador que hizo lo posible, pero que fracas\u00f3.      <\/p>\n\n<p class=\"wp-block-paragraph\">Cada uno de los otros ni\u00f1os llega portando plantas exuberantes con flores coloridas. El emperador inspecciona cada una, pero cuando ve el jarr\u00f3n de Peng y escucha su informe, declara a Peng su heredero y revela que las semillas que distribuy\u00f3 nunca podr\u00edan brotar. La honestidad y la valent\u00eda son las cualidades que buscaba en su sucesor. Solo Peng tuvo el valor de traer un jarr\u00f3n vac\u00edo y decir la verdad.   <\/p>\n\n<p class=\"wp-block-paragraph\">Esta es una historia que los prelectores pueden seguir, con una lecci\u00f3n que pueden entender. El texto escaso cobra vida en las ilustraciones suaves y acogedoras de Paolo Proietti, con las expresiones en los rostros de los personajes que revelan claramente sus sentimientos. <em>El jarr\u00f3n de Peng<\/em> podr\u00eda servir como una gran invitaci\u00f3n para que los ni\u00f1os de una clase de la escuela del Primer D\u00eda compartan sus propios momentos de duda e incertidumbre, abri\u00e9ndolos a una discusi\u00f3n sobre el valor y la veracidad. <\/p>\n\n<p class=\"wp-block-paragraph\">Un pangol\u00edn es un peque\u00f1o mam\u00edfero en peligro de extinci\u00f3n que vive en los bosques y praderas de \u00c1frica y Asia. <em>Di la verdad, pangol\u00edn<\/em><strong><em> <\/em><\/strong>est\u00e1 ambientado en una corte real y comienza con una crisis. \u00a1Pangol\u00edn est\u00e1 en problemas! Estaba jugando en el columpio real cuando las cuerdas se rompieron. Sabe que tiene que dec\u00edrselo a la Reina, pero \u00bfqu\u00e9 dir\u00e1?   <\/p>\n\n<p class=\"wp-block-paragraph\">Mientras que Peng depend\u00eda del buen consejo de sus padres para que lo guiaran, Pangol\u00edn recurre a sus amigos: Tej\u00f3n, Ganso, Zorro, Gato y Carlino. Sus sugerencias van desde lo poco pr\u00e1ctico (un m\u00fasico que necesitaba cuerdas nuevas tom\u00f3 las cuerdas) hasta lo absurdo (abducci\u00f3n alien\u00edgena). Pero cuando Pangol\u00edn intenta seguir sus indicaciones, se pone nervioso y se confunde. La sabia Reina le pregunta a Pangol\u00edn qu\u00e9 le preocupa. Su confesi\u00f3n tartamudeada es recompensada con el perd\u00f3n y la oportunidad de hacer las cosas bien. Las v\u00edvidas ilustraciones de Paola Escobar son cautivadoras. Nos llevan a trav\u00e9s de una historia que salta brillantemente de escena en escena.      <\/p>\n\n<p class=\"wp-block-paragraph\">Ambos libros ofrecen oportunidades para interactuar con las mentes de los j\u00f3venes lectores. Si bien la f\u00e1bula de Peng se presta f\u00e1cilmente a un momento de ense\u00f1anza, las historias fant\u00e1sticas de Pangol\u00edn son ciertamente m\u00e1s entretenidas y pueden conducir a una discusi\u00f3n sobre los costos de mentir. <\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n<p class=\"wp-block-paragraph\"><strong>Paul Buckley ha escrito numerosos art\u00edculos y libros sobre la historia, la fe y la pr\u00e1ctica cu\u00e1queras. Se re\u00fane para adorar con Clear Creek Meeting en Richmond, Indiana, y viaja en el ministerio instando a la renovaci\u00f3n espiritual entre Amigos. Su libro m\u00e1s reciente es   <\/strong><strong>\n  <em>El cu\u00e1querismo primitivo revivido: vivir como Amigos en el siglo XXI<\/em>\n<\/strong><strong>.<\/strong><\/p>\n","protected":false},"author":5090,"featured_media":3093285,"comment_status":"open","ping_status":"closed","template":"","categories":[10532,10323],"fpb_issue_category":[10709],"class_list":["post-3121678","fpb_book","type-fpb_book","status-publish","has-post-thumbnail","hentry","category-libros-de-diciembre-de-2023-estanteria-de-jovenes-amigos","category-resenas-de-libros-cuaqueros","fpb_issue_category-la-administracion-como-un-testimonio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El jarr\u00f3n de Peng: un cuento popular chino Y Di la verdad, pangol\u00edn - Friends Journal<\/title>\n<meta name=\"description\" content=\"Escasean los buenos libros infantiles centrados en la veracidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/book\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RESE\u00d1A: El jarr\u00f3n de Peng: un cuento popular chino Y Di la verdad, pangol\u00edn\" \/>\n<meta property=\"og:description\" content=\"Escasean los buenos libros infantiles centrados en la veracidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/book\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-12T05:15:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2023\/12\/PnegTell_FBcrop.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"RESE\u00d1A: El jarr\u00f3n de Peng: un cuento popular chino Y Di la verdad, pangol\u00edn\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\\\/\",\"name\":\"El jarr\u00f3n de Peng: un cuento popular chino Y Di la verdad, pangol\u00edn - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Pengs.jpg\",\"datePublished\":\"2023-12-01T06:20:00+00:00\",\"dateModified\":\"2025-10-12T05:15:45+00:00\",\"description\":\"Escasean los buenos libros infantiles centrados en la veracidad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Pengs.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Pengs.jpg\",\"width\":500,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Books\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El jarr\u00f3n de Peng: un cuento popular chino Y Di la verdad, pangol\u00edn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El jarr\u00f3n de Peng: un cuento popular chino Y Di la verdad, pangol\u00edn - Friends Journal","description":"Escasean los buenos libros infantiles centrados en la veracidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/book\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\/","og_locale":"es_ES","og_type":"article","og_title":"RESE\u00d1A: El jarr\u00f3n de Peng: un cuento popular chino Y Di la verdad, pangol\u00edn","og_description":"Escasean los buenos libros infantiles centrados en la veracidad.","og_url":"https:\/\/www.friendsjournal.org\/es\/book\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_modified_time":"2025-10-12T05:15:45+00:00","og_image":[{"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2023\/12\/PnegTell_FBcrop.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"RESE\u00d1A: El jarr\u00f3n de Peng: un cuento popular chino Y Di la verdad, pangol\u00edn","twitter_site":"@friendsournal","twitter_misc":{"Est. reading time":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/book\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\/","url":"https:\/\/www.friendsjournal.org\/es\/book\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\/","name":"El jarr\u00f3n de Peng: un cuento popular chino Y Di la verdad, pangol\u00edn - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2023\/12\/Pengs.jpg","datePublished":"2023-12-01T06:20:00+00:00","dateModified":"2025-10-12T05:15:45+00:00","description":"Escasean los buenos libros infantiles centrados en la veracidad.","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/book\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/book\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2023\/12\/Pengs.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2023\/12\/Pengs.jpg","width":500,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/book\/el-jarron-de-peng-un-cuento-popular-chino-y-di-la-verdad-pangolin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Books","item":"https:\/\/www.friendsjournal.org\/es\/book\/"},{"@type":"ListItem","position":3,"name":"El jarr\u00f3n de Peng: un cuento popular chino Y Di la verdad, pangol\u00edn"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"fpb_reviewer_name":"Paul Buckley","fpb_book_details":{"author":"","pricing":false,"quakerbooks_link":"","category_issue_link":null},"fpb_reviewer_profile_picture":false},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book\/3121678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/fpb_book"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3121678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3093285"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3121678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3121678"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3121678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}