{"id":3121853,"date":"2022-11-01T00:40:00","date_gmt":"2022-11-01T04:40:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/book\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\/"},"modified":"2025-10-12T01:28:54","modified_gmt":"2025-10-12T05:28:54","slug":"restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada","status":"publish","type":"fpb_book","link":"https:\/\/www.friendsjournal.org\/es\/book\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\/","title":{"rendered":"Restauraci\u00f3n de la vida salvaje: la nueva ciencia radical de la recuperaci\u00f3n ecol\u00f3gica (la edici\u00f3n ilustrada)"},"content":{"rendered":"\n<h3 class=\"wp-block-heading has-text-align-center\"><em>Por Paul Jepson y Cain Blythe. The MIT Press, 2022. 224 p\u00e1ginas. 29,95 $\/tapa dura.   <\/em><\/h3>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/bookshop.org\/p\/books\/rewilding-the-radical-new-science-of-ecological-recovery-the-illustrated-edition-paul-jepson\/18365567?ean=9780262046763&amp;next=t\" target=\"_blank\" rel=\"noreferrer noopener\">Comprar en QuakerBooks<\/a><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\">Mientras preparaba esta rese\u00f1a, me llam\u00f3 la atenci\u00f3n un art\u00edculo del <em>New York Times<\/em>. Trataba sobre un hombre que se hab\u00eda hecho cargo del rancho de su padre en el noreste de Nevada y que hab\u00eda cambiado su actitud con respecto a los castores que abundaban en la tierra. Su padre hab\u00eda destruido sus presas con regularidad, pero el hijo decidi\u00f3 asociarse con los castores. El a\u00f1o pasado, durante una sequ\u00eda extrema, su ganado tuvo mucha agua en las charcas de los castores. Y cuando una gran lluvia podr\u00eda haber inundado la tierra, las presas de los castores ralentizaron el agua y permitieron que se filtrara. Este es un hermoso ejemplo de asociaci\u00f3n con la naturaleza: un ejemplo actual y real de restauraci\u00f3n de la vida salvaje.     <\/p>\n\n<p class=\"wp-block-paragraph\">Publicado originalmente en 2020 por Icon Books, con sede en Londres, <em>Rewilding<\/em> ya est\u00e1 disponible para los lectores estadounidenses como una edici\u00f3n ilustrada de tapa dura de MIT Press en Cambridge, Massachusetts. Como advertencia, perm\u00edtanme decir que el libro es un libro de ciencia para no cient\u00edficos, pero tuve que buscar algunas palabras para comprender completamente lo que estaba leyendo. Aparte de esa advertencia, este es un libro maravilloso y esperanzador sobre una ciencia de vanguardia que se ocupa de la tierra y sus habitantes. Los autores explican que la conservaci\u00f3n convencional norteamericana trabaja para recrear una l\u00ednea de base de la \u00e9poca del contacto europeo (alrededor de 1492), mientras que en Europa, la l\u00ednea de base se establece para mediados del siglo XIX, antes del impacto de la industrializaci\u00f3n. El objetivo actual es reconstruir el mundo natural para que refleje esos tiempos relativamente recientes.    <\/p>\n\n<p class=\"wp-block-paragraph\">La ciencia de la restauraci\u00f3n de la vida salvaje, sin embargo, establece su l\u00ednea de base hace unos 11.700 a\u00f1os, la \u00e9poca aproximada del asentamiento humano en Norteam\u00e9rica. Con las nuevas posibilidades de la investigaci\u00f3n del ADN en hallazgos antiguos, podemos aprender qu\u00e9 flora y fauna viv\u00edan aqu\u00ed antes del asentamiento humano y c\u00f3mo y d\u00f3nde viv\u00edan. Los autores explican:  <\/p>\n\n<p class=\"wp-block-paragraph\">[La restauraci\u00f3n de la vida salvaje] es la nueva comprensi\u00f3n de los procesos ecol\u00f3gicos que surge de la interacci\u00f3n entre el pastoreo de los herb\u00edvoros y la estructura de la vegetaci\u00f3n y las perturbaciones naturales, lo que representa la contribuci\u00f3n central de la ciencia de la restauraci\u00f3n de la vida salvaje a las disciplinas m\u00e1s amplias de la restauraci\u00f3n ecol\u00f3gica y la ciencia de la conservaci\u00f3n.<\/p>\n\n<p class=\"wp-block-paragraph\">Aunque la ciencia de la restauraci\u00f3n de la vida salvaje es nueva, ya existen ejemplos de algunos \u00e9xitos, como la reintroducci\u00f3n de lobos en el Parque Nacional de Yellowstone, donde se han producido cambios sorprendentes y positivos en toda la ecolog\u00eda del parque desde que los lobos se han asentado. Hace m\u00e1s de 30 a\u00f1os, los Pa\u00edses Bajos reintrodujeron una mezcla de especies de ciervos salvajes y razas \u201csalvajizadas\u00bb de ponis y ganado. Las aves y los peque\u00f1os mam\u00edferos se recuperaron, pero exist\u00eda la preocupaci\u00f3n de que dejar que el ganado y los ponis murieran de hambre en los duros inviernos fuera cruel. Esto llev\u00f3 a comprender que, si bien los animales domesticados est\u00e1n protegidos del trato cruel, los animales restaurados a la vida salvaje est\u00e1n destinados a ser salvajes, y los animales salvajes mueren con regularidad en la naturaleza. Este es uno de los muchos desaf\u00edos para la nueva ciencia. La reintroducci\u00f3n de lobos en Yellowstone encontr\u00f3 una feroz oposici\u00f3n, pero los resultados sorprendieron y complacieron a la mayor\u00eda.     <\/p>\n\n<p class=\"wp-block-paragraph\">Y no solo la naturaleza se recupera cuando se alivia de la huella humana, sino que los sistemas terrestres restaurados a la vida salvaje tienen el potencial de secuestrar m\u00e1s carbono en sus suelos, en las arboledas y en la fauna animal expandida. Esto significa que puede ayudar a revertir el avance de la crisis clim\u00e1tica. <\/p>\n\n<p class=\"wp-block-paragraph\">En la introducci\u00f3n, los autores comparten su deleite con la sugerencia de la editorial de una versi\u00f3n ilustrada. Escribieron: \u201cComo dice el viejo adagio, &#8216;una imagen vale m\u00e1s que mil palabras'\u00bb, y estoy de acuerdo. Las fotograf\u00edas en color de animales emocionantes, como los caballos Konik, los Tauros (animales parecidos al ganado) y las tortugas gigantes de Aldabra (elegidas por su similitud con los animales que vagaban por la tierra hace miles de a\u00f1os) dan vida a la narraci\u00f3n. Y las excelentes infograf\u00edas me ayudaron a imaginar cu\u00e1l podr\u00eda ser el resultado en un proyecto exitoso de restauraci\u00f3n de la vida salvaje. Estas im\u00e1genes a\u00f1adidas recientemente me animaron con frecuencia a detenerme a reflexionar y comprender esta nueva y radical forma de recuperaci\u00f3n ecol\u00f3gica.    <\/p>\n\n<p class=\"wp-block-paragraph\">\u00bfPor qu\u00e9 querr\u00edas leer un libro sobre la reintroducci\u00f3n de megaherb\u00edvoros, carn\u00edvoros y pastores en varios paisajes? He llegado a creer que este enfoque de restauraci\u00f3n de la vida salvaje para respetar los sistemas naturales y el deseo de co-crear y asociarse con la tierra y todos sus habitantes refleja la nueva comprensi\u00f3n de los Amigos de que hay algo de Dios en toda la Creaci\u00f3n. Leer este libro le da al lector la oportunidad de defender y apoyar esta nueva ciencia, y considerar c\u00f3mo los humanos podr\u00edan seguir adelante en este mundo problem\u00e1tico, incluyendo el cuidado de la Tierra en nuestro trabajo, juego y culto cotidianos.  <\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n<p class=\"wp-block-paragraph\"><strong>Ruah Swennerfelt es miembro del Meeting de Middlebury (Vt.), donde forma parte del Comit\u00e9 de Cuidado de la Tierra. Ella y su marido, Louis Cox, son colonos en tierras no cedidas de la naci\u00f3n Abenaki. Cultivan la mayor\u00eda de las verduras y frutas que comen, sinti\u00e9ndose arraigados al lugar y viviendo vidas ricas y satisfactorias.  <\/strong><\/p>\n","protected":false},"author":5090,"featured_media":3089561,"comment_status":"open","ping_status":"closed","template":"","categories":[10323,10517],"fpb_issue_category":[10696],"class_list":["post-3121853","fpb_book","type-fpb_book","status-publish","has-post-thumbnail","hentry","category-resenas-de-libros-cuaqueros","category-resenas-de-libros-de-noviembre-de-2022","fpb_issue_category-ficcion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restauraci\u00f3n de la vida salvaje: la nueva ciencia radical de la recuperaci\u00f3n ecol\u00f3gica (la edici\u00f3n ilustrada) - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/book\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RESE\u00d1A: Restauraci\u00f3n de la vida salvaje: la nueva ciencia radical de la recuperaci\u00f3n ecol\u00f3gica (la edici\u00f3n ilustrada)\" \/>\n<meta property=\"og:description\" content=\"Por Paul Jepson y Cain Blythe. The MIT Press, 2022. 224 p\u00e1ginas. 29,95 $\/tapa dura. Mientras preparaba esta rese\u00f1a, me&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/book\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-12T05:28:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/10\/ReWilding_FBcrop.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"RESE\u00d1A: Restauraci\u00f3n de la vida salvaje: la nueva ciencia radical de la recuperaci\u00f3n ecol\u00f3gica (la edici\u00f3n ilustrada)\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\\\/\",\"name\":\"Restauraci\u00f3n de la vida salvaje: la nueva ciencia radical de la recuperaci\u00f3n ecol\u00f3gica (la edici\u00f3n ilustrada) - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/RewildingIllustrated.jpg\",\"datePublished\":\"2022-11-01T04:40:00+00:00\",\"dateModified\":\"2025-10-12T05:28:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/RewildingIllustrated.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/RewildingIllustrated.jpg\",\"width\":500,\"height\":690},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Books\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Restauraci\u00f3n de la vida salvaje: la nueva ciencia radical de la recuperaci\u00f3n ecol\u00f3gica (la edici\u00f3n ilustrada)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restauraci\u00f3n de la vida salvaje: la nueva ciencia radical de la recuperaci\u00f3n ecol\u00f3gica (la edici\u00f3n ilustrada) - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/book\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\/","og_locale":"es_ES","og_type":"article","og_title":"RESE\u00d1A: Restauraci\u00f3n de la vida salvaje: la nueva ciencia radical de la recuperaci\u00f3n ecol\u00f3gica (la edici\u00f3n ilustrada)","og_description":"Por Paul Jepson y Cain Blythe. The MIT Press, 2022. 224 p\u00e1ginas. 29,95 $\/tapa dura. Mientras preparaba esta rese\u00f1a, me&hellip;","og_url":"https:\/\/www.friendsjournal.org\/es\/book\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_modified_time":"2025-10-12T05:28:54+00:00","og_image":[{"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/10\/ReWilding_FBcrop.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"RESE\u00d1A: Restauraci\u00f3n de la vida salvaje: la nueva ciencia radical de la recuperaci\u00f3n ecol\u00f3gica (la edici\u00f3n ilustrada)","twitter_site":"@friendsournal","twitter_misc":{"Est. reading time":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/book\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\/","url":"https:\/\/www.friendsjournal.org\/es\/book\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\/","name":"Restauraci\u00f3n de la vida salvaje: la nueva ciencia radical de la recuperaci\u00f3n ecol\u00f3gica (la edici\u00f3n ilustrada) - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/10\/RewildingIllustrated.jpg","datePublished":"2022-11-01T04:40:00+00:00","dateModified":"2025-10-12T05:28:54+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/book\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/book\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/10\/RewildingIllustrated.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/10\/RewildingIllustrated.jpg","width":500,"height":690},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/book\/restauracion-de-la-vida-salvaje-la-nueva-ciencia-radical-de-la-recuperacion-ecologica-la-edicion-ilustrada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Books","item":"https:\/\/www.friendsjournal.org\/es\/book\/"},{"@type":"ListItem","position":3,"name":"Restauraci\u00f3n de la vida salvaje: la nueva ciencia radical de la recuperaci\u00f3n ecol\u00f3gica (la edici\u00f3n ilustrada)"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"fpb_reviewer_name":"Ruah Swennerfelt","fpb_book_details":{"author":"","pricing":false,"quakerbooks_link":"","category_issue_link":null},"fpb_reviewer_profile_picture":false},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book\/3121853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/fpb_book"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3121853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3089561"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3121853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3121853"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3121853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}