{"id":3121883,"date":"2022-12-01T01:30:00","date_gmt":"2022-12-01T06:30:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/book\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\/"},"modified":"2025-10-12T01:31:23","modified_gmt":"2025-10-12T05:31:23","slug":"palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles","status":"publish","type":"fpb_book","link":"https:\/\/www.friendsjournal.org\/es\/book\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\/","title":{"rendered":"Palabras para hacer un Amigo: una historia en japon\u00e9s e ingl\u00e9s"},"content":{"rendered":"\n<h3 class=\"wp-block-heading has-text-align-center\">Por Donna Jo Napoli, ilustrado por Naoko Stoop. Random House Studio, 2021. 40 p\u00e1ginas. 17,99 $\/tapa dura; 10,99 $\/eBook. Recomendado para edades de 4 a 8 a\u00f1os.    <\/h3>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/bookshop.org\/p\/books\/words-to-make-a-friend-a-story-in-japanese-and-english-donna-jo-napoli\/16215052?ean=9780593122273&amp;next=t\" target=\"_blank\" rel=\"noreferrer noopener\">Comprar en QuakerBooks<\/a><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">La conocida novelista y ling\u00fcista de libros infantiles Donna Jo Napoli tuvo una idea simple pero brillante para introducir la idea de hacerse amigo de alguien cuando no se comparte el mismo idioma. Un d\u00eda de nieve, una nueva chica se muda al lado. Ella habla japon\u00e9s. Cuando las dos chicas empiezan a jugar, se presentan sus idiomas mutuamente. Las chicas eligen naturalmente palabras que rebotan con onomatopeyas. Al ver un p\u00e1jaro carpintero, una dice: \u201cPeck peck\u00bb; la otra dice: \u201cKotsu kotsu\u00bb. Acolchando un mu\u00f1eco de nieve, la chica que habla japon\u00e9s dice: \u201cNade nade\u00bb, mientras que la chica que habla ingl\u00e9s dice: \u201cPat pat pat\u00bb.      <\/p>\n\n<p class=\"wp-block-paragraph\">Debido a que el japon\u00e9s es f\u00e1cil de pronunciar, este libro ser\u00e1 una alegr\u00eda para leer en voz alta. Naoko Stoop se bas\u00f3 en su experiencia personal para hacer las ilustraciones tiernas y encantadoras, que fueron elaboradas con t\u00e9cnicas mixtas sobre madera contrachapada, y luego terminadas digitalmente. Stoop se mud\u00f3 a Canad\u00e1 desde Jap\u00f3n cuando era adulta; tuvo que luchar para conocer gente y hacer nuevos amigos, ya que todo su vocabulario de experiencia era ajeno a la gente que conoc\u00eda. Ha pintado nieve que est\u00e1 tan texturizada que se siente fr\u00eda en la p\u00e1gina, y los personajes simples de las dos chicas son deliciosamente expresivos. Al final, despu\u00e9s del t\u00e9 y la merienda, hacen m\u00e1scaras de origami y descubren que la risa es la misma en todos los idiomas. Este libro podr\u00eda combinarse f\u00e1cilmente con <em>A Hundred Thousand Welcomes<\/em> de Mary Lee Donovan e ilustrado por Lian Cho.     <\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n<p class=\"wp-block-paragraph\"><strong>Alison James es miembro del Meeting de South Starksboro (Vermont).<\/strong><\/p>\n","protected":false},"author":5090,"featured_media":3089747,"comment_status":"open","ping_status":"closed","template":"","categories":[10518,10323],"fpb_issue_category":[10697],"class_list":["post-3121883","fpb_book","type-fpb_book","status-publish","has-post-thumbnail","hentry","category-libros-de-diciembre-de-2022-estanteria-de-jovenes-amigos","category-resenas-de-libros-cuaqueros","fpb_issue_category-expiacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Palabras para hacer un Amigo: una historia en japon\u00e9s e ingl\u00e9s - Friends Journal<\/title>\n<meta name=\"description\" content=\"Una alegr\u00eda biling\u00fce para leer en voz alta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/book\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RESE\u00d1A: Palabras para hacer un Amigo: una historia en japon\u00e9s e ingl\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Una alegr\u00eda biling\u00fce para leer en voz alta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/book\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-12T05:31:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/11\/Words_FBcrop.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"RESE\u00d1A: Palabras para hacer un Amigo: una historia en japon\u00e9s e ingl\u00e9s\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\\\/\",\"name\":\"Palabras para hacer un Amigo: una historia en japon\u00e9s e ingl\u00e9s - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Words.jpg\",\"datePublished\":\"2022-12-01T06:30:00+00:00\",\"dateModified\":\"2025-10-12T05:31:23+00:00\",\"description\":\"Una alegr\u00eda biling\u00fce para leer en voz alta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Words.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Words.jpg\",\"width\":500,\"height\":641},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Books\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Palabras para hacer un Amigo: una historia en japon\u00e9s e ingl\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palabras para hacer un Amigo: una historia en japon\u00e9s e ingl\u00e9s - Friends Journal","description":"Una alegr\u00eda biling\u00fce para leer en voz alta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/book\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\/","og_locale":"es_ES","og_type":"article","og_title":"RESE\u00d1A: Palabras para hacer un Amigo: una historia en japon\u00e9s e ingl\u00e9s","og_description":"Una alegr\u00eda biling\u00fce para leer en voz alta.","og_url":"https:\/\/www.friendsjournal.org\/es\/book\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_modified_time":"2025-10-12T05:31:23+00:00","og_image":[{"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/11\/Words_FBcrop.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"RESE\u00d1A: Palabras para hacer un Amigo: una historia en japon\u00e9s e ingl\u00e9s","twitter_site":"@friendsournal","twitter_misc":{"Est. reading time":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/book\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\/","url":"https:\/\/www.friendsjournal.org\/es\/book\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\/","name":"Palabras para hacer un Amigo: una historia en japon\u00e9s e ingl\u00e9s - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/11\/Words.jpg","datePublished":"2022-12-01T06:30:00+00:00","dateModified":"2025-10-12T05:31:23+00:00","description":"Una alegr\u00eda biling\u00fce para leer en voz alta.","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/book\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/book\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/11\/Words.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/11\/Words.jpg","width":500,"height":641},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/book\/palabras-para-hacer-un-amigo-una-historia-en-japones-e-ingles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Books","item":"https:\/\/www.friendsjournal.org\/es\/book\/"},{"@type":"ListItem","position":3,"name":"Palabras para hacer un Amigo: una historia en japon\u00e9s e ingl\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"fpb_reviewer_name":"Alison James","fpb_book_details":{"author":"","pricing":false,"quakerbooks_link":"","category_issue_link":null},"fpb_reviewer_profile_picture":false},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book\/3121883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/fpb_book"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3121883"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3089747"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3121883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3121883"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3121883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}