{"id":3122038,"date":"2024-05-01T01:05:00","date_gmt":"2024-05-01T05:05:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/book\/estimado-sr-g\/"},"modified":"2025-10-12T01:44:10","modified_gmt":"2025-10-12T05:44:10","slug":"estimado-sr-g","status":"publish","type":"fpb_book","link":"https:\/\/www.friendsjournal.org\/es\/book\/estimado-sr-g\/","title":{"rendered":"Estimado Sr. G"},"content":{"rendered":"\n<h3 class=\"wp-block-heading has-text-align-center\"><strong><em>Por Christine Evans, ilustrado por Gracey Zhang. Union Square Kids, 2023. 32 p\u00e1ginas. 17,99 $\/tapa dura. Recomendado para edades de 4 a 8 a\u00f1os.    <\/em><\/strong><\/h3>\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/bookshop.org\/lists\/friends-journal-selections-may-2024\" target=\"_blank\" rel=\"noreferrer noopener\">Comprar en QuakerBooks<\/a><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\"><em>Estimado Sr. G<\/em> es una historia amable y dulce sobre la amistad entre dos amigos por correspondencia poco probables. Cuando el joven Jackson accidentalmente patea su pelota de f\u00fatbol hacia las rosas de su vecino, el Sr. Graham, escribe una simple nota de disculpa y la entrega con bollos que hizo con su madre. El Sr. G responde aceptando la disculpa de Jackson y con una invitaci\u00f3n para que su joven vecino aprenda m\u00e1s sobre el cultivo de rosas. As\u00ed comienza una c\u00e1lida amistad entre Jackson y el Sr. G, marcada por muchas cartas de ida y vuelta. Cuando el Sr. G se muda a una residencia para personas mayores, la amistad contin\u00faa a trav\u00e9s de m\u00e1s cartas y una visita. Jackson y su abuelo sustituto siguen siendo amigos durante el resto de la vida del Sr. G.     <\/p>\n\n<p class=\"wp-block-paragraph\">Esta encantadora historia, contada completamente a trav\u00e9s de cartas y las coloridas y juguetonas ilustraciones de Gracey Zhang, destaca las fortalezas de la comunidad. El Sr. G y Jackson son diferentes en muchos sentidos, pero en sus cartas descubren cu\u00e1nto tienen en com\u00fan, incluidos los cumplea\u00f1os con una semana (y m\u00e1s de algunos a\u00f1os) de diferencia. El acto de disculpa que comienza la historia es un gesto de paz, un maravilloso ejemplo de asumir las propias acciones y la integridad de admitir las faltas. Hay alegr\u00eda en cada p\u00e1gina y se muestran paralelismos entre la vida sencilla y feliz de un ni\u00f1o peque\u00f1o y la de un anciano.   <\/p>\n\n<p class=\"wp-block-paragraph\">Las rosas del Sr. G juegan un papel importante: primero como motivo de su correspondencia y luego como un proyecto continuo, ya que el Sr. G le ense\u00f1a a Jackson c\u00f3mo cuidar las plantas. Cuando el Sr. G se muda, le pide a Jackson y a su madre que trasladen las rosas a su jard\u00edn. En invierno, cuando la vida del Sr. G comienza a declinar, las rosas parecen muertas, pero el Sr. G le asegura a Jackson que volver\u00e1n a florecer en la primavera, ofreciendo esperanza. El fallecimiento del Sr. G se maneja con delicadeza, tanto que es posible que los j\u00f3venes lectores no se den cuenta de que ha muerto. Esto de ninguna manera cambia el impacto de la historia.    <\/p>\n\n<p class=\"wp-block-paragraph\">Los j\u00f3venes lectores de esta historia pueden sentirse inspirados a escribir sus propias cartas, una novedad para algunos en esta era. Tambi\u00e9n pueden reconocer el beneficio de hacerse amigos de personas de otras generaciones o sentirse impulsados a hablar m\u00e1s con sus abuelos o bisabuelos. Pueden decidir probar la jardiner\u00eda o, tal vez, simplemente se sentir\u00e1n reconfortados por la historia de la amistad entre Jackson y el Sr. G. En cualquier caso, sonreir\u00e1n.  <\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n<p class=\"wp-block-paragraph\"><strong>Karen Clark, una Amiga convencida, es miembro del Meeting de Little Falls en Fallston, Maryland, y maestra de quinto grado en Friends School of Baltimore. Ha ense\u00f1ado en escuelas independientes durante 22 a\u00f1os, educando a estudiantes desde preescolar hasta la escuela intermedia. <\/strong><\/p>\n","protected":false},"author":5090,"featured_media":3094639,"comment_status":"open","ping_status":"closed","template":"","categories":[10540,10323],"fpb_issue_category":[10714],"class_list":["post-3122038","fpb_book","type-fpb_book","status-publish","has-post-thumbnail","hentry","category-libros-de-mayo-de-2024-estanteria-de-jovenes-amigos","category-resenas-de-libros-cuaqueros","fpb_issue_category-membresia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estimado Sr. G - Friends Journal<\/title>\n<meta name=\"description\" content=\"Escribir cartas ayuda a construir una amistad entre un ni\u00f1o y su vecino mayor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/book\/estimado-sr-g\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RESE\u00d1A: Estimado Sr. G\" \/>\n<meta property=\"og:description\" content=\"Escribir cartas ayuda a construir una amistad entre un ni\u00f1o y su vecino mayor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/book\/estimado-sr-g\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-12T05:44:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2024\/04\/Dear_FBcrop.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"RESE\u00d1A: Estimado Sr. G\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/estimado-sr-g\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/estimado-sr-g\\\/\",\"name\":\"Estimado Sr. G - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/estimado-sr-g\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/estimado-sr-g\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Dear.jpg\",\"datePublished\":\"2024-05-01T05:05:00+00:00\",\"dateModified\":\"2025-10-12T05:44:10+00:00\",\"description\":\"Escribir cartas ayuda a construir una amistad entre un ni\u00f1o y su vecino mayor.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/estimado-sr-g\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/estimado-sr-g\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/estimado-sr-g\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Dear.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Dear.jpg\",\"width\":500,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/estimado-sr-g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Books\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Estimado Sr. G\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estimado Sr. G - Friends Journal","description":"Escribir cartas ayuda a construir una amistad entre un ni\u00f1o y su vecino mayor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/book\/estimado-sr-g\/","og_locale":"es_ES","og_type":"article","og_title":"RESE\u00d1A: Estimado Sr. G","og_description":"Escribir cartas ayuda a construir una amistad entre un ni\u00f1o y su vecino mayor.","og_url":"https:\/\/www.friendsjournal.org\/es\/book\/estimado-sr-g\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_modified_time":"2025-10-12T05:44:10+00:00","og_image":[{"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2024\/04\/Dear_FBcrop.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"RESE\u00d1A: Estimado Sr. G","twitter_site":"@friendsournal","twitter_misc":{"Est. reading time":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/book\/estimado-sr-g\/","url":"https:\/\/www.friendsjournal.org\/es\/book\/estimado-sr-g\/","name":"Estimado Sr. G - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/estimado-sr-g\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/estimado-sr-g\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2024\/04\/Dear.jpg","datePublished":"2024-05-01T05:05:00+00:00","dateModified":"2025-10-12T05:44:10+00:00","description":"Escribir cartas ayuda a construir una amistad entre un ni\u00f1o y su vecino mayor.","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/estimado-sr-g\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/book\/estimado-sr-g\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/book\/estimado-sr-g\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2024\/04\/Dear.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2024\/04\/Dear.jpg","width":500,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/book\/estimado-sr-g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Books","item":"https:\/\/www.friendsjournal.org\/es\/book\/"},{"@type":"ListItem","position":3,"name":"Estimado Sr. G"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"fpb_reviewer_name":"Karen Clark","fpb_book_details":{"author":"","pricing":false,"quakerbooks_link":"","category_issue_link":null},"fpb_reviewer_profile_picture":false},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book\/3122038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/fpb_book"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3122038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3094639"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3122038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3122038"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3122038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}