{"id":3124250,"date":"2021-03-01T00:50:00","date_gmt":"2021-03-01T05:50:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/book\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\/"},"modified":"2025-10-12T04:27:47","modified_gmt":"2025-10-12T08:27:47","slug":"prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares","status":"publish","type":"fpb_book","link":"https:\/\/www.friendsjournal.org\/es\/book\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\/","title":{"rendered":"Prisi\u00f3n con otro nombre: las consecuencias perjudiciales de las reformas populares"},"content":{"rendered":"\n<h3 class=\"has-text-align-center wp-block-heading\"><strong><em>Por Maya Schenwar y Victoria Law. The New Press, 2020. 320 p\u00e1ginas. 26,99 $\/tapa dura; 17,99 $\/eBook.   <\/em><\/strong><\/h3>\n\n<div class=\"wp-block-buttons aligncenter is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/bookshop.org\/books\/prison-by-any-other-name-the-harmful-consequences-of-popular-reforms\/9781620973103?aid=3862&amp;listref=friends-journal-selections-march-2021\">Comprar en QuakerBooks<\/a><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\"><em>Prisi\u00f3n con otro nombre<\/em> analiza cr\u00edticamente las alternativas a la prisi\u00f3n. En \u00faltima instancia, se trata de la abolici\u00f3n de la prisi\u00f3n, no solo de los bloques f\u00edsicos de celdas, sino de la variedad de opciones que se ofrecen a los jueces como alternativas a la condena de los acusados a jaulas, ya que considera que todas ellas son demasiado restrictivas y punitivas. <\/p>\n\n<p class=\"wp-block-paragraph\">La organizaci\u00f3n estatal con la que he colaborado como voluntaria durante varios a\u00f1os ha presionado con \u00e9xito para disminuir el n\u00famero de personas en la prisi\u00f3n estatal mediante la legislaci\u00f3n de un mayor uso de alternativas a la condena, por lo que me sent\u00ed algo a la defensiva al leer este libro. Mientras le\u00eda, pens\u00e9:  <em>S\u00ed, las personas en estos sistemas sufren una p\u00e9rdida, pero no est\u00e1n en la prisi\u00f3n. Debe haber sanciones por infringir la ley. De lo contrario, no tenemos leyes; solo tenemos sugerencias.  <\/em><\/p>\n\n<p class=\"wp-block-paragraph\">Dicho esto, me perturb\u00f3 saber que estas sanciones alternativas restringen a un n\u00famero mucho mayor de personas de las que ser\u00edan condenadas a la prisi\u00f3n si no hubiera opciones; adem\u00e1s, los t\u00e9rminos de confinamiento son a menudo significativamente m\u00e1s largos de lo que ser\u00eda el encarcelamiento tras las rejas por el mismo delito.<\/p>\n\n<p class=\"wp-block-paragraph\">Schenwar y Law muestran c\u00f3mo la libertad de las personas se ve restringida por el arresto domiciliario, lo que imposibilita, por ejemplo, que los padres asistan a las reuniones de padres y profesores. Mientras que la comida, la vivienda y la atenci\u00f3n m\u00e9dica se proporcionan tras las rejas, las personas en arresto domiciliario deben pagar estos gastos mientras alquilan equipos de vigilancia electr\u00f3nica por hasta 500 d\u00f3lares al mes, a menudo sin poder trabajar. Nos dicen que las puertas a menudo est\u00e1n cerradas en los centros de drogodependencia y salud mental, y a las personas obligadas a asistir a programas de salud mental, drogodependencia o alcohol no les va tan bien en comparaci\u00f3n con las que asisten voluntariamente, cuando est\u00e1n psicol\u00f3gicamente preparadas. Nos dicen que las personas en el registro de delincuentes sexuales tienen problemas para alquilar apartamentos, lo que hace imposible una vida normal. Y nos muestran que la retirada de ni\u00f1os al cuidado de crianza a veces puede parecer arbitraria, y el cuidado de crianza puede ser m\u00e1s traum\u00e1tico para los ni\u00f1os que quedarse con padres demasiado estresados.    <\/p>\n\n<p class=\"wp-block-paragraph\">Aquellos que reciben castigos alternativos todav\u00eda tienen antecedentes penales y se enfrentan a la discriminaci\u00f3n resultante.<\/p>\n\n<p class=\"wp-block-paragraph\">Compart\u00ed un borrador de esta rese\u00f1a con un compa\u00f1ero voluntario de justicia penal que es un juez jubilado. Pens\u00f3 que los ejemplos de alternativas a la prisi\u00f3n demasiado duras eran los peores casos, no los t\u00edpicos. Sin embargo, estuvo de acuerdo en que podr\u00edamos hacerlo mejor.  <\/p>\n\n<p class=\"wp-block-paragraph\">Cuando llegu\u00e9 al \u00faltimo cap\u00edtulo, \u201cM\u00e1s all\u00e1 de las alternativas\u201d, entend\u00ed a Michelle Alexander, autora de <em>The New Jim Crow<\/em>, cuando escribi\u00f3 en su pr\u00f3logo a <em>Prison by Any Other Name<\/em>: \u201cEste libro nos desaf\u00eda a pensar m\u00e1s profunda y cuidadosamente sobre lo que entendemos por \u2018justicia\u2019 y qu\u00e9 tipo de mundo pretendemos co-crear\u201d. Encontr\u00e9 este cap\u00edtulo inspirador. <\/p>\n\n<p class=\"wp-block-paragraph\">Los autores escriben:<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>El objetivo no es proporcionar una alternativa a la vigilancia electr\u00f3nica, una alternativa a la libertad condicional, una alternativa al registro, y as\u00ed sucesivamente, sino observar los problemas reales a los que nos enfrentamos y tomar lecciones de los proyectos en todo el pa\u00eds que est\u00e1n abordando estos problemas de manera efectiva.<\/p><\/blockquote>\n\n<p class=\"wp-block-paragraph\">El objetivo de abolir las prisiones, as\u00ed como de retirar fondos a la polic\u00eda, es crear el tipo de sociedad que no requiera prisiones ni polic\u00eda. El libro sugiere que no hemos desarrollado habilidades para lidiar con personas con enfermedades mentales o situaciones violentas porque pensamos que solo la polic\u00eda puede manejarlas. Necesitamos aprender a calmar situaciones dif\u00edciles y construir estructuras de mediaci\u00f3n y resoluci\u00f3n de disputas basadas en la comunidad que responsabilicen a las personas por sus acciones, centren las necesidades de las v\u00edctimas y brinden apoyo tanto a las v\u00edctimas como a los perpetradores para sanar.  <\/p>\n\n<p class=\"wp-block-paragraph\">Necesitamos construir comunidad y proporcionar recursos para que todos podamos estar sanos y seguros. Los autores dan ejemplos de comunidades que ya est\u00e1n construyendo seguridad fuera de los sistemas estatales. No s\u00e9 si alguna vez podremos abolir por completo las prisiones y la polic\u00eda, pero este libro nos muestra que con comunidades donde las personas puedan prosperar, seguramente podremos avanzar en esa direcci\u00f3n.  <\/p>\n\n<hr class=\"wp-block-separator\" \/>\n\n<p class=\"wp-block-paragraph\"><strong>Patience A. Schenck es miembro de Annapolis (Md.) Meeting y residente de Friends House en Sandy Spring, Md. Es fundadora y voluntaria de Maryland Alliance for Justice Reform. <\/strong><\/p>\n","protected":false},"author":5090,"featured_media":3085302,"comment_status":"closed","ping_status":"closed","template":"","categories":[10438,10323],"fpb_issue_category":[10678],"class_list":["post-3124250","fpb_book","type-fpb_book","status-publish","has-post-thumbnail","hentry","category-libros-de-marzo-de-2021","category-resenas-de-libros-cuaqueros","fpb_issue_category-pandemia-a-un-ano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prisi\u00f3n con otro nombre: las consecuencias perjudiciales de las reformas populares - Friends Journal<\/title>\n<meta name=\"description\" content=\"A veces, las &quot;soluciones&quot; hacen m\u00e1s da\u00f1o que bien.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/book\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RESE\u00d1A: Prisi\u00f3n con otro nombre: las consecuencias perjudiciales de las reformas populares\" \/>\n<meta property=\"og:description\" content=\"A veces, las &quot;soluciones&quot; hacen m\u00e1s da\u00f1o que bien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/book\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-12T08:27:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/02\/Prison_FBcrop.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"RESE\u00d1A: Prisi\u00f3n con otro nombre: las consecuencias perjudiciales de las reformas populares\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\\\/\",\"name\":\"Prisi\u00f3n con otro nombre: las consecuencias perjudiciales de las reformas populares - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Prison.jpg\",\"datePublished\":\"2021-03-01T05:50:00+00:00\",\"dateModified\":\"2025-10-12T08:27:47+00:00\",\"description\":\"A veces, las \\\"soluciones\\\" hacen m\u00e1s da\u00f1o que bien.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Prison.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Prison.jpg\",\"width\":500,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Books\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Prisi\u00f3n con otro nombre: las consecuencias perjudiciales de las reformas populares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prisi\u00f3n con otro nombre: las consecuencias perjudiciales de las reformas populares - Friends Journal","description":"A veces, las \"soluciones\" hacen m\u00e1s da\u00f1o que bien.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/book\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\/","og_locale":"es_ES","og_type":"article","og_title":"RESE\u00d1A: Prisi\u00f3n con otro nombre: las consecuencias perjudiciales de las reformas populares","og_description":"A veces, las \"soluciones\" hacen m\u00e1s da\u00f1o que bien.","og_url":"https:\/\/www.friendsjournal.org\/es\/book\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_modified_time":"2025-10-12T08:27:47+00:00","og_image":[{"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/02\/Prison_FBcrop.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"RESE\u00d1A: Prisi\u00f3n con otro nombre: las consecuencias perjudiciales de las reformas populares","twitter_site":"@friendsournal","twitter_misc":{"Est. reading time":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/book\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\/","url":"https:\/\/www.friendsjournal.org\/es\/book\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\/","name":"Prisi\u00f3n con otro nombre: las consecuencias perjudiciales de las reformas populares - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/02\/Prison.jpg","datePublished":"2021-03-01T05:50:00+00:00","dateModified":"2025-10-12T08:27:47+00:00","description":"A veces, las \"soluciones\" hacen m\u00e1s da\u00f1o que bien.","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/book\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/book\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/02\/Prison.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/02\/Prison.jpg","width":500,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/book\/prision-con-otro-nombre-las-consecuencias-perjudiciales-de-las-reformas-populares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Books","item":"https:\/\/www.friendsjournal.org\/es\/book\/"},{"@type":"ListItem","position":3,"name":"Prisi\u00f3n con otro nombre: las consecuencias perjudiciales de las reformas populares"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"fpb_reviewer_name":"Patience a. Schenck","fpb_book_details":{"author":"","pricing":false,"quakerbooks_link":"","category_issue_link":null},"fpb_reviewer_profile_picture":false},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book\/3124250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/fpb_book"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3124250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3085302"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3124250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3124250"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3124250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}