{"id":3125065,"date":"2020-09-01T00:50:00","date_gmt":"2020-09-01T04:50:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/book\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\/"},"modified":"2025-10-12T05:30:53","modified_gmt":"2025-10-12T09:30:53","slug":"santa-desunion-como-lo-que-nos-separa-puede-salvarnos","status":"publish","type":"fpb_book","link":"https:\/\/www.friendsjournal.org\/es\/book\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\/","title":{"rendered":"Santa desuni\u00f3n: c\u00f3mo lo que nos separa puede salvarnos"},"content":{"rendered":"\n<h3 class=\"has-text-align-center wp-block-heading\"><em>Por Layton E. Williams. Westminster John Knox Press, 2019. 236 p\u00e1ginas. 17 $\/tapa blanda; 13 $\/libro electr\u00f3nico.   <\/em><\/h3>\n\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link\" href=\"https:\/\/quakerbooks.org\/products\/holy-disunity\">Comprar en QuakerBooks<\/a><\/div>\n\n<p class=\"wp-block-paragraph\">Cuando era ni\u00f1o y zurdo, aprend\u00ed pronto que la sociedad me consideraba de alguna manera diferente. Cuando supe lo que significaban \u201cgauche\u201d y \u201csiniestro\u201d, me preocup\u00e9 durante a\u00f1os tratando de averiguar por qu\u00e9 a menudo me dec\u00edan que hab\u00eda algo malo en m\u00ed. Solo m\u00e1s tarde reconoc\u00ed estas palabras como folclore inofensivo, y con m\u00e1s madurez finalmente aprend\u00ed que ser diferente era un regalo que estimul\u00f3 y guio significativamente mi camino hacia el autoconocimiento.  <\/p>\n\n<p class=\"wp-block-paragraph\">Este simple ejemplo ilustra m\u00e1s o menos c\u00f3mo Williams usa la palabra clave \u201cregalo\u201d en este libro. La primera de las 12 desuniones en las que descubre un regalo es la \u201cdiferencia\u201d. Es la m\u00e1s extendida; hay formas casi innumerables en las que las personas pueden estar en el lado equivocado de ser diferentes. Su diferencia personal es que ella, una ministra presbiteriana ordenada, pertenece a la comunidad LGBTQ, una identidad que gener\u00f3 muchas experiencias personales a las que se refiere a lo largo del libro. Como un Tipo Cuatro del Eneagrama (el Individualista), su larga sensaci\u00f3n de ser rechazada result\u00f3 ser el punto alrededor del cual construy\u00f3 su sentido de identidad, y as\u00ed se convirti\u00f3 en un regalo. Identificar y aceptar las diferencias tiene un significado mucho m\u00e1s amplio: todas nuestras relaciones entre nosotros y con Dios son posibles, y se les permite crecer, gracias a estas mismas diferencias.     <\/p>\n\n<p class=\"wp-block-paragraph\">El resto de las complejas desuniones en las que identifica un regalo se parafrasean en los siguientes 11 p\u00e1rrafos: <\/p>\n\n<p class=\"wp-block-paragraph\">El ineludible ajuste de cuentas humano con la duda puede ser una puerta de entrada al descubrimiento, envi\u00e1ndonos en viajes que conducen a nuevas verdades.<\/p>\n\n<p class=\"wp-block-paragraph\">Evitamos el desacuerdo como impropio, pero los argumentos que tienen una base de confianza pueden convertirse en un di\u00e1logo sagrado: \u201cEstamos llamados&#8230; a responder\u201d.<\/p>\n\n<p class=\"wp-block-paragraph\">A menudo nos encontramos en una tensi\u00f3n entre dos verdades: por ejemplo, nuestra insignificancia y nuestra importancia. Estamos llamados a vivir en el espacio entre las dos, manteniendo al mismo tiempo dos verdades aparentemente opuestas, y esto nos da el regalo de la conciencia de que siempre hay m\u00e1s en la historia. <\/p>\n\n<p class=\"wp-block-paragraph\">Se requiere espacio para el crecimiento, y esos espacios dejados por la separaci\u00f3n pueden ser el suelo f\u00e9rtil en el que pueden crecer cosas aparentemente imposibles.<\/p>\n\n<p class=\"wp-block-paragraph\">Permitirnos ser vulnerables tiene un poder transformador, descubriendo nuestro ser aut\u00e9ntico y viendo plenamente las luchas y la humanidad de los dem\u00e1s.<\/p>\n\n<p class=\"wp-block-paragraph\">Huimos de los problemas<em>,<\/em> pero es mejor verlos por lo que son: \u201caquello que nos preocupa busca decirnos la verdad\u201d. Es la puerta de entrada a la empat\u00eda que reconoce la verdad preocupante con el prop\u00f3sito de responder a ella. <\/p>\n\n<p class=\"wp-block-paragraph\">La protesta nombra lo que no se puede nombrar, funcionando como un espejo ineludible de una verdad. Deber\u00edamos, nos dice Williams, estar dispuestos a ofender m\u00e1s. <\/p>\n\n<p class=\"wp-block-paragraph\">Com\u00fan a nuestra humanidad es nuestra hambre<em> <\/em>de sustento del cuerpo y del esp\u00edritu. El regalo aqu\u00ed es que esta hambre nos recuerda nuestra conexi\u00f3n con el resto de la creaci\u00f3n, un anhelo por alg\u00fan sentido de pertenencia a algo m\u00e1s grande que nosotros mismos. Es nuestra hambre la que nos lleva a lo Divino.  <\/p>\n\n<p class=\"wp-block-paragraph\">Ser humano significa aceptar limitaciones, y su regalo para nosotros es la humildad. Los muchos tipos de limitaciones nos invitan a depender unos de otros, y superarlos puede conducir a cosas imprevistas. <\/p>\n\n<p class=\"wp-block-paragraph\">No somos buenos para ver nada positivo en el fracaso<em>,<\/em> sin embargo, s\u00ed tiene regalos que ofrecernos. Es nuestro miedo al fracaso lo que impulsa gran parte de nuestro miedo a las 12 desuniones. El regalo es nuestra oportunidad de aprender y crecer.  <\/p>\n\n<p class=\"wp-block-paragraph\">No tenemos m\u00e1s remedio que aceptar la realidad de que nuestro viaje est\u00e1 lleno de incertidumbre. Cuanto m\u00e1s inexpugnables se vuelven las convicciones y certezas, m\u00e1s peligrosas son a medida que demuestran ser ilusiones. La fidelidad ante la incertidumbre conduce a su regalo: la motivaci\u00f3n para dejar ir.  <\/p>\n\n<p class=\"wp-block-paragraph\">Cada cap\u00edtulo analiza c\u00f3mo una desuni\u00f3n particular nos separa y concluye instando a c\u00f3mo puede salvarnos, qu\u00e9 regalo ofrece. Los numerosos ejemplos provienen de la propia experiencia de Williams y la de sus feligreses, y una secci\u00f3n siempre est\u00e1 dedicada a ejemplos de la Biblia. Ella no afirma que las 12 que ha elegido sean las \u00fanicas desuniones, y es bastante f\u00e1cil pensar en m\u00e1s. Al renunciar al \u00eddolo de la unidad, podemos ver lo que es sagrado en la desuni\u00f3n. Cada desuni\u00f3n es una oportunidad para el crecimiento y la transformaci\u00f3n.    <\/p>\n\n<hr class=\"wp-block-separator\" \/>\n\n<p class=\"wp-block-paragraph\"><strong>William Shetter es miembro del Meeting de Bloomington (Indiana). Intenta identificar los regalos que se pueden descubrir en la reciente separaci\u00f3n del \u201cdistanciamiento social\u201d.<\/strong><\/p>\n","protected":false},"author":5090,"featured_media":3084107,"comment_status":"closed","ping_status":"closed","template":"","categories":[10424,10323],"fpb_issue_category":[],"class_list":["post-3125065","fpb_book","type-fpb_book","status-publish","has-post-thumbnail","hentry","category-libros-de-septiembre-de-2020","category-resenas-de-libros-cuaqueros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santa desuni\u00f3n: c\u00f3mo lo que nos separa puede salvarnos - Friends Journal<\/title>\n<meta name=\"description\" content=\"Al renunciar al \u00eddolo de la unidad, podemos ver lo que es sagrado en la desuni\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/book\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RESE\u00d1A: santa desuni\u00f3n: c\u00f3mo lo que nos separa puede salvarnos\" \/>\n<meta property=\"og:description\" content=\"Al renunciar al \u00eddolo de la unidad, podemos ver lo que es sagrado en la desuni\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/book\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-12T09:30:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/08\/Holy_FBcrop.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"RESE\u00d1A: santa desuni\u00f3n: c\u00f3mo lo que nos separa puede salvarnos\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\\\/\",\"name\":\"Santa desuni\u00f3n: c\u00f3mo lo que nos separa puede salvarnos - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Holy.jpg\",\"datePublished\":\"2020-09-01T04:50:00+00:00\",\"dateModified\":\"2025-10-12T09:30:53+00:00\",\"description\":\"Al renunciar al \u00eddolo de la unidad, podemos ver lo que es sagrado en la desuni\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Holy.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Holy.jpg\",\"width\":500,\"height\":773},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Books\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Santa desuni\u00f3n: c\u00f3mo lo que nos separa puede salvarnos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santa desuni\u00f3n: c\u00f3mo lo que nos separa puede salvarnos - Friends Journal","description":"Al renunciar al \u00eddolo de la unidad, podemos ver lo que es sagrado en la desuni\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/book\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\/","og_locale":"es_ES","og_type":"article","og_title":"RESE\u00d1A: santa desuni\u00f3n: c\u00f3mo lo que nos separa puede salvarnos","og_description":"Al renunciar al \u00eddolo de la unidad, podemos ver lo que es sagrado en la desuni\u00f3n.","og_url":"https:\/\/www.friendsjournal.org\/es\/book\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_modified_time":"2025-10-12T09:30:53+00:00","og_image":[{"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/08\/Holy_FBcrop.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"RESE\u00d1A: santa desuni\u00f3n: c\u00f3mo lo que nos separa puede salvarnos","twitter_site":"@friendsournal","twitter_misc":{"Est. reading time":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/book\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\/","url":"https:\/\/www.friendsjournal.org\/es\/book\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\/","name":"Santa desuni\u00f3n: c\u00f3mo lo que nos separa puede salvarnos - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/08\/Holy.jpg","datePublished":"2020-09-01T04:50:00+00:00","dateModified":"2025-10-12T09:30:53+00:00","description":"Al renunciar al \u00eddolo de la unidad, podemos ver lo que es sagrado en la desuni\u00f3n.","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/book\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/book\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/08\/Holy.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/08\/Holy.jpg","width":500,"height":773},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/book\/santa-desunion-como-lo-que-nos-separa-puede-salvarnos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Books","item":"https:\/\/www.friendsjournal.org\/es\/book\/"},{"@type":"ListItem","position":3,"name":"Santa desuni\u00f3n: c\u00f3mo lo que nos separa puede salvarnos"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"fpb_reviewer_name":" William Shetter","fpb_book_details":{"author":"","pricing":false,"quakerbooks_link":"","category_issue_link":null},"fpb_reviewer_profile_picture":false},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book\/3125065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/fpb_book"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3125065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3084107"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3125065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3125065"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3125065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}