{"id":3125085,"date":"2020-09-01T01:05:00","date_gmt":"2020-09-01T05:05:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/book\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\/"},"modified":"2025-10-12T05:31:28","modified_gmt":"2025-10-12T09:31:28","slug":"el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion","status":"publish","type":"fpb_book","link":"https:\/\/www.friendsjournal.org\/es\/book\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\/","title":{"rendered":"El peque\u00f1o libro de la sanaci\u00f3n racial: llegando a la mesa para contar la verdad, la liberaci\u00f3n y la transformaci\u00f3n"},"content":{"rendered":"\n<h3 class=\"has-text-align-center wp-block-heading\"><strong><em>Por Thomas Norman DeWolf y Jodie Geddes. Good Books, 2019. 120 p\u00e1ginas. 5,99 $\/libro de bolsillo o libro electr\u00f3nico.   <\/em><\/strong><\/h3>\n\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link\" href=\"https:\/\/quakerbooks.org\/products\/the-little-book-of-racial-healing?variant=35847151288486\">Comprar en QuakerBooks<\/a><\/div>\n\n<p class=\"wp-block-paragraph\">Como mujer blanca que vive en una zona predominantemente blanca, he buscado recursos para educar y guiar mi viaje hacia la concienciaci\u00f3n de las realidades de la injusticia racial y mi lugar en la lucha por la verdadera igualdad. <em>El peque\u00f1o libro de la sanaci\u00f3n racial<\/em> es un gran recurso para m\u00ed. En el mensaje de DeWolf (\u201cNo tengo ning\u00fan inter\u00e9s en hacer que los blancos se sientan culpables o avergonzados por el pasado o el presente\u201d), encontr\u00e9 permiso para sentirme inc\u00f3moda, enfurecida, torpe y cari\u00f1osa conmigo misma al empezar a navegar por debates dif\u00edciles y a reexaminar todo lo que me hab\u00edan ense\u00f1ado en mi experiencia educativa colonizada. <\/p>\n\n<p class=\"wp-block-paragraph\">Las palabras de Geddes (\u201cEmpezamos a reclamar nuestra humanidad cuando recordamos nuestra interconexi\u00f3n y compartimos entre nosotros\u201d) me ayudaron a ver m\u00e1s all\u00e1 de la ira que sent\u00eda crecer en mi interior, al descubrir m\u00e1s brutalidades e injusticias, hasta un lugar de paz donde pod\u00eda sentirme verdaderamente conectada con mis semejantes: negros, morenos y blancos.<\/p>\n\n<p class=\"wp-block-paragraph\">Organizado en nueve breves cap\u00edtulos, el libro gu\u00eda al lector a trav\u00e9s de los pasos de reconocer y examinar el trauma, para luego trabajar hacia la sanaci\u00f3n a trav\u00e9s de conversaciones que nos ayuden a encontrar nuestra conexi\u00f3n, y finalmente hacia un camino de acci\u00f3n a trav\u00e9s de la educaci\u00f3n continua y la participaci\u00f3n en movimientos comunitarios. An\u00e9cdotas esparcidas a lo largo de los cap\u00edtulos nos conectan con la humanidad en cada uno de estos pasos. El cap\u00edtulo sobre el proceso circular ofrece una gu\u00eda espec\u00edfica y creativa para utilizar esta poderosa t\u00e9cnica para crear una atm\u00f3sfera de confianza e intenci\u00f3n. Los griots (narradores de \u00c1frica Occidental), los bardos y los poetas a lo largo de la historia han conocido el poder de la narraci\u00f3n, y este libro ofrece el proceso circular como un escenario para este arte, para proporcionar espejos en los que nos vemos a nosotros mismos, as\u00ed como ventanas a las experiencias de los dem\u00e1s. Reconoce que todos llegamos al c\u00edrculo desde diferentes lugares, en diferentes puntos de nuestro viaje. Todo lo que tenemos que ofrecer son nuestras experiencias y nuestros o\u00eddos.     <\/p>\n\n<p class=\"wp-block-paragraph\">En <em>El peque\u00f1o libro de la sanaci\u00f3n racial<\/em>, me encontr\u00e9 con la idea revolucionaria de la justicia restaurativa, en la que no hay ni ganador ni perdedor, sino una soluci\u00f3n real y viable que puede beneficiar a todas las partes. Esto puede ocurrir en el c\u00edrculo m\u00e1s peque\u00f1o, en barrios y escuelas, en empresas, e incluso como una mejor alternativa a nuestro sistema de justicia penal, creado de forma desigual y muy deteriorado. Comenzando con la sanaci\u00f3n individual; luego llevando nuestros seres reci\u00e9n abiertos a conversaciones que reducen la \u201cotredad\u201d y aumentan la conexi\u00f3n; y luego, finalmente, ofreciendo nuestros seres completos al servicio de nuestras comunidades, este libro traza un camino hacia un futuro brillante.  <\/p>\n\n<hr class=\"wp-block-separator\" \/>\n\n<p class=\"wp-block-paragraph\"><strong>Karen Heidenreich asiste al Meeting de Little Falls en Fallston, Maryland. Ense\u00f1a en una escuela independiente en Baltimore, Maryland, y forma parte del Comit\u00e9 de Inclusi\u00f3n de Empleados de la escuela, del Grupo de Trabajo Estudiantil de Diversidad\/Equidad\/Inclusi\u00f3n y del Grupo de Trabajo LGBTQ+. Cofund\u00f3 el cap\u00edtulo de Coming to the Table en el condado de Harford, Maryland.  <\/strong><\/p>\n","protected":false},"author":5090,"featured_media":3084085,"comment_status":"closed","ping_status":"closed","template":"","categories":[10424,10323],"fpb_issue_category":[],"class_list":["post-3125085","fpb_book","type-fpb_book","status-publish","has-post-thumbnail","hentry","category-libros-de-septiembre-de-2020","category-resenas-de-libros-cuaqueros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El peque\u00f1o libro de la sanaci\u00f3n racial: llegando a la mesa para contar la verdad, la liberaci\u00f3n y la transformaci\u00f3n - Friends Journal<\/title>\n<meta name=\"description\" content=\"Un encuentro con la idea revolucionaria de la justicia restaurativa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/book\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RESE\u00d1A: El peque\u00f1o libro de la sanaci\u00f3n racial: llegando a la mesa para contar la verdad, la liberaci\u00f3n y la transformaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Un encuentro con la idea revolucionaria de la justicia restaurativa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/book\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-12T09:31:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/08\/RacialHealing_FBcrop.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"RESE\u00d1A: El peque\u00f1o libro de la sanaci\u00f3n racial: llegando a la mesa para contar la verdad, la liberaci\u00f3n y la transformaci\u00f3n\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\\\/\",\"name\":\"El peque\u00f1o libro de la sanaci\u00f3n racial: llegando a la mesa para contar la verdad, la liberaci\u00f3n y la transformaci\u00f3n - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/TheLittleBook.jpg\",\"datePublished\":\"2020-09-01T05:05:00+00:00\",\"dateModified\":\"2025-10-12T09:31:28+00:00\",\"description\":\"Un encuentro con la idea revolucionaria de la justicia restaurativa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/TheLittleBook.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/TheLittleBook.jpg\",\"width\":500,\"height\":772},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Books\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El peque\u00f1o libro de la sanaci\u00f3n racial: llegando a la mesa para contar la verdad, la liberaci\u00f3n y la transformaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El peque\u00f1o libro de la sanaci\u00f3n racial: llegando a la mesa para contar la verdad, la liberaci\u00f3n y la transformaci\u00f3n - Friends Journal","description":"Un encuentro con la idea revolucionaria de la justicia restaurativa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/book\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\/","og_locale":"es_ES","og_type":"article","og_title":"RESE\u00d1A: El peque\u00f1o libro de la sanaci\u00f3n racial: llegando a la mesa para contar la verdad, la liberaci\u00f3n y la transformaci\u00f3n","og_description":"Un encuentro con la idea revolucionaria de la justicia restaurativa.","og_url":"https:\/\/www.friendsjournal.org\/es\/book\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_modified_time":"2025-10-12T09:31:28+00:00","og_image":[{"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/08\/RacialHealing_FBcrop.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"RESE\u00d1A: El peque\u00f1o libro de la sanaci\u00f3n racial: llegando a la mesa para contar la verdad, la liberaci\u00f3n y la transformaci\u00f3n","twitter_site":"@friendsournal","twitter_misc":{"Est. reading time":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/book\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\/","url":"https:\/\/www.friendsjournal.org\/es\/book\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\/","name":"El peque\u00f1o libro de la sanaci\u00f3n racial: llegando a la mesa para contar la verdad, la liberaci\u00f3n y la transformaci\u00f3n - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/08\/TheLittleBook.jpg","datePublished":"2020-09-01T05:05:00+00:00","dateModified":"2025-10-12T09:31:28+00:00","description":"Un encuentro con la idea revolucionaria de la justicia restaurativa.","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/book\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/book\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/08\/TheLittleBook.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/08\/TheLittleBook.jpg","width":500,"height":772},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/book\/el-pequeno-libro-de-la-sanacion-racial-llegando-a-la-mesa-para-contar-la-verdad-la-liberacion-y-la-transformacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Books","item":"https:\/\/www.friendsjournal.org\/es\/book\/"},{"@type":"ListItem","position":3,"name":"El peque\u00f1o libro de la sanaci\u00f3n racial: llegando a la mesa para contar la verdad, la liberaci\u00f3n y la transformaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"fpb_reviewer_name":"Karen Heidenreich","fpb_book_details":{"author":"","pricing":false,"quakerbooks_link":"","category_issue_link":null},"fpb_reviewer_profile_picture":false},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book\/3125085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/fpb_book"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3125085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3084085"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3125085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3125085"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3125085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}