{"id":3125107,"date":"2020-10-01T02:00:00","date_gmt":"2020-10-01T06:00:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/book\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\/"},"modified":"2025-10-12T05:32:38","modified_gmt":"2025-10-12T09:32:38","slug":"en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955","status":"publish","type":"fpb_book","link":"https:\/\/www.friendsjournal.org\/es\/book\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\/","title":{"rendered":"En resumen: Un cu\u00e1quero detr\u00e1s del sue\u00f1o: Charlie Walker y el movimiento por los derechos civiles (Volumen I, 1920\u20131955)"},"content":{"rendered":"\n<h3 class=\"has-text-align-center wp-block-heading\">Por Brenda Walker Beadenkopf. EA Books, 2019. 322 p\u00e1ginas. 20 $\/tapa blanda; 9,50 $\/libro electr\u00f3nico.   <\/h3>\n\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link\" href=\"https:\/\/quakerbooks.org\/products\/quaker-behind-the-dream-a?_pos=1&amp;_sid=92a5f97d9&amp;_ss=r\">Comprar en QuakerBooks<\/a><\/div>\n\n<p class=\"wp-block-paragraph\">Las historias contin\u00faan, esta vez de la mano de una hija cari\u00f1osa que relata el papel de su padre en el movimiento por los derechos civiles de EE. UU. del siglo XX. Este primer volumen abarca de 1920 a 1955; podemos esperar otro volumen que cubra a\u00f1os posteriores. <\/p>\n\n<p class=\"wp-block-paragraph\">Es un trabajo enorme, pero Beadenkopf es periodista de profesi\u00f3n, por lo que respondi\u00f3 a los impulsos de su madre \u2014y de Dios\u2014 de emprender la tarea de contar la historia de su padre en la primera parte del movimiento por los derechos civiles, ayudando a dar forma a su identidad no violenta, que ella llama \u201clas ense\u00f1anzas de Jes\u00fas en una forma pr\u00e1ctica\u201d.<\/p>\n\n<p class=\"wp-block-paragraph\">Afortunadamente, Charlie Walker acumul\u00f3 una gran cantidad de artefactos \u2014art\u00edculos de peri\u00f3dicos, discursos grabados, etc.\u2014 que su hija ahora tiene como material de origen. Al igual que con el l\u00edder y organizador cu\u00e1quero de los derechos civiles Bayard Rustin, que estaba relacionado con Walker, la historia de aquellos tiempos se enriquece a medida que escuchamos sobre m\u00e1s de las personas que se dedicaron a la lucha, a menudo encontrando satisfacci\u00f3n y sirviendo como modelos a seguir. Charlie Walker es uno de ellos.  <\/p>\n","protected":false},"author":5090,"featured_media":3084300,"comment_status":"closed","ping_status":"closed","template":"","categories":[10426,10323],"fpb_issue_category":[10674],"class_list":["post-3125107","fpb_book","type-fpb_book","status-publish","has-post-thumbnail","hentry","category-libros-de-octubre-de-2020","category-resenas-de-libros-cuaqueros","fpb_issue_category-proceso-cuaquero"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En resumen: Un cu\u00e1quero detr\u00e1s del sue\u00f1o: Charlie Walker y el movimiento por los derechos civiles (Volumen I, 1920\u20131955) - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/book\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EN RESUMEN: un cu\u00e1quero detr\u00e1s del sue\u00f1o: Charlie Walker y el movimiento por los derechos civiles (volumen i, 1920\u20131955)\" \/>\n<meta property=\"og:description\" content=\"Por Brenda Walker Beadenkopf. EA Books, 2019. 322 p\u00e1ginas. 20 $\/tapa blanda; 9,50 $\/libro electr\u00f3nico. Las historias contin\u00faan, esta vez&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/book\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-12T09:32:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/09\/AQuaker2_FBcrop.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"EN RESUMEN: un cu\u00e1quero detr\u00e1s del sue\u00f1o: Charlie Walker y el movimiento por los derechos civiles (volumen i, 1920\u20131955)\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\\\/\",\"name\":\"En resumen: Un cu\u00e1quero detr\u00e1s del sue\u00f1o: Charlie Walker y el movimiento por los derechos civiles (Volumen I, 1920\u20131955) - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/AQuaker2.jpg\",\"datePublished\":\"2020-10-01T06:00:00+00:00\",\"dateModified\":\"2025-10-12T09:32:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/AQuaker2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/AQuaker2.jpg\",\"width\":500,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Books\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"En resumen: Un cu\u00e1quero detr\u00e1s del sue\u00f1o: Charlie Walker y el movimiento por los derechos civiles (Volumen I, 1920\u20131955)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En resumen: Un cu\u00e1quero detr\u00e1s del sue\u00f1o: Charlie Walker y el movimiento por los derechos civiles (Volumen I, 1920\u20131955) - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/book\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\/","og_locale":"es_ES","og_type":"article","og_title":"EN RESUMEN: un cu\u00e1quero detr\u00e1s del sue\u00f1o: Charlie Walker y el movimiento por los derechos civiles (volumen i, 1920\u20131955)","og_description":"Por Brenda Walker Beadenkopf. EA Books, 2019. 322 p\u00e1ginas. 20 $\/tapa blanda; 9,50 $\/libro electr\u00f3nico. Las historias contin\u00faan, esta vez&hellip;","og_url":"https:\/\/www.friendsjournal.org\/es\/book\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_modified_time":"2025-10-12T09:32:38+00:00","og_image":[{"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/09\/AQuaker2_FBcrop.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"EN RESUMEN: un cu\u00e1quero detr\u00e1s del sue\u00f1o: Charlie Walker y el movimiento por los derechos civiles (volumen i, 1920\u20131955)","twitter_site":"@friendsournal","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/book\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\/","url":"https:\/\/www.friendsjournal.org\/es\/book\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\/","name":"En resumen: Un cu\u00e1quero detr\u00e1s del sue\u00f1o: Charlie Walker y el movimiento por los derechos civiles (Volumen I, 1920\u20131955) - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/09\/AQuaker2.jpg","datePublished":"2020-10-01T06:00:00+00:00","dateModified":"2025-10-12T09:32:38+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/book\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/book\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/09\/AQuaker2.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/09\/AQuaker2.jpg","width":500,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/book\/en-resumen-un-cuaquero-detras-del-sueno-charlie-walker-y-el-movimiento-por-los-derechos-civiles-volumen-i-1920-1955\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Books","item":"https:\/\/www.friendsjournal.org\/es\/book\/"},{"@type":"ListItem","position":3,"name":"En resumen: Un cu\u00e1quero detr\u00e1s del sue\u00f1o: Charlie Walker y el movimiento por los derechos civiles (Volumen I, 1920\u20131955)"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"fpb_reviewer_name":"Karie Firoozmand","fpb_book_details":{"author":"","pricing":false,"quakerbooks_link":"","category_issue_link":null},"fpb_reviewer_profile_picture":false},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book\/3125107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/fpb_book"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3125107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3084300"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3125107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3125107"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3125107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}