{"id":3125369,"date":"2019-12-01T01:00:15","date_gmt":"2019-12-01T06:00:15","guid":{"rendered":"https:\/\/www.friendsjournal.org\/book\/the-unsung-hero-of-birdsong-usa\/"},"modified":"2019-12-01T01:00:15","modified_gmt":"2019-12-01T06:00:15","slug":"the-unsung-hero-of-birdsong-usa","status":"publish","type":"fpb_book","link":"https:\/\/www.friendsjournal.org\/es\/book\/the-unsung-hero-of-birdsong-usa\/","title":{"rendered":"The unsung hero of birdsong, USA"},"content":{"rendered":"<p><b><i><a href=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/The-Unsung-Hero-of-Birdsong.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-3033585\" src=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/The-Unsung-Hero-of-Birdsong-198x300.jpg\" alt=\"\" width=\"198\" height=\"300\" srcset=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/The-Unsung-Hero-of-Birdsong-198x300.jpg 198w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/The-Unsung-Hero-of-Birdsong.jpg 600w\" sizes=\"auto, (max-width: 198px) 100vw, 198px\" \/><\/a>Por Brenda Woods. Nancy Paulsen Books, 2019. 208 p\u00e1ginas. 16,99 $\/tapa dura; 8,99 $\/tapa blanda (disponible en enero de 2020); 9,99 $\/libro electr\u00f3nico. Recomendado para mayores de 10 a\u00f1os.    <\/i><\/b><\/p>\n<p><span style=\"font-weight: 400;\">Birdsong, Carolina del Sur, es el escenario de una amistad \u00fanica entre Gabriel Haberlin, de 12 a\u00f1os, que es blanco, y Meriwether Hunter, un hombre negro desempleado. En esta breve novela de iniciaci\u00f3n, los lectores ven el mundo a trav\u00e9s de los ojos del ni\u00f1o, que narra una historia convencional de adolescencia circunscrita por la escuela, una familia y amigos que le apoyan, y visitas ocasionales a la cercana Charleston, Carolina del Sur. La vida transcurre sin incidentes hasta que un accidente de bicicleta une a los personajes en un giro del destino que hace que los dos personajes principales pongan patas arriba la adormecida Birdsong durante un tiempo. A trav\u00e9s de la intervenci\u00f3n divina, Meriwether salva a Gabriel de ser atropellado por un coche, tras lo cual el ni\u00f1o establece un v\u00ednculo con su salvador y se embarca en un \u201cdestino especial\u00bb. Como forma de agradecer el acto de bondad de Meriwether, Gabriel insta a su padre a que emplee a Meriwether en su gasolinera. Surge un conflicto cuando otro mec\u00e1nico, Lucas, con presuntos v\u00ednculos con el KKK y enfadado por la contrataci\u00f3n, empieza a acosar a Meriwether y a su familia. Lo que sigue es un cap\u00edtulo tras otro de creciente tensi\u00f3n, que m\u00e1s tarde se resuelve en parte gracias a la valent\u00eda y la tenacidad de Gabriel.     <\/span><\/p>\n<p><span style=\"font-weight: 400;\">La significaci\u00f3n b\u00edblica de la edad y el nombre de Gabriel (como arc\u00e1ngel y mensajero de la verdad) no pasar\u00e1 desapercibida para los lectores. Su naturaleza espiritual le permite ser sensible y receptivo a quienes le rodean, invit\u00e1ndoles a compartir su perspectiva incontaminada de la humanidad. En muchos aspectos, Gabriel es un ni\u00f1o normal que, guiado por una br\u00fajula moral, posee un sentido notablemente funcional de lo que est\u00e1 bien y lo que est\u00e1 mal. Mientras que la raza de Meriwether preocupa a los adultos en la discriminatoria Birdsong, Gabriel acepta y acoge a su nuevo amigo sin dudarlo. La creciente conciencia del ni\u00f1o sobre la raza es evidente en las preguntas que hace a sus padres, educados en el Oberlin College, sobre la desigualdad de las escuelas blancas y negras y la presencia de carteles de \u201csolo para blancos\u00bb. La respuesta comprensiva que recibe le impulsa a un nivel superior de percepci\u00f3n: \u201cSer\u00eda bueno que la gente de color no tuviera constantes recordatorios de que no es bienvenida. Imag\u00ednate que esos carteles, en lugar de decir &#8216;No se admiten personas de color&#8217;, dijeran &#8216;No se admiten blancos'\u00bb. La imagen que Gabriel evoca de tal cartel le lleva a experimentar un malestar visceral. A medida que Gabriel descubre m\u00e1s sobre la complejidad de su entorno, y en particular sobre la intolerancia racial en Birdsong, llega a comprender que \u201cser de color y ser negro es exactamente lo mismo\u00bb. La gasolinera de su padre no solo es una de las que atienden a personas de color, sino que tambi\u00e9n aparece en          <\/span><i><br \/>\n  <span style=\"font-weight: 400;\">The Negro Motorist Green Book<\/span><br \/>\n<\/i><span style=\"font-weight: 400;\">, que enumeraba los lugares donde los negros eran bienvenidos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Meriwether comparte su verdad m\u00e1s guardada con Gabriel: que luch\u00f3 en la Batalla de las Ardenas como parte del 761\u00ba Batall\u00f3n de Tanques, una unidad afroamericana. En un acto de autopreservaci\u00f3n, Meriwether nunca ha revelado su servicio militar debido al trato hostil y la muerte brutal que los veteranos de la Segunda Guerra Mundial encontraron bajo Jim Crow. Adem\u00e1s, Meriwether est\u00e1 abatido por el hecho de que el lado violento del Sur segregado se traduzca en una temprana p\u00e9rdida de inocencia para los ni\u00f1os de color, como ocurre ahora con Gabriel. Este \u00faltimo siente que est\u00e1 creciendo al situarse en el umbral de la edad adulta, incluso imaginando la justicia en forma de un desfile en Birdsong para los veteranos negros con el fin de reafirmar la dignidad y la justicia que se les ha negado. Meriwether ense\u00f1a a Gabriel a ver el mundo desde los ojos de los dem\u00e1s, y unidos moment\u00e1neamente, act\u00faan como agentes en la transformaci\u00f3n de la peque\u00f1a ciudad. Gabriel aprende verdades desagradables sobre su mundo; su decisi\u00f3n de seguir su conciencia ante la adversidad se ve reforzada por la convicci\u00f3n fundamental de que la verdad no es prescindible ni negociable. En este libro, Brenda Woods es h\u00e1bil al presentar a su joven p\u00fablico un retrato realista de la segregaci\u00f3n, los linchamientos y la raza en la Birdsong microc\u00f3smica. Recomiendo este libro a los padres y a las bibliotecas escolares y de reuniones. Woods merece elogios por articular las contribuciones olvidadas del hist\u00f3rico 761\u00ba, al que est\u00e1 dedicado el libro, y de los veteranos de color que ayudaron a los Aliados a lograr la victoria.        <\/span><\/p>\n","protected":false},"author":5090,"featured_media":3082834,"comment_status":"open","ping_status":"closed","template":"","categories":[10409,10323],"fpb_issue_category":[10665],"class_list":["post-3125369","fpb_book","type-fpb_book","status-publish","has-post-thumbnail","hentry","category-libros-de-diciembre-de-2019-una-estanteria-de-jovenes-amigos","category-resenas-de-libros-cuaqueros","fpb_issue_category-ninos-cuaqueros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The unsung hero of birdsong, USA - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/book\/the-unsung-hero-of-birdsong-usa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The unsung hero of birdsong, USA\" \/>\n<meta property=\"og:description\" content=\"Por Brenda Woods. Nancy Paulsen Books, 2019. 208 p\u00e1ginas. 16,99 $\/tapa dura; 8,99 $\/tapa blanda (disponible en enero de 2020); 9,99 $\/libro electr\u00f3nico. Recomendado para mayores de 10 a\u00f1os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/book\/the-unsung-hero-of-birdsong-usa\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/The-Unsung-Hero-of-Birdsong.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"907\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"El h\u00e9roe an\u00f3nimo del canto de los p\u00e1jaros, EE. UU., por Brenda Woods.\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/the-unsung-hero-of-birdsong-usa\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/the-unsung-hero-of-birdsong-usa\\\/\",\"name\":\"The unsung hero of birdsong, USA - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/the-unsung-hero-of-birdsong-usa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/the-unsung-hero-of-birdsong-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/The-Unsung-Hero-of-Birdsong.jpg\",\"datePublished\":\"2019-12-01T06:00:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/the-unsung-hero-of-birdsong-usa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/the-unsung-hero-of-birdsong-usa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/the-unsung-hero-of-birdsong-usa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/The-Unsung-Hero-of-Birdsong.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/The-Unsung-Hero-of-Birdsong.jpg\",\"width\":600,\"height\":907},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/the-unsung-hero-of-birdsong-usa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Books\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The unsung hero of birdsong, USA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The unsung hero of birdsong, USA - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/book\/the-unsung-hero-of-birdsong-usa\/","og_locale":"es_ES","og_type":"article","og_title":"The unsung hero of birdsong, USA","og_description":"Por Brenda Woods. Nancy Paulsen Books, 2019. 208 p\u00e1ginas. 16,99 $\/tapa dura; 8,99 $\/tapa blanda (disponible en enero de 2020); 9,99 $\/libro electr\u00f3nico. Recomendado para mayores de 10 a\u00f1os.","og_url":"https:\/\/www.friendsjournal.org\/es\/book\/the-unsung-hero-of-birdsong-usa\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","og_image":[{"width":600,"height":907,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/The-Unsung-Hero-of-Birdsong.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"El h\u00e9roe an\u00f3nimo del canto de los p\u00e1jaros, EE. UU., por Brenda Woods.","twitter_site":"@friendsournal","twitter_misc":{"Est. reading time":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/book\/the-unsung-hero-of-birdsong-usa\/","url":"https:\/\/www.friendsjournal.org\/es\/book\/the-unsung-hero-of-birdsong-usa\/","name":"The unsung hero of birdsong, USA - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/the-unsung-hero-of-birdsong-usa\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/the-unsung-hero-of-birdsong-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/The-Unsung-Hero-of-Birdsong.jpg","datePublished":"2019-12-01T06:00:15+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/the-unsung-hero-of-birdsong-usa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/book\/the-unsung-hero-of-birdsong-usa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/book\/the-unsung-hero-of-birdsong-usa\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/The-Unsung-Hero-of-Birdsong.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/The-Unsung-Hero-of-Birdsong.jpg","width":600,"height":907},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/book\/the-unsung-hero-of-birdsong-usa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Books","item":"https:\/\/www.friendsjournal.org\/es\/book\/"},{"@type":"ListItem","position":3,"name":"The unsung hero of birdsong, USA"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"author_name":"Rese\u00f1ado por Jerry Mizell Williams","bio":"<p>Jerry Mizell Williams es miembro del Green Street Meeting en Filadelfia, Pensilvania. Es autor de numerosos libros, art\u00edculos y rese\u00f1as de libros sobre la Am\u00e9rica Latina colonial. <\/p>\n"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book\/3125369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/fpb_book"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3125369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3082834"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3125369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3125369"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3125369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}