{"id":3125373,"date":"2019-12-01T01:05:17","date_gmt":"2019-12-01T06:05:17","guid":{"rendered":"https:\/\/www.friendsjournal.org\/book\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\/"},"modified":"2019-12-01T01:05:17","modified_gmt":"2019-12-01T06:05:17","slug":"nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial","status":"publish","type":"fpb_book","link":"https:\/\/www.friendsjournal.org\/es\/book\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\/","title":{"rendered":"Ni\u00f1o enemigo: La historia de Norman Mineta, un ni\u00f1o encarcelado en un campo de internamiento japon\u00e9s-americano durante la Segunda Guerra Mundial"},"content":{"rendered":"<p><b><i><a href=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/Enemy-Child.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-3033581\" src=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/Enemy-Child-270x300.jpg\" alt=\"\" width=\"270\" height=\"300\" srcset=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/Enemy-Child-270x300.jpg 270w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/Enemy-Child.jpg 600w\" sizes=\"auto, (max-width: 270px) 100vw, 270px\" \/><\/a>Por Andrea Warren. Margaret Ferguson Books, 2019. 224 p\u00e1ginas. 22,99 $\/tapa dura. Recomendado para mayores de 10 a\u00f1os.    <\/i><\/b><\/p>\n<p><span style=\"font-weight: 400;\">Bas\u00e1ndose en la investigaci\u00f3n y en cuatro d\u00edas de entrevistas con el ex Secretario de Transporte Norman Mineta, Andrea Warren ha escrito una biograf\u00eda tan absorbente como una buena novela hist\u00f3rica. La historia comienza con la c\u00f3moda vida de clase media de Norman en San Jos\u00e9, California, y termina con su distinguida carrera en el gobierno. Sin embargo, el libro se centra en su tiempo en el campo de internamiento de Heart Mountain. Los detalles pintan un cuadro de un entorno espartano y unas condiciones aterradoras que se hicieron m\u00e1s tolerables gracias a la creatividad y al minucioso esfuerzo de los estadounidenses de origen japon\u00e9s obligados a vivir all\u00ed durante la Segunda Guerra Mundial. El libro est\u00e1 generosamente ilustrado con fotograf\u00edas y dibujos. El retrato de la portada del joven Norman, sonriendo c\u00e1lidamente entre dos filas de alambre de espino, destaca la contradicci\u00f3n del t\u00edtulo.     <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cont\u00e9 siete referencias a los cu\u00e1queros, desde la presentaci\u00f3n de la querida e influyente maestra de Norman en el campamento, la Amiga Dorothea Foucar, hasta la secci\u00f3n m\u00e1s extensa \u201cWaging Peace\u00bb en el ap\u00e9ndice. A lo largo del libro, uno se forma la impresi\u00f3n de que los Amigos intervienen con ayuda pr\u00e1ctica. El hermano de Norman, Albert, fue uno de los muchos estudiantes a los que los cu\u00e1queros ayudaron encontrando universidades que los aceptaran, liber\u00e1ndolos as\u00ed para salir de los campamentos. Cuando una familia de Bainbridge Island, Wash., regres\u00f3 a casa despu\u00e9s de la guerra y encontr\u00f3 su granja destrozada, los Amigos trabajaron para que la operaci\u00f3n volviera a funcionar. Este sentido de la continua participaci\u00f3n de los cu\u00e1queros en el alivio del sufrimiento podr\u00eda hacer que este libro sea particularmente \u00fatil en las escuelas y hogares cu\u00e1queros. Tambi\u00e9n es potencialmente \u00fatil en entornos educativos la secci\u00f3n de 13 p\u00e1ginas de \u201cInformaci\u00f3n adicional\u00bb, que incluye informaci\u00f3n sobre \u201cSeleccionar los t\u00e9rminos correctos\u00bb y proporciona informaci\u00f3n hist\u00f3rica y perspectivas contempor\u00e1neas. Una lista de recomendaciones multimedia y una bibliograf\u00eda se suman a la utilidad del libro para la planificaci\u00f3n del curr\u00edculo.      <\/span><\/p>\n<p><span style=\"font-weight: 400;\">En una coincidencia inusual, Norman y el joven Alan Simpson se asociaron como compa\u00f1eros de tienda cuando un l\u00edder valiente llev\u00f3 a su tropa a Heart Mountain para un evento conjunto con los Scouts internados. Esa amistad, reavivada en la edad adulta y descrita extensamente en el libro, muestra la importancia de la cooperaci\u00f3n a trav\u00e9s de las l\u00edneas ideol\u00f3gicas. El libro me pareci\u00f3 fascinante de leer y lo recomiendo encarecidamente a los lectores a partir de diez a\u00f1os.  <\/span><\/p>\n","protected":false},"author":5090,"featured_media":3082831,"comment_status":"open","ping_status":"closed","template":"","categories":[10409,10323],"fpb_issue_category":[10665],"class_list":["post-3125373","fpb_book","type-fpb_book","status-publish","has-post-thumbnail","hentry","category-libros-de-diciembre-de-2019-una-estanteria-de-jovenes-amigos","category-resenas-de-libros-cuaqueros","fpb_issue_category-ninos-cuaqueros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ni\u00f1o enemigo: La historia de Norman Mineta, un ni\u00f1o encarcelado en un campo de internamiento japon\u00e9s-americano durante la Segunda Guerra Mundial - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/book\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ni\u00f1o enemigo: la historia de Norman Mineta, un ni\u00f1o encarcelado en un campo de internamiento japon\u00e9s-americano durante la Segunda Guerra Mundial\" \/>\n<meta property=\"og:description\" content=\"Por Andrea Warren. Margaret Ferguson Books, 2019. 224 p\u00e1ginas. 22,99 $\/tapa dura. Recomendado para mayores de 10 a\u00f1os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/book\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/Enemy-Child.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ni\u00f1o enemigo: la historia de Norman Mineta, un ni\u00f1o encarcelado en un campo de internamiento japon\u00e9s-americano durante la Segunda Guerra Mundial por Andrea Warren.\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\\\/\",\"name\":\"Ni\u00f1o enemigo: La historia de Norman Mineta, un ni\u00f1o encarcelado en un campo de internamiento japon\u00e9s-americano durante la Segunda Guerra Mundial - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Enemy-Child.jpg\",\"datePublished\":\"2019-12-01T06:05:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Enemy-Child.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Enemy-Child.jpg\",\"width\":600,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Books\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ni\u00f1o enemigo: La historia de Norman Mineta, un ni\u00f1o encarcelado en un campo de internamiento japon\u00e9s-americano durante la Segunda Guerra Mundial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ni\u00f1o enemigo: La historia de Norman Mineta, un ni\u00f1o encarcelado en un campo de internamiento japon\u00e9s-americano durante la Segunda Guerra Mundial - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/book\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\/","og_locale":"es_ES","og_type":"article","og_title":"Ni\u00f1o enemigo: la historia de Norman Mineta, un ni\u00f1o encarcelado en un campo de internamiento japon\u00e9s-americano durante la Segunda Guerra Mundial","og_description":"Por Andrea Warren. Margaret Ferguson Books, 2019. 224 p\u00e1ginas. 22,99 $\/tapa dura. Recomendado para mayores de 10 a\u00f1os.","og_url":"https:\/\/www.friendsjournal.org\/es\/book\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","og_image":[{"width":600,"height":667,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/Enemy-Child.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Ni\u00f1o enemigo: la historia de Norman Mineta, un ni\u00f1o encarcelado en un campo de internamiento japon\u00e9s-americano durante la Segunda Guerra Mundial por Andrea Warren.","twitter_site":"@friendsournal","twitter_misc":{"Est. reading time":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/book\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\/","url":"https:\/\/www.friendsjournal.org\/es\/book\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\/","name":"Ni\u00f1o enemigo: La historia de Norman Mineta, un ni\u00f1o encarcelado en un campo de internamiento japon\u00e9s-americano durante la Segunda Guerra Mundial - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/Enemy-Child.jpg","datePublished":"2019-12-01T06:05:17+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/book\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/book\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/Enemy-Child.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2019\/11\/Enemy-Child.jpg","width":600,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/book\/nino-enemigo-la-historia-de-norman-mineta-un-nino-encarcelado-en-un-campo-de-internamiento-japones-americano-durante-la-segunda-guerra-mundial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Books","item":"https:\/\/www.friendsjournal.org\/es\/book\/"},{"@type":"ListItem","position":3,"name":"Ni\u00f1o enemigo: La historia de Norman Mineta, un ni\u00f1o encarcelado en un campo de internamiento japon\u00e9s-americano durante la Segunda Guerra Mundial"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"author_name":"Rese\u00f1ado por Ann Birch","bio":"<p>Ann Birch es bibliotecaria de un colegio comunitario y secretaria del Meeting de El Paso (Texas).<\/p>\n"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book\/3125373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/fpb_book"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3125373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3082831"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3125373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3125373"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3125373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}