{"id":3132677,"date":"2025-11-01T01:00:00","date_gmt":"2025-11-01T05:00:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/book\/palestina-e-israel-comprendiendo-encuentros\/"},"modified":"2025-11-17T16:31:17","modified_gmt":"2025-11-17T21:31:17","slug":"palestina-e-israel-comprendiendo-encuentros","status":"publish","type":"fpb_book","link":"https:\/\/www.friendsjournal.org\/es\/book\/palestina-e-israel-comprendiendo-encuentros\/","title":{"rendered":"Palestina e Israel: comprendiendo encuentros"},"content":{"rendered":"\n<h4 class=\"wp-block-heading has-text-align-center\"><strong><em>Por Max L. Carter. Barclay Press, 2025. 320 p\u00e1ginas. 30 $\/tapa blanda.   <\/em><\/strong><\/h4>\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/bookshop.org\/lists\/friends-journal-selections-november-2025\" target=\"_blank\" rel=\"noreferrer noopener\">Comprar en QuakerBooks<\/a><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\">Max Carter, cu\u00e1quero de Carolina del Norte, brome\u00f3 una vez: \u201cEs un \u2018chiste interno\u2019 entre aquellos familiarizados con las complejidades de la pol\u00edtica de Oriente Medio que aquellos que pasan una semana en Palestina-Israel regresan para escribir un libro\u201d.<\/p>\n\n<p class=\"wp-block-paragraph\">En el caso de Carter, sin embargo, ha vivido, trabajado y viajado en Palestina-Israel durante d\u00e9cadas y ha escrito tres libros importantes sobre el tema. El primero fue <g id=\"gid_0\"><g id=\"gid_1\">Palestine and Israel: A Personal Encounter<\/g><\/g>, que cubre sus dos a\u00f1os de ense\u00f1anza en la Ramallah Friends School a principios de la d\u00e9cada de 1970 y sus observaciones mientras dirig\u00eda muchos viajes de aprendizaje de servicio a Tierra Santa cada a\u00f1o desde principios de la d\u00e9cada de 1990 hasta 2005. Su siguiente libro, coescrito con dos primos, <a href=\"https:\/\/www.friendsjournal.org\/sw\/book\/maisha-ya-annice-carter-ya-huduma-ya-quaker-kuoanisha-mazoezi-na-kanuni-nyumbani-palestina-na-kenya\/\"><em>Annice Carter\u2019s Life of Quaker Service<\/em><\/a>, incluye un enfoque en el trabajo de su t\u00eda abuela como educadora en la Ramallah Friends School bajo el Mandato Brit\u00e1nico en las d\u00e9cadas de 1920 y 1930.  <\/p>\n\n<p class=\"wp-block-paragraph\">El \u00faltimo libro de Carter, <em>Palestine and Israel: Understanding Encounters<\/em>, ofrece reflexiones detalladas sobre los viajes anuales de aprendizaje de servicio que \u00e9l y su esposa, Jane Carter, codirigieron desde 2006 hasta 2019: para estudiantes de Guilford College en enero y para Friends United Meeting (FUM) cada verano. Como participante en el viaje de aprendizaje de servicio de FUM en 2023, estaba ansioso por leer las reflexiones de Carter sobre estos viajes anteriores donde los participantes viajaron, como nosotros, por los territorios palestinos ocupados y en Israel y hablaron con pol\u00edticos, activistas por la paz y los derechos humanos, l\u00edderes religiosos, empresarios, kibbutzim, periodistas, educadores, estudiantes, excombatientes y familias palestinas comunes. <\/p>\n\n<p class=\"wp-block-paragraph\">Al igual que sus otros libros, este est\u00e1 bien escrito y es perspicaz, e incluso a veces divertido. Si bien hay alguna variaci\u00f3n en los detalles entre los diferentes grupos que Max y Jane han llevado a Palestina-Israel, hay mucha similitud en los itinerarios que se relatan en orden cronol\u00f3gico. Sin embargo, el libro no se siente demasiado repetitivo porque cada una de las personas visitadas est\u00e1 hablando en un momento diferente en el tiempo y sobre los desaf\u00edos hist\u00f3ricos enfrentados en un momento particular.  <\/p>\n\n<p class=\"wp-block-paragraph\">Esto permite que se comparta mucha perspectiva hist\u00f3rica en forma de una colorida cr\u00f3nica de viajes por un observador experimentado y astuto. Las opresivas y deterioradas condiciones de derechos humanos a lo largo del tiempo son muy evidentes. Tambi\u00e9n lo es el pensamiento en evoluci\u00f3n de diferentes actores sobre c\u00f3mo el pueblo de Palestina-Israel podr\u00eda lograr la paz, la justicia, la igualdad y la autodeterminaci\u00f3n para todos, rompiendo con el sistema de apartheid de un solo estado respaldado por Estados Unidos que ha estado en vigor durante d\u00e9cadas.  <\/p>\n\n<p class=\"wp-block-paragraph\">Encontr\u00e9 que los antecedentes hist\u00f3ricos incrustados en las cr\u00f3nicas de viaje de Carter son especialmente \u00fatiles para comprender el horrible ataque violento contra el sur de Israel por el ala militar de Ham\u00e1s el 7 de octubre de 2023, y el asalto mucho m\u00e1s masivo y continuo contra los 2,2 millones de civiles palestinos en Gaza por el Estado de Israel desde entonces, y ahora cada vez m\u00e1s en Cisjordania y Jerusal\u00e9n Este. El libro deja claro que esta explosi\u00f3n de violencia masiva de dos a\u00f1os en Palestina-Israel tiene ra\u00edces que son anteriores al 7 de octubre. Tambi\u00e9n sugiere que nuestro objetivo como pacificadores no puede ser volver al opresivo, pero menos obviamente violento, statu quo del 6 de octubre.  <\/p>\n\n<p class=\"wp-block-paragraph\">Es importante destacar que Carter describe sus muchos encuentros con palestinos e israel\u00edes comunes que buscan un futuro diferente, activistas por la paz y la justicia que imaginan una nueva realidad donde todos los palestinos e israel\u00edes puedan vivir juntos en igualdad y seguridad y con plenos derechos humanos para todos. Estas personas son las semillas de la esperanza a largo plazo para la regi\u00f3n, y rompen los tropos y estereotipos est\u00e1ndar de israel\u00edes y palestinos demasiado comunes en los medios de comunicaci\u00f3n estadounidenses durante d\u00e9cadas. Sin embargo, como muchos de estos mismos activistas por la paz y los derechos humanos explicaron a las delegaciones de Carter, no pueden lograr sus objetivos visionarios por s\u00ed solos.  <\/p>\n\n<p class=\"wp-block-paragraph\">Seg\u00fan estos activistas, una transformaci\u00f3n tan profunda requerir\u00e1 que aquellos de nosotros fuera de Palestina-Israel tambi\u00e9n participemos en el discernimiento y la educaci\u00f3n pol\u00edtica; la asistencia humanitaria; el cabildeo y la defensa de una paz justa; y diversas formas de resistencia no violenta, en particular campa\u00f1as no violentas de boicot, desinversi\u00f3n y sanciones, como se hizo para poner fin al apartheid en Sud\u00e1frica. Estas campa\u00f1as globales, dicen, deben dirigirse contra las corporaciones que se benefician de la ocupaci\u00f3n militar de Israel y las pol\u00edticas de apartheid contra los palestinos, as\u00ed como contra los gobiernos occidentales como Estados Unidos que permiten estas violaciones extremas de los derechos humanos b\u00e1sicos y el derecho internacional a trav\u00e9s de la cobertura diplom\u00e1tica en la ONU, la ayuda masiva de armas militares ofensivas y la promoci\u00f3n de narrativas falsas o incompletas sobre la regi\u00f3n. <\/p>\n\n<p class=\"wp-block-paragraph\">Todas estas solicitudes urgentes de personas de buena voluntad que viven en Palestina-Israel llegan alto y claro en las p\u00e1ginas del nuevo libro de Carter. El efecto es a la vez aleccionador y desafiante. Simplemente no es suficiente dejar todo esto al personal profesional del Friends Committee on National Legislation o del American Friends Service Committee. Agradezco a Max Carter por recordarnos nuestras propias responsabilidades morales como activistas por la paz y la justicia basados en la fe.   <\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n<p class=\"wp-block-paragraph\"><strong>Steve Chase es miembro del Friends Meeting de Washington (D.C.) y participa en el Quaker Affinity Group de la iniciativa Apartheid-Free Communities. Tambi\u00e9n es el autor del folleto de Pendle Hill   <em>\u00bfBoicot, desinversi\u00f3n y sanciones? Un cu\u00e1quero sionista reconsidera los derechos palestinos <\/em>, y es el entrevistado en el video de QuakerSpeak titulado \u201cAcerc\u00e1ndonos a una Comunidad Amada: Un Cu\u00e1quero Reconsidera Israel-Palestina\u201d.<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"author":5090,"featured_media":3132675,"comment_status":"open","ping_status":"closed","template":"","categories":[25271],"fpb_issue_category":[25268],"class_list":["post-3132677","fpb_book","type-fpb_book","status-publish","has-post-thumbnail","hentry","category-libros-de-noviembre-de-2025","fpb_issue_category-ficcion_2025"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Palestina e Israel: comprendiendo encuentros - Friends Journal<\/title>\n<meta name=\"description\" content=\"El reportaje de Max Carter desde Palestina e Israel recuerda a todos Los Amigos nuestras responsabilidades morales como activistas por la paz y la justicia desde la fe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/book\/palestina-e-israel-comprendiendo-encuentros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RESE\u00d1A: Palestina e Israel: comprendiendo encuentros\" \/>\n<meta property=\"og:description\" content=\"El reportaje de Max Carter desde Palestina e Israel recuerda a todos Los Amigos nuestras responsabilidades morales como activistas por la paz y la justicia desde la fe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/book\/palestina-e-israel-comprendiendo-encuentros\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-17T21:31:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/11\/P-I_FBcrop.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/palestina-e-israel-comprendiendo-encuentros\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/palestina-e-israel-comprendiendo-encuentros\\\/\",\"name\":\"Palestina e Israel: comprendiendo encuentros - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/palestina-e-israel-comprendiendo-encuentros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/palestina-e-israel-comprendiendo-encuentros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/P-I.jpg\",\"datePublished\":\"2025-11-01T05:00:00+00:00\",\"dateModified\":\"2025-11-17T21:31:17+00:00\",\"description\":\"El reportaje de Max Carter desde Palestina e Israel recuerda a todos Los Amigos nuestras responsabilidades morales como activistas por la paz y la justicia desde la fe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/palestina-e-israel-comprendiendo-encuentros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/palestina-e-israel-comprendiendo-encuentros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/palestina-e-israel-comprendiendo-encuentros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/P-I.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/P-I.jpg\",\"width\":500,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/palestina-e-israel-comprendiendo-encuentros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Books\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Palestina e Israel: comprendiendo encuentros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palestina e Israel: comprendiendo encuentros - Friends Journal","description":"El reportaje de Max Carter desde Palestina e Israel recuerda a todos Los Amigos nuestras responsabilidades morales como activistas por la paz y la justicia desde la fe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/book\/palestina-e-israel-comprendiendo-encuentros\/","og_locale":"es_ES","og_type":"article","og_title":"RESE\u00d1A: Palestina e Israel: comprendiendo encuentros","og_description":"El reportaje de Max Carter desde Palestina e Israel recuerda a todos Los Amigos nuestras responsabilidades morales como activistas por la paz y la justicia desde la fe.","og_url":"https:\/\/www.friendsjournal.org\/es\/book\/palestina-e-israel-comprendiendo-encuentros\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_modified_time":"2025-11-17T21:31:17+00:00","og_image":[{"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/11\/P-I_FBcrop.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@friendsournal","twitter_misc":{"Est. reading time":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/book\/palestina-e-israel-comprendiendo-encuentros\/","url":"https:\/\/www.friendsjournal.org\/es\/book\/palestina-e-israel-comprendiendo-encuentros\/","name":"Palestina e Israel: comprendiendo encuentros - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/palestina-e-israel-comprendiendo-encuentros\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/palestina-e-israel-comprendiendo-encuentros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/11\/P-I.jpg","datePublished":"2025-11-01T05:00:00+00:00","dateModified":"2025-11-17T21:31:17+00:00","description":"El reportaje de Max Carter desde Palestina e Israel recuerda a todos Los Amigos nuestras responsabilidades morales como activistas por la paz y la justicia desde la fe.","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/palestina-e-israel-comprendiendo-encuentros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/book\/palestina-e-israel-comprendiendo-encuentros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/book\/palestina-e-israel-comprendiendo-encuentros\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/11\/P-I.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/11\/P-I.jpg","width":500,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/book\/palestina-e-israel-comprendiendo-encuentros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Books","item":"https:\/\/www.friendsjournal.org\/es\/book\/"},{"@type":"ListItem","position":3,"name":"Palestina e Israel: comprendiendo encuentros"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"fpb_book_details":{"author":"","pricing":false,"quakerbooks_link":"","category_issue_link":null},"fpb_reviewer_profile_picture":false,"fpb_reviewer_name":"  Steve Chase"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book\/3132677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/fpb_book"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3132677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3132675"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3132677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3132677"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3132677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}