{"id":3132699,"date":"2025-11-01T00:50:00","date_gmt":"2025-11-01T04:50:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/book\/aflame-aprendiendo-del-silencio\/"},"modified":"2025-11-24T15:40:57","modified_gmt":"2025-11-24T20:40:57","slug":"aflame-aprendiendo-del-silencio","status":"publish","type":"fpb_book","link":"https:\/\/www.friendsjournal.org\/es\/book\/aflame-aprendiendo-del-silencio\/","title":{"rendered":"Aflame: aprendiendo del silencio"},"content":{"rendered":"\n<h4 class=\"wp-block-heading has-text-align-center\"><strong><em>Por Pico Iyer. Riverhead Books, 2025. 240 p\u00e1ginas. 30 $\/tapa dura; 13,99 $\/eBook.   <\/em><\/strong><\/h4>\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/bookshop.org\/lists\/friends-journal-selections-november-2025\" target=\"_blank\" rel=\"noreferrer noopener\">Comprar en QuakerBooks<\/a><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\"><em>Aflame: Learning from Silence<\/em> se centra en los m\u00e1s de 100 retiros que el autor Pico Iyer ha realizado a lo largo de tres d\u00e9cadas en el Hermitage, una peque\u00f1a ermita benedictina en Big Sur, California. Comparte una serie de descubrimientos de su tiempo en el Hermitage, muchos de los cuales hablan de los beneficios de la sencillez. Aunque el t\u00edtulo menciona el silencio, el libro se centra m\u00e1s ampliamente en escapar del ruido innecesario de nuestras vidas, a menudo demasiado ocupadas. A trav\u00e9s de las reflexiones del propio Iyer, la mir\u00edada de autores sobre los que reflexiona y los miembros de su comunidad del Hermitage, <em>Aflame<\/em> ofrece un b\u00e1lsamo muy necesario para el alma en estos tiempos dif\u00edciles en los que vivimos.   <\/p>\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de leer <em>Aflame<\/em>, estoy deseando experimentar la magia del Hermitage. Iyer describe c\u00f3mo la sencillez del espacio y el poder de su belleza natural permiten a los residentes y visitantes ser su mejor versi\u00f3n. Cita a Henry Miller: \u201cAl no haber nada que mejorar en el entorno, la tendencia es empezar a mejorarse a uno mismo\u00bb. Muchos visitantes reflexionan sobre el hecho de que la falta de planes y la oportunidad de \u201cvaciarse\u00bb les invitan a llenar su tiempo con \u201ctodo lo que les rodea\u00bb, incluyendo la luz del sol, las estrellas y los amigos que se pueden hacer. \u201cEscribo tantas cartas como puedo mientras estoy sobre el mar\u00bb, declara Iyer, \u201cporque este es el \u00fanico lugar donde, como dicen mis amigos budistas, la mente es tan vasta como el cielo azul y abierto\u00bb. Y observa que \u201cen el silencio, todos los desconocidos que se encuentran en la propiedad llegan a sentirse como amigos, unidos en la ra\u00edz\u00bb. Tanto la comunidad como el entorno animan a los presentes a experimentar la espiritualidad en su m\u00e1xima expresi\u00f3n.      <\/p>\n\n<p class=\"wp-block-paragraph\">Creo que las reflexiones de Iyer como escritor espiritual resonar\u00e1n entre los Amigos. Iyer comparte que \u201cla contemplaci\u00f3n, llego a ver, no significa en ning\u00fan caso cerrar los ojos, sino abrirlos a la gloria de todo lo que te rodea. Volver a tus sentidos, saliendo de tu cabeza\u00bb. Al considerar el impacto del Hermitage en su trabajo como autor, Iyer tambi\u00e9n comparte la sabidur\u00eda de grandes escritores como Franz Kafka: \u201cQu\u00e9date sentado a tu mesa y escucha. Ni siquiera escuches, simplemente espera, estate quieto, tranquilo y solitario. El mundo se te ofrecer\u00e1 libremente para ser desenmascarado\u00bb; y Albert Camus: \u201cQuer\u00eda cambiar vidas, s\u00ed, . . . pero no el mundo, al que adoraba como divino\u00bb.  <\/p>\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, muchas de las historias que comparte Iyer se basan en conversaciones que mantuvo en el Hermitage. Est\u00e1 claro que Iyer es un pensador profundo que no solo tiene ideas significativas que ofrecer por s\u00ed mismo, sino que tambi\u00e9n es receptivo a los otros buscadores del Hermitage que le ayudan a aclarar los mensajes que tiene que compartir como escritor. En otras palabras, las verdades que Iyer llega a comprender se ven reforzadas por la comunidad, como suele ocurrir con los Amigos en sus propias reuniones y otros espacios cu\u00e1queros.  <\/p>\n\n<p class=\"wp-block-paragraph\">Atesor\u00e9 cada p\u00e1gina de <em>Aflame<\/em>. El libro articula una gu\u00eda significativa sobre c\u00f3mo reducir la velocidad y escuchar a ese Dios dentro de nosotros mismos, de los dem\u00e1s y del mundo natural. Creo que los Amigos reconocer\u00e1n la fe y la pr\u00e1ctica cu\u00e1queras en las palabras y experiencias de Iyer en el Hermitage.  <\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n<p class=\"wp-block-paragraph\"><strong>Lauren Brownlee es miembro del Meeting de Bethesda (Maryland), donde forma parte del Comit\u00e9 de Paz y Justicia Social.<\/strong><\/p>\n","protected":false},"author":5090,"featured_media":3132692,"comment_status":"open","ping_status":"closed","template":"","categories":[25271],"fpb_issue_category":[25268],"class_list":["post-3132699","fpb_book","type-fpb_book","status-publish","has-post-thumbnail","hentry","category-libros-de-noviembre-de-2025","fpb_issue_category-ficcion_2025"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aflame: aprendiendo del silencio - Friends Journal<\/title>\n<meta name=\"description\" content=\"Pico Iyer ofrece una gu\u00eda \u00fatil sobre c\u00f3mo reducir el ritmo y escuchar a Dios dentro de nosotros mismos, en los dem\u00e1s y en el mundo natural.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/book\/aflame-aprendiendo-del-silencio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RESE\u00d1A: aflame: aprendiendo del silencio\" \/>\n<meta property=\"og:description\" content=\"Pico Iyer ofrece una gu\u00eda \u00fatil sobre c\u00f3mo reducir el ritmo y escuchar a Dios dentro de nosotros mismos, en los dem\u00e1s y en el mundo natural.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/book\/aflame-aprendiendo-del-silencio\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-24T20:40:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/11\/Aflame_FBcrop.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/aflame-aprendiendo-del-silencio\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/aflame-aprendiendo-del-silencio\\\/\",\"name\":\"Aflame: aprendiendo del silencio - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/aflame-aprendiendo-del-silencio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/aflame-aprendiendo-del-silencio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Aflame.png\",\"datePublished\":\"2025-11-01T04:50:00+00:00\",\"dateModified\":\"2025-11-24T20:40:57+00:00\",\"description\":\"Pico Iyer ofrece una gu\u00eda \u00fatil sobre c\u00f3mo reducir el ritmo y escuchar a Dios dentro de nosotros mismos, en los dem\u00e1s y en el mundo natural.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/aflame-aprendiendo-del-silencio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/aflame-aprendiendo-del-silencio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/aflame-aprendiendo-del-silencio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Aflame.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Aflame.png\",\"width\":500,\"height\":755},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/aflame-aprendiendo-del-silencio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Books\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/book\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aflame: aprendiendo del silencio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aflame: aprendiendo del silencio - Friends Journal","description":"Pico Iyer ofrece una gu\u00eda \u00fatil sobre c\u00f3mo reducir el ritmo y escuchar a Dios dentro de nosotros mismos, en los dem\u00e1s y en el mundo natural.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/book\/aflame-aprendiendo-del-silencio\/","og_locale":"es_ES","og_type":"article","og_title":"RESE\u00d1A: aflame: aprendiendo del silencio","og_description":"Pico Iyer ofrece una gu\u00eda \u00fatil sobre c\u00f3mo reducir el ritmo y escuchar a Dios dentro de nosotros mismos, en los dem\u00e1s y en el mundo natural.","og_url":"https:\/\/www.friendsjournal.org\/es\/book\/aflame-aprendiendo-del-silencio\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_modified_time":"2025-11-24T20:40:57+00:00","og_image":[{"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/11\/Aflame_FBcrop.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@friendsournal","twitter_misc":{"Est. reading time":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/book\/aflame-aprendiendo-del-silencio\/","url":"https:\/\/www.friendsjournal.org\/es\/book\/aflame-aprendiendo-del-silencio\/","name":"Aflame: aprendiendo del silencio - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/aflame-aprendiendo-del-silencio\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/aflame-aprendiendo-del-silencio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/11\/Aflame.png","datePublished":"2025-11-01T04:50:00+00:00","dateModified":"2025-11-24T20:40:57+00:00","description":"Pico Iyer ofrece una gu\u00eda \u00fatil sobre c\u00f3mo reducir el ritmo y escuchar a Dios dentro de nosotros mismos, en los dem\u00e1s y en el mundo natural.","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/book\/aflame-aprendiendo-del-silencio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/book\/aflame-aprendiendo-del-silencio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/book\/aflame-aprendiendo-del-silencio\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/11\/Aflame.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/11\/Aflame.png","width":500,"height":755},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/book\/aflame-aprendiendo-del-silencio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Books","item":"https:\/\/www.friendsjournal.org\/es\/book\/"},{"@type":"ListItem","position":3,"name":"Aflame: aprendiendo del silencio"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"fpb_book_details":{"author":"","pricing":false,"quakerbooks_link":"","category_issue_link":null},"fpb_reviewer_profile_picture":false,"fpb_reviewer_name":"Lauren Brownlee"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book\/3132699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_book"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/fpb_book"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3132699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3132692"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3132699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3132699"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3132699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}