{"id":3120654,"date":"2025-07-07T12:01:55","date_gmt":"2025-07-07T16:01:55","guid":{"rendered":"https:\/\/www.friendsjournal.org\/staff\/renzo-mejia-carranza\/"},"modified":"2026-03-25T20:04:28","modified_gmt":"2026-03-26T00:04:28","slug":"renzo-mejia-carranza","status":"publish","type":"fpb_staff","link":"https:\/\/www.friendsjournal.org\/es\/staff\/renzo-mejia-carranza\/","title":{"rendered":"Renzo mejia carranza"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Renzo se uni\u00f3 al equipo de Friends Publishing en junio de 2025 como Editor Correspondiente para Latinoam\u00e9rica. Le apasiona la teolog\u00eda pol\u00edtica, la teolog\u00eda dial\u00e9ctica y la tradici\u00f3n cu\u00e1quera, y tambi\u00e9n dedica tiempo a estudiar lenguas modernas y cl\u00e1sicas, particularmente las b\u00edblicas. Miembro de la Junta de Los Amigos de Fairfield (Indiana), Renzo naci\u00f3 en Ciudad de Guatemala y ahora vive en Richmond, Indiana, donde est\u00e1 cursando un MDiv en la Escuela de Religi\u00f3n del Earlham College. En su tiempo libre, disfruta leyendo filosof\u00eda, explorando la geopol\u00edtica y, por supuesto, comiendo su cocina favorita: la italiana. Puede contactar con Renzo Mejia Carranza en <a href=\"mailto:renzo@friendsjournal.org\">renzo@friendsjournal.org<\/a>.<\/p>\n\n<p class=\"wp-block-paragraph\">Renzo tambi\u00e9n est\u00e1 disponible en Signal, el servicio de mensajer\u00eda y voz y v\u00eddeo cifrado en: rzcarr.88<\/p>\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"660\" src=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/07\/File.jpg\" alt=\"\" class=\"wp-image-3134522\" style=\"width:217px;height:auto\" srcset=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/07\/File.jpg 660w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/07\/File-300x300.jpg 300w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/07\/File-150x150.jpg 150w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/07\/File-600x600.jpg 600w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/07\/File-100x100.jpg 100w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/figure>\n","protected":false},"featured_media":3136144,"template":"","categories":[],"class_list":["post-3120654","fpb_staff","type-fpb_staff","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Renzo mejia carranza - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/staff\/renzo-mejia-carranza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renzo mejia carranza - Friends Journal\" \/>\n<meta property=\"og:description\" content=\"Renzo se uni\u00f3 al equipo de Friends Publishing en junio de 2025 como Editor Correspondiente para Latinoam\u00e9rica. Le apasiona la&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/staff\/renzo-mejia-carranza\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T00:04:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/07\/renzo-headshot2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/staff\\\/renzo-mejia-carranza\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/staff\\\/renzo-mejia-carranza\\\/\",\"name\":\"Renzo mejia carranza - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/staff\\\/renzo-mejia-carranza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/staff\\\/renzo-mejia-carranza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/renzo-headshot2.jpg\",\"datePublished\":\"2025-07-07T16:01:55+00:00\",\"dateModified\":\"2026-03-26T00:04:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/staff\\\/renzo-mejia-carranza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/staff\\\/renzo-mejia-carranza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/staff\\\/renzo-mejia-carranza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/renzo-headshot2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/renzo-headshot2.jpg\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/staff\\\/renzo-mejia-carranza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renzo mejia carranza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Renzo mejia carranza - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/staff\/renzo-mejia-carranza\/","og_locale":"es_ES","og_type":"article","og_title":"Renzo mejia carranza - Friends Journal","og_description":"Renzo se uni\u00f3 al equipo de Friends Publishing en junio de 2025 como Editor Correspondiente para Latinoam\u00e9rica. Le apasiona la&hellip;","og_url":"https:\/\/www.friendsjournal.org\/es\/staff\/renzo-mejia-carranza\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_modified_time":"2026-03-26T00:04:28+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/07\/renzo-headshot2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@friendsournal","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/staff\/renzo-mejia-carranza\/","url":"https:\/\/www.friendsjournal.org\/es\/staff\/renzo-mejia-carranza\/","name":"Renzo mejia carranza - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/staff\/renzo-mejia-carranza\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/staff\/renzo-mejia-carranza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/07\/renzo-headshot2.jpg","datePublished":"2025-07-07T16:01:55+00:00","dateModified":"2026-03-26T00:04:28+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/staff\/renzo-mejia-carranza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/staff\/renzo-mejia-carranza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/staff\/renzo-mejia-carranza\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/07\/renzo-headshot2.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/07\/renzo-headshot2.jpg","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/staff\/renzo-mejia-carranza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Renzo mejia carranza"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"fpb_staff_title":"Editor corresponsal"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_staff\/3120654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_staff"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/fpb_staff"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3136144"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3120654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3120654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}