{"id":3099770,"date":"2025-09-01T00:25:00","date_gmt":"2025-09-01T04:25:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/helen-rose-dickinson\/"},"modified":"2025-10-01T14:01:55","modified_gmt":"2025-10-01T18:01:55","slug":"helen-rose-dickinson","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/es\/helen-rose-dickinson\/","title":{"rendered":"Helen Rose Dickinson"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Dickinson<\/strong>\u2014<em>Helen Rose Dickinson<\/em>, 79 a\u00f1os, el 30 de noviembre de 2024, en el centro de enfermer\u00eda Sancta Maria en Cambridge, Mass. Helen naci\u00f3 el 6 de febrero de 1945, hija de George y Ruth Brown Dickinson en Skowhegan, Maine. Fue la cuarta de siete hijos: dos ni\u00f1os y cinco ni\u00f1as.  <\/p>\n\n<p class=\"wp-block-paragraph\">Helen creci\u00f3 en Norridgewock, Maine, en una granja lechera. Le gustaba se\u00f1alar que, aunque no hab\u00eda poni, la granja familiar ten\u00eda muchas vacas, gatos trabajadores, perros, ovejas y cerdos. La granja tambi\u00e9n produc\u00eda heno, ma\u00edz y jud\u00edas verdes. Helen cultivaba su propio cuarto de acre de jud\u00edas verdes que vend\u00eda a una empresa conservera. Despu\u00e9s de pagar a sus hermanos y hermanas por ayudarla con la cosecha, Helen gastaba el resto de sus ganancias en la Feria Estatal de Skowhegan. Tambi\u00e9n le gustaba pasear por el bosque con el perro de la familia.     <\/p>\n\n<p class=\"wp-block-paragraph\">Helen asisti\u00f3 a la escuela secundaria de Skowhegan y a la Academia Bloomfield, luego fue a la Universidad de Maine, donde se especializ\u00f3 en bioqu\u00edmica, gradu\u00e1ndose en 1967. Realiz\u00f3 estudios de posgrado en la Universidad Estatal de Oreg\u00f3n, donde se gradu\u00f3 con un doctorado en bioqu\u00edmica en 1972. Helen realiz\u00f3 trabajos de postdoctorado sobre carbohidratos complejos en el Instituto de Tecnolog\u00eda de Illinois y sobre pol\u00edmeros biol\u00f3gicos en la Universidad Case Western Reserve en Cleveland, Ohio. Trabaj\u00f3 en el campo de la qu\u00edmica en Maine; el norte de Nueva York; St. Louis, Mo.; y el \u00e1rea de Chicago, Ill. Sus puestos incluyeron investigaci\u00f3n bioqu\u00edmica, investigaci\u00f3n de medicamentos gen\u00e9ricos y desarrollo de productos pl\u00e1sticos. Helen fue miembro de la Sociedad Qu\u00edmica Americana. Fue una de las editoras del bolet\u00edn del cap\u00edtulo de Chicago.<\/p>\n\n<p class=\"wp-block-paragraph\">Helen se crio en la Iglesia Congregacional y m\u00e1s tarde asisti\u00f3 a la Iglesia Unitaria. Asisti\u00f3 a su primera Junta de Los Amigos cuando viv\u00eda en St. Louis. A Helen le atrajo el estilo de culto, ya que ten\u00eda un inter\u00e9s de larga data en la meditaci\u00f3n. Finalmente, Helen se uni\u00f3 y fue un miembro activo de la Junta de Oak Park (Illinois). Form\u00f3 parte del Comit\u00e9 de Supervisar; aconsejar, fue secretaria de actas dos veces y secretaria de la Junta dos veces.    <\/p>\n\n<p class=\"wp-block-paragraph\">Los intereses de Helen eran variados. Fue miembro de Toastmasters International y le gustaba pintar y hacer fotograf\u00eda. Tom\u00f3 clases de flauta y posteriormente se uni\u00f3 a la Triton College Community Band. La Junta de Oak Park disfrut\u00f3 escuch\u00e1ndola tocar la flauta en varias ocasiones.   <\/p>\n\n<p class=\"wp-block-paragraph\">Mientras estaba en la banda, Helen conoci\u00f3 a su buena amiga Louise. Louise era la instructora de observaci\u00f3n de aves de Triton. Introdujo a Helen en la observaci\u00f3n de aves a trav\u00e9s del curso anual de seis semanas de Triton. Helen asisti\u00f3 al curso durante m\u00e1s de diez a\u00f1os.   <\/p>\n\n<p class=\"wp-block-paragraph\">Helen se jubil\u00f3 en 2019 de Fresenius Kabi, una empresa mundial de tecnolog\u00eda m\u00e9dica con sede en Melrose Park, Ill. Tras su jubilaci\u00f3n, se mantuvo en forma dando paseos diarios, a menudo con una amiga, por su vecindario de Elmwood Park. Disfrutaba particularmente viendo los p\u00e1jaros y los enormes \u00e1rboles.  <\/p>\n\n<p class=\"wp-block-paragraph\">A Helen le precedieron sus padres.<\/p>\n\n<p class=\"wp-block-paragraph\">Le sobreviven dos hermanos, Richard Dickinson y Frank Dickinson; cuatro hermanas, Trudy Tremblay, Colleen Dillon (William), Lorna Bradbury (Gordon) y Elizabeth Eggleston (James); 12 sobrinas y sobrinos; y 14 sobrinas y sobrinos nietos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dickinson\u2014Helen Rose Dickinson, 79 a\u00f1os, el 30 de noviembre de 2024, en el centro de enfermer\u00eda Sancta Maria en Cambridge,&hellip;<\/p>\n","protected":false},"author":5090,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9829],"tags":[],"fpb_issue_category":[9831],"class_list":["post-3099770","post","type-post","status-publish","format-standard","hentry","category-hitos","fpb_issue_category-septiembre-de-2025"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Helen Rose Dickinson - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/helen-rose-dickinson\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Helen Rose Dickinson\" \/>\n<meta property=\"og:description\" content=\"Dickinson\u2014Helen Rose Dickinson, 79 a\u00f1os, el 30 de noviembre de 2024, en el centro de enfermer\u00eda Sancta Maria en Cambridge,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/helen-rose-dickinson\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-01T04:25:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-01T18:01:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"779\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Friends Journal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Friends Journal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/helen-rose-dickinson\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/helen-rose-dickinson\\\/\"},\"author\":{\"name\":\"Friends Journal\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/315ffb22a36ecbabdf5dbdc09d7d1eb7\"},\"headline\":\"Helen Rose Dickinson\",\"datePublished\":\"2025-09-01T04:25:00+00:00\",\"dateModified\":\"2025-10-01T18:01:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/helen-rose-dickinson\\\/\"},\"wordCount\":582,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"articleSection\":[\"Hitos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/helen-rose-dickinson\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/helen-rose-dickinson\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/helen-rose-dickinson\\\/\",\"name\":\"Helen Rose Dickinson - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"datePublished\":\"2025-09-01T04:25:00+00:00\",\"dateModified\":\"2025-10-01T18:01:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/helen-rose-dickinson\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/helen-rose-dickinson\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/helen-rose-dickinson\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Helen Rose Dickinson\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/315ffb22a36ecbabdf5dbdc09d7d1eb7\",\"name\":\"Friends Journal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"caption\":\"Friends Journal\"},\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/author\\\/alla-podolsky\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Helen Rose Dickinson - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/helen-rose-dickinson\/","og_locale":"es_ES","og_type":"article","og_title":"Helen Rose Dickinson","og_description":"Dickinson\u2014Helen Rose Dickinson, 79 a\u00f1os, el 30 de noviembre de 2024, en el centro de enfermer\u00eda Sancta Maria en Cambridge,&hellip;","og_url":"https:\/\/www.friendsjournal.org\/es\/helen-rose-dickinson\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"2025-09-01T04:25:00+00:00","article_modified_time":"2025-10-01T18:01:55+00:00","og_image":[{"width":779,"height":438,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg","type":"image\/jpeg"}],"author":"Friends Journal","twitter_card":"summary_large_image","twitter_creator":"@friendsournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"Friends Journal","Est. reading time":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/es\/helen-rose-dickinson\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/helen-rose-dickinson\/"},"author":{"name":"Friends Journal","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/315ffb22a36ecbabdf5dbdc09d7d1eb7"},"headline":"Helen Rose Dickinson","datePublished":"2025-09-01T04:25:00+00:00","dateModified":"2025-10-01T18:01:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/helen-rose-dickinson\/"},"wordCount":582,"commentCount":0,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"articleSection":["Hitos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.friendsjournal.org\/es\/helen-rose-dickinson\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/helen-rose-dickinson\/","url":"https:\/\/www.friendsjournal.org\/es\/helen-rose-dickinson\/","name":"Helen Rose Dickinson - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"datePublished":"2025-09-01T04:25:00+00:00","dateModified":"2025-10-01T18:01:55+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/helen-rose-dickinson\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/helen-rose-dickinson\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/helen-rose-dickinson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Helen Rose Dickinson"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/315ffb22a36ecbabdf5dbdc09d7d1eb7","name":"Friends Journal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","caption":"Friends Journal"},"url":"https:\/\/www.friendsjournal.org\/es\/author\/alla-podolsky\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"author_name":"Equipo"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3099770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3099770"}],"version-history":[{"count":2,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3099770\/revisions"}],"predecessor-version":[{"id":3100334,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3099770\/revisions\/3100334"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3099770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3099770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/tags?post=3099770"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3099770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}