{"id":3101041,"date":"1955-11-19T00:00:00","date_gmt":"1955-11-19T05:00:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/dificultades-de-aprendizaje\/"},"modified":"1955-11-19T00:00:00","modified_gmt":"1955-11-19T05:00:00","slug":"dificultades-de-aprendizaje","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/es\/dificultades-de-aprendizaje\/","title":{"rendered":"Dificultades de aprendizaje"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2159,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"fpb_issue_category":[],"class_list":["post-3101041","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dificultades de aprendizaje - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/dificultades-de-aprendizaje\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dificultades de aprendizaje - Friends Journal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/dificultades-de-aprendizaje\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"1955-11-19T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"779\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"E Noonan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"E Noonan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/dificultades-de-aprendizaje\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/dificultades-de-aprendizaje\\\/\"},\"author\":{\"name\":\"E Noonan\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/265cc952305ef424621c0dd4c1cc903b\"},\"headline\":\"Dificultades de aprendizaje\",\"datePublished\":\"1955-11-19T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/dificultades-de-aprendizaje\\\/\"},\"wordCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/dificultades-de-aprendizaje\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/dificultades-de-aprendizaje\\\/\",\"name\":\"Dificultades de aprendizaje - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"datePublished\":\"1955-11-19T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/dificultades-de-aprendizaje\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/dificultades-de-aprendizaje\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/dificultades-de-aprendizaje\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dificultades de aprendizaje\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/265cc952305ef424621c0dd4c1cc903b\",\"name\":\"E Noonan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cf60754b1e3e8e4a2d5d7737ea0416e441ac01b12b1408e6cf2af424f29719b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cf60754b1e3e8e4a2d5d7737ea0416e441ac01b12b1408e6cf2af424f29719b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cf60754b1e3e8e4a2d5d7737ea0416e441ac01b12b1408e6cf2af424f29719b?s=96&d=mm&r=g\",\"caption\":\"E Noonan\"},\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/author\\\/enoonan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dificultades de aprendizaje - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/dificultades-de-aprendizaje\/","og_locale":"es_ES","og_type":"article","og_title":"Dificultades de aprendizaje - Friends Journal","og_url":"https:\/\/www.friendsjournal.org\/es\/dificultades-de-aprendizaje\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"1955-11-19T05:00:00+00:00","og_image":[{"width":779,"height":438,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg","type":"image\/jpeg"}],"author":"E Noonan","twitter_card":"summary_large_image","twitter_creator":"@friendsournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"E Noonan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/es\/dificultades-de-aprendizaje\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/dificultades-de-aprendizaje\/"},"author":{"name":"E Noonan","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/265cc952305ef424621c0dd4c1cc903b"},"headline":"Dificultades de aprendizaje","datePublished":"1955-11-19T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/dificultades-de-aprendizaje\/"},"wordCount":3,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/dificultades-de-aprendizaje\/","url":"https:\/\/www.friendsjournal.org\/es\/dificultades-de-aprendizaje\/","name":"Dificultades de aprendizaje - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"datePublished":"1955-11-19T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/dificultades-de-aprendizaje\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/dificultades-de-aprendizaje\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/dificultades-de-aprendizaje\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Dificultades de aprendizaje"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/265cc952305ef424621c0dd4c1cc903b","name":"E Noonan","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0cf60754b1e3e8e4a2d5d7737ea0416e441ac01b12b1408e6cf2af424f29719b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0cf60754b1e3e8e4a2d5d7737ea0416e441ac01b12b1408e6cf2af424f29719b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0cf60754b1e3e8e4a2d5d7737ea0416e441ac01b12b1408e6cf2af424f29719b?s=96&d=mm&r=g","caption":"E Noonan"},"url":"https:\/\/www.friendsjournal.org\/es\/author\/enoonan\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"fpb_author_profile_picture":null,"author_name":"E. Gillet Ketchum","bio":null,"issue":null,"issue_path":null,"page_number":null,"fpb_display_featured_image":null,"fj_schema_markup":null},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3101041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/2159"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3101041"}],"version-history":[{"count":0,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3101041\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3101041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3101041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/tags?post=3101041"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3101041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}