{"id":3112496,"date":"1990-03-01T00:00:44","date_gmt":"1990-03-01T05:00:44","guid":{"rendered":"https:\/\/www.friendsjournal.org\/en-un-asiento-solido\/"},"modified":"1990-03-01T00:00:44","modified_gmt":"1990-03-01T05:00:44","slug":"en-un-asiento-solido","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/es\/en-un-asiento-solido\/","title":{"rendered":"En un asiento s\u00f3lido"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1052,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"fpb_issue_category":[],"class_list":["post-3112496","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En un asiento s\u00f3lido - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/en-un-asiento-solido\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En un asiento s\u00f3lido - Friends Journal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/en-un-asiento-solido\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"1990-03-01T05:00:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"779\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SusanKaul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"SusanKaul\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/en-un-asiento-solido\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/en-un-asiento-solido\\\/\"},\"author\":{\"name\":\"SusanKaul\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/4802c3baea8e6ea1dd39e247ddb4f5ff\"},\"headline\":\"En un asiento s\u00f3lido\",\"datePublished\":\"1990-03-01T05:00:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/en-un-asiento-solido\\\/\"},\"wordCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/en-un-asiento-solido\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/en-un-asiento-solido\\\/\",\"name\":\"En un asiento s\u00f3lido - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"datePublished\":\"1990-03-01T05:00:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/en-un-asiento-solido\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/en-un-asiento-solido\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/en-un-asiento-solido\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En un asiento s\u00f3lido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/4802c3baea8e6ea1dd39e247ddb4f5ff\",\"name\":\"SusanKaul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"SusanKaul\"},\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/author\\\/susankaul\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En un asiento s\u00f3lido - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/en-un-asiento-solido\/","og_locale":"es_ES","og_type":"article","og_title":"En un asiento s\u00f3lido - Friends Journal","og_url":"https:\/\/www.friendsjournal.org\/es\/en-un-asiento-solido\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"1990-03-01T05:00:44+00:00","og_image":[{"width":779,"height":438,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg","type":"image\/jpeg"}],"author":"SusanKaul","twitter_card":"summary_large_image","twitter_creator":"@friendsournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"SusanKaul"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/es\/en-un-asiento-solido\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/en-un-asiento-solido\/"},"author":{"name":"SusanKaul","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/4802c3baea8e6ea1dd39e247ddb4f5ff"},"headline":"En un asiento s\u00f3lido","datePublished":"1990-03-01T05:00:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/en-un-asiento-solido\/"},"wordCount":5,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/en-un-asiento-solido\/","url":"https:\/\/www.friendsjournal.org\/es\/en-un-asiento-solido\/","name":"En un asiento s\u00f3lido - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"datePublished":"1990-03-01T05:00:44+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/en-un-asiento-solido\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/en-un-asiento-solido\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/en-un-asiento-solido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"En un asiento s\u00f3lido"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/4802c3baea8e6ea1dd39e247ddb4f5ff","name":"SusanKaul","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"SusanKaul"},"url":"https:\/\/www.friendsjournal.org\/es\/author\/susankaul\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"fpb_author_profile_picture":null,"author_name":"Brian Drayton","bio":null,"issue":null,"issue_path":null,"page_number":null,"fpb_display_featured_image":null,"fj_schema_markup":null},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3112496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/1052"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3112496"}],"version-history":[{"count":0,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3112496\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3112496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3112496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/tags?post=3112496"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3112496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}