{"id":3115368,"date":"2000-01-01T00:00:43","date_gmt":"2000-01-01T05:00:43","guid":{"rendered":"https:\/\/www.friendsjournal.org\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\/"},"modified":"2000-01-01T00:00:43","modified_gmt":"2000-01-01T05:00:43","slug":"la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/es\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\/","title":{"rendered":"La fe detr\u00e1s de la fe: sobre caminar alegremente en tiempos oscuros"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1719,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"fpb_issue_category":[],"class_list":["post-3115368","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La fe detr\u00e1s de la fe: sobre caminar alegremente en tiempos oscuros - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La fe detr\u00e1s de la fe: sobre caminar alegremente en tiempos oscuros - Friends Journal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"2000-01-01T05:00:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"779\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"John Edwards\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"John Edwards\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\\\/\"},\"author\":{\"name\":\"John Edwards\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/c2b19588946f73617ffa9de58f38ed86\"},\"headline\":\"La fe detr\u00e1s de la fe: sobre caminar alegremente en tiempos oscuros\",\"datePublished\":\"2000-01-01T05:00:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\\\/\"},\"wordCount\":13,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\\\/\",\"name\":\"La fe detr\u00e1s de la fe: sobre caminar alegremente en tiempos oscuros - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"datePublished\":\"2000-01-01T05:00:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La fe detr\u00e1s de la fe: sobre caminar alegremente en tiempos oscuros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/c2b19588946f73617ffa9de58f38ed86\",\"name\":\"John Edwards\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd557a588354bdd47514d67bbe9a026c5aba18eb478a2eae14e7f61c9b1dbd8b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd557a588354bdd47514d67bbe9a026c5aba18eb478a2eae14e7f61c9b1dbd8b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd557a588354bdd47514d67bbe9a026c5aba18eb478a2eae14e7f61c9b1dbd8b?s=96&d=mm&r=g\",\"caption\":\"John Edwards\"},\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/author\\\/johnedwards\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La fe detr\u00e1s de la fe: sobre caminar alegremente en tiempos oscuros - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\/","og_locale":"es_ES","og_type":"article","og_title":"La fe detr\u00e1s de la fe: sobre caminar alegremente en tiempos oscuros - Friends Journal","og_url":"https:\/\/www.friendsjournal.org\/es\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"2000-01-01T05:00:43+00:00","og_image":[{"width":779,"height":438,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg","type":"image\/jpeg"}],"author":"John Edwards","twitter_card":"summary_large_image","twitter_creator":"@friendsournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"John Edwards"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/es\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\/"},"author":{"name":"John Edwards","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/c2b19588946f73617ffa9de58f38ed86"},"headline":"La fe detr\u00e1s de la fe: sobre caminar alegremente en tiempos oscuros","datePublished":"2000-01-01T05:00:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\/"},"wordCount":13,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\/","url":"https:\/\/www.friendsjournal.org\/es\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\/","name":"La fe detr\u00e1s de la fe: sobre caminar alegremente en tiempos oscuros - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"datePublished":"2000-01-01T05:00:43+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/la-fe-detras-de-la-fe-sobre-caminar-alegremente-en-tiempos-oscuros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"La fe detr\u00e1s de la fe: sobre caminar alegremente en tiempos oscuros"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/c2b19588946f73617ffa9de58f38ed86","name":"John Edwards","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/dd557a588354bdd47514d67bbe9a026c5aba18eb478a2eae14e7f61c9b1dbd8b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd557a588354bdd47514d67bbe9a026c5aba18eb478a2eae14e7f61c9b1dbd8b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd557a588354bdd47514d67bbe9a026c5aba18eb478a2eae14e7f61c9b1dbd8b?s=96&d=mm&r=g","caption":"John Edwards"},"url":"https:\/\/www.friendsjournal.org\/es\/author\/johnedwards\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"fpb_author_profile_picture":null,"author_name":"Keith Helmuth","bio":null,"issue":null,"issue_path":null,"page_number":null,"fpb_display_featured_image":null,"fj_schema_markup":null},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3115368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/1719"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3115368"}],"version-history":[{"count":0,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3115368\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3115368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3115368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/tags?post=3115368"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3115368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}