{"id":3115650,"date":"2001-06-01T00:00:38","date_gmt":"2001-06-01T04:00:38","guid":{"rendered":"https:\/\/www.friendsjournal.org\/amigos-como-sanadores\/"},"modified":"2001-06-01T00:00:38","modified_gmt":"2001-06-01T04:00:38","slug":"amigos-como-sanadores","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/es\/amigos-como-sanadores\/","title":{"rendered":"Amigos como sanadores"},"content":{"rendered":"<p>Veinte Amigos se sientan c\u00f3modamente en c\u00edrculo bajo el sol que calienta el centro de retiro de Powell House. Mientras algunos Amigos miran alrededor de la sala, hacia arriba o por las ventanas que dan al paisaje cubierto de nieve, la mayor\u00eda tienen los ojos cerrados y se est\u00e1n acomodando en el silencio familiar y la reuni\u00f3n del Esp\u00edritu com\u00fan a un Meeting cu\u00e1quero para el culto. Una cosa, sin embargo, distingue este Meeting del culto habitual: dos sillas vac\u00edas se encuentran dentro del c\u00edrculo.  <\/p>\n<p>La sensaci\u00f3n de calidez y culto, la reuni\u00f3n de amor y Esp\u00edritu comienza a asentarse m\u00e1s plenamente alrededor del grupo. En breve, una joven se levanta de su asiento en el sof\u00e1 y camina hacia la silla en el centro del c\u00edrculo y se sienta, con los ojos cerrados, en silenciosa espera. En unos momentos, otra mujer entra y suavemente pone las manos sobre sus hombros. Pronto se les une un hombre que viene y le toma las manos.   <\/p>\n<p>El tiempo parece suspenderse a medida que la energ\u00eda en la sala se vuelve m\u00e1s vibrante y enfocada. El rostro de la joven responde al amor y al cuidado, y comienza a llorar. Su cuerpo se tensa y luego se relaja. Otro miembro se une a los reunidos en el centro; se arrodilla y acuna sus pies, mientras que los que la rodean contin\u00faan sentados en silencio y sostienen la ahora palpable energ\u00eda.   <\/p>\n<p>Despu\u00e9s de varios minutos, primero uno y luego el segundo y tercer Amigo retiran suavemente sus manos y dan un paso atr\u00e1s. Por un momento se quedan de pie en un peque\u00f1o c\u00edrculo con los brazos extendidos alrededor de la mujer mientras ella contin\u00faa sentada, las \u00faltimas l\u00e1grimas movi\u00e9ndose lentamente por sus mejillas. Uno por uno, reanudan sus asientos entre el c\u00edrculo m\u00e1s amplio, a los que se une un momento despu\u00e9s la joven, visiblemente cambiada.  <\/p>\n<p>Se ha producido una curaci\u00f3n espiritual entre Amigos.<\/p>\n<p>Durante la siguiente hora m\u00e1s o menos, varias personas m\u00e1s se acercan a las sillas interiores y los Amigos se sienten atra\u00eddos a intervenir y poner las manos sobre las cabezas y los corazones y, muy silenciosamente, se realiza un poderoso trabajo de curaci\u00f3n. Despu\u00e9s de esto, los nombres de los seres queridos se pronuncian en el centro para ser sostenidos en la Luz del amor y la curaci\u00f3n a distancia. El Meeting se cierra con las manos tomadas alrededor del c\u00edrculo, que abunda en gratitud y energ\u00eda curativa que fluye a trav\u00e9s de todos.  <\/p>\n<p>Dos de estos Meetings de \u201cculto para la curaci\u00f3n\u00bb se llevaron a cabo durante la Primera Reuni\u00f3n Anual de Sanadores Cu\u00e1queros. Amigos que practican una variedad de trabajo de curaci\u00f3n, tanto de forma independiente como dentro de los Meetings cu\u00e1queros, se reunieron desde Maryland, Nueva York, Vermont, Massachusetts y puntos intermedios en Powell House, el centro de retiro del Meeting Anual de Nueva York, durante el fin de semana del 22 al 25 de febrero de 2001, para compartir nuestro conocimiento y experiencia del trabajo de curaci\u00f3n como Amigos y para comenzar una red para conectarnos. <\/p>\n<p>Nos tomamos tiempo para aprender sobre el papel de los primeros cu\u00e1queros como sanadores. A partir de numerosos ejemplos hist\u00f3ricos, escuchamos sobre las luchas de los Amigos para hacer trabajo de curaci\u00f3n y mantener su integridad; c\u00f3mo tuvieron que enfrentar la persecuci\u00f3n; y, lamentablemente, c\u00f3mo el miedo finalmente llev\u00f3 a muchos Amigos sanadores a la oscuridad y caus\u00f3 la destrucci\u00f3n del <em>Libro de los Milagros<\/em> de George Fox. <\/p>\n<p>En nuestro pasado m\u00e1s reciente, hemos estado presenciando un retorno de la actividad de curaci\u00f3n dentro de la Sociedad Religiosa de los Amigos. Ha habido un aumento de las solicitudes de talleres relacionados con la curaci\u00f3n dentro de los entornos de la Conferencia General de los Amigos, las reuniones anuales, Pendle Hill y otros retiros cu\u00e1queros. Estos han tenido una buena asistencia, y el trabajo se est\u00e1 llevando de vuelta a los Meetings individuales en forma de culto de curaci\u00f3n.  <\/p>\n<p>\u00bfQu\u00e9 significa ser un sanador cu\u00e1quero? \u00bfC\u00f3mo discernimos lo que es simplemente basado en el ego y lo que es una verdadera gu\u00eda? Una vez que reconocemos que tenemos este don de la curaci\u00f3n, \u00bfentonces qu\u00e9? \u00bfQu\u00e9 es la curaci\u00f3n, de todos modos? Estas fueron solo algunas de las muchas preguntas que surgieron y se exploraron durante esta nevada reuni\u00f3n de fin de semana en Old Chatham, Nueva York.    <\/p>\n<p>Al hablar sobre el trabajo de curaci\u00f3n, uno descubre cu\u00e1n limitado es nuestro lenguaje ordinario. Las palabras no transmiten las profundas experiencias que tenemos, y gran parte de lo que sucede en las sesiones de curaci\u00f3n no se ve y no se habla f\u00e1cilmente. Si bien algunas personas pueden ver el movimiento de la energ\u00eda en varias formas, otras lo sienten o lo perciben, pero la mayor\u00eda de nosotros debemos confiar en la fe. La curaci\u00f3n no suele aparecer evidente como en los milagros de Jes\u00fas. Los s\u00edntomas pueden no desaparecer, la enfermedad puede no curarse, la muerte llega de todos modos. No existen est\u00e1ndares concretos mediante los cuales podamos medir y conocer la autenticidad de este don. Sin embargo, se nos recuerda que la curaci\u00f3n es un proceso de transformaci\u00f3n que est\u00e1 disponible para todos.      <\/p>\n<p>A medida que compartimos nuestras propias historias personales, descubrimos que hab\u00edamos llegado al ministerio de curaci\u00f3n de diferentes maneras y por diferentes razones; tenemos varios m\u00e9todos de trabajo y de ver el proceso de curaci\u00f3n. Para algunos, existe una cierta t\u00e9cnica estudiada que abre el camino; para otros, es un proceso de ser guiado y de reconocer un don. Requiere que nos abramos a nuestra intuici\u00f3n y visi\u00f3n y dejemos de lado nuestro \u201cyo\u00bb para permitir que el Esp\u00edritu y el poder de la curaci\u00f3n fluyan a trav\u00e9s de nosotros. Algunos dicen que usamos nuestras manos como conductos para el poder de la curaci\u00f3n de Dios. Tambi\u00e9n podr\u00eda expresarse que el Esp\u00edritu nos usa a nosotros. Otros usan el poder de la oraci\u00f3n reunida y el modelo de Jes\u00fas para guiar el trabajo. En todos los casos, es una llamada a la que debemos responder, una llamada que es continua y profunda.      <\/p>\n<p>\u00bfC\u00f3mo sabemos cu\u00e1ndo una gu\u00eda para curar es una verdadera gu\u00eda y no solo algo que creemos que queremos hacer? A menudo, la llamada a la curaci\u00f3n es algo que no hemos planeado ni nunca hubi\u00e9ramos imaginado para nosotros mismos. Es posible que no lleguemos a ella por elecci\u00f3n o incluso voluntariamente. Es un viaje de aprendizaje sagrado que exige la entrega a lo que creemos que no podemos hacer e incluso podemos tener miedo. El coraje para persistir no es la ausencia de miedo, sino m\u00e1s bien hacer algo frente a ese miedo. Cuando se sigue una verdadera gu\u00eda, lo imposible parece posible y emocionante, y luego, por gracia, la tarea en cuesti\u00f3n se vuelve f\u00e1cil y alegre. Debemos confiar y recordar que nunca estamos solos.      <\/p>\n<p>En este viaje de curaci\u00f3n, es importante conocer la naturaleza de nuestro propio camino y mantener el equilibrio en nuestras vidas. Como sanadores que de tantas maneras nutren a otros, tambi\u00e9n debemos recordar nutrirnos y protegernos a nosotros mismos. Como grupo, compartimos muchas formas valiosas de practicar el autocuidado, f\u00edsica, emocional y espiritualmente. Es esencial para nuestro bienestar que creemos espacio en nuestras vidas para la paz y la reflexi\u00f3n tranquila. En este trabajo, donde a menudo lidiamos con mucho dolor, el humor puede ser un gran b\u00e1lsamo y limpiador.    <\/p>\n<p>El tema m\u00e1s controvertido entre nosotros fue el t\u00edtulo \u201cSanadores Cu\u00e1queros\u00bb. Algunos sienten que su trabajo de curaci\u00f3n no debe ser nombrado dentro de un contexto religioso, mientras que otros sienten que es esencial que su gu\u00eda se identifique en el contexto de su fe y pr\u00e1ctica cu\u00e1quera. Para algunos, la palabra \u201csanador\u00bb es inc\u00f3moda ya que establece una expectativa err\u00f3nea de que uno puede curar a otro. Este trabajo no se trata de reclamar ese poder para nosotros mismos.   <\/p>\n<p>Este fue un fin de semana de profundo compartir, curaci\u00f3n y descubrimiento. Las discusiones fueron ricas. Encontramos consuelo en nuestra singularidad y diversidad como Amigos, que todas nuestras diferentes voces juntas traen un regalo a la comunidad. Aunque no todos resonamos en c\u00f3mo nombrar a este grupo emergente, todos sentimos que nuestra Luz era honrada entre los Amigos en nuestro terreno com\u00fan del ministerio de curaci\u00f3n. Nos fuimos con una firme resoluci\u00f3n de reunirnos nuevamente el pr\u00f3ximo a\u00f1o en una segunda reuni\u00f3n anual, sin importar c\u00f3mo decidamos llamarnos. Cuando salimos al paisaje reci\u00e9n cubierto de nieve para regresar a nuestros Meetings de origen, fuimos profundamente fortalecidos y afirmados en nuestros ministerios de curaci\u00f3n.     <\/p>\n<blockquote><p>\u201cAhora bien, hay diversidad de dones, pero el mismo Esp\u00edritu. . . . Porque a uno le es dada por el Esp\u00edritu palabra de sabidur\u00eda; a otro, palabra de ciencia . . . ; a otro, fe . . . ; a otro, dones de sanidad . . . ; a otro, el hacer milagros; a otro, profec\u00eda; a otro, el discernimiento de esp\u00edritus . . . ; Pero todas estas cosas las hace uno y el mismo Esp\u00edritu. . . .\u00bb<br \/>\n\u20141 Corintios 12:4-11<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Veinte Amigos se sientan c\u00f3modamente en c\u00edrculo bajo el sol que calienta el centro de retiro de Powell House. Mientras&hellip;<\/p>\n","protected":false},"author":285,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9799],"tags":[11477,11485,11494],"fpb_issue_category":[],"class_list":["post-3115650","post","type-post","status-publish","format-standard","hentry","category-cronicas","tag-actualidad","tag-el-cuaquerismo-hoy","tag-sanacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amigos como sanadores - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/amigos-como-sanadores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amigos como sanadores - Friends Journal\" \/>\n<meta property=\"og:description\" content=\"Veinte Amigos se sientan c\u00f3modamente en c\u00edrculo bajo el sol que calienta el centro de retiro de Powell House. Mientras&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/amigos-como-sanadores\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"2001-06-01T04:00:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"779\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"BobbiandCurtisBailinBuffy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"BobbiandCurtisBailinBuffy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/amigos-como-sanadores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/amigos-como-sanadores\\\/\"},\"author\":{\"name\":\"BobbiandCurtisBailinBuffy\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/5b5ec6f63611bff01b4876b327a841d0\"},\"headline\":\"Amigos como sanadores\",\"datePublished\":\"2001-06-01T04:00:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/amigos-como-sanadores\\\/\"},\"wordCount\":1622,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"keywords\":[\"Actualidad\",\"El cuaquerismo hoy\",\"Sanaci\u00f3n\"],\"articleSection\":[\"cr\u00f3nicas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/amigos-como-sanadores\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/amigos-como-sanadores\\\/\",\"name\":\"Amigos como sanadores - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"datePublished\":\"2001-06-01T04:00:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/amigos-como-sanadores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/amigos-como-sanadores\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/amigos-como-sanadores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amigos como sanadores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/5b5ec6f63611bff01b4876b327a841d0\",\"name\":\"BobbiandCurtisBailinBuffy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"BobbiandCurtisBailinBuffy\"},\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/author\\\/bobbiandcurtisbailinbuffy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amigos como sanadores - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/amigos-como-sanadores\/","og_locale":"es_ES","og_type":"article","og_title":"Amigos como sanadores - Friends Journal","og_description":"Veinte Amigos se sientan c\u00f3modamente en c\u00edrculo bajo el sol que calienta el centro de retiro de Powell House. Mientras&hellip;","og_url":"https:\/\/www.friendsjournal.org\/es\/amigos-como-sanadores\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"2001-06-01T04:00:38+00:00","og_image":[{"width":779,"height":438,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg","type":"image\/jpeg"}],"author":"BobbiandCurtisBailinBuffy","twitter_card":"summary_large_image","twitter_creator":"@friendsournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"BobbiandCurtisBailinBuffy","Est. reading time":"8 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/es\/amigos-como-sanadores\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/amigos-como-sanadores\/"},"author":{"name":"BobbiandCurtisBailinBuffy","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/5b5ec6f63611bff01b4876b327a841d0"},"headline":"Amigos como sanadores","datePublished":"2001-06-01T04:00:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/amigos-como-sanadores\/"},"wordCount":1622,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"keywords":["Actualidad","El cuaquerismo hoy","Sanaci\u00f3n"],"articleSection":["cr\u00f3nicas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/amigos-como-sanadores\/","url":"https:\/\/www.friendsjournal.org\/es\/amigos-como-sanadores\/","name":"Amigos como sanadores - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"datePublished":"2001-06-01T04:00:38+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/amigos-como-sanadores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/amigos-como-sanadores\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/amigos-como-sanadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Amigos como sanadores"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/5b5ec6f63611bff01b4876b327a841d0","name":"BobbiandCurtisBailinBuffy","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"BobbiandCurtisBailinBuffy"},"url":"https:\/\/www.friendsjournal.org\/es\/author\/bobbiandcurtisbailinbuffy\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"author_name":"Bobbi Bailin y Buffy Curtis","issue":"Junio de 2001"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3115650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/285"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3115650"}],"version-history":[{"count":0,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3115650\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3115650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3115650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/tags?post=3115650"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3115650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}