{"id":3116657,"date":"2004-07-01T00:00:51","date_gmt":"2004-07-01T04:00:51","guid":{"rendered":"https:\/\/www.friendsjournal.org\/para-que-sirve-la-jubilacion\/"},"modified":"2004-07-01T00:00:51","modified_gmt":"2004-07-01T04:00:51","slug":"para-que-sirve-la-jubilacion","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/es\/para-que-sirve-la-jubilacion\/","title":{"rendered":"\u00bfPara qu\u00e9 sirve la jubilaci\u00f3n?"},"content":{"rendered":"<p>Durante un tiempo, en el verano de 2003, fui consciente de que hab\u00eda una pregunta sin respuesta esperando a ser formulada. A medida que me manten\u00eda consciente de ello, empec\u00e9 a plantear la pregunta a lo largo de una l\u00ednea de progresi\u00f3n particular: De joven, me preguntaban qu\u00e9 quer\u00eda ser. Yo respond\u00eda arquitecto, ingeniero, carpintero. La vida estaba contenida en la familia, la escuela, la escuela dominical y las actividades del Meeting. Ansiaba ir a la escuela secundaria y a los Boy Scouts. Para eso era la vida.     <\/p>\n<p>Cuando llegu\u00e9 a la escuela secundaria, mir\u00e9 hacia el futuro, hacia el instituto, donde pod\u00eda elegir entre cursos preparatorios para la universidad, talleres o cursos de empresariales, con algunas opciones secundarias en cada uno. Tambi\u00e9n hab\u00eda una variedad de actividades en las que pod\u00eda participar. Los Scouts ten\u00edan una progresi\u00f3n establecida de rangos y muchas insignias de m\u00e9rito para elegir, junto con actividades como acampadas, jamborees y servicio comunitario. Y la universidad estaba a la vuelta de la esquina. Para eso era la vida.    <\/p>\n<p>En la universidad, las preguntas se hicieron m\u00e1s grandes y abiertas. \u00bfCon qui\u00e9n me casar\u00eda? \u00bfCu\u00e1l ser\u00eda mi vocaci\u00f3n? \u00bfD\u00f3nde vivir\u00edamos? \u00bfCu\u00e1ntos hijos tendr\u00edamos? De esto se trataba la vida, y la universidad era el final de la preparaci\u00f3n.     <\/p>\n<p>La Segunda Guerra Mundial interrumpi\u00f3 abruptamente esta progresi\u00f3n. Plante\u00f3 un conjunto de preguntas completamente diferente y pospuso las respuestas a las anteriores. Las cuestiones de la guerra, el reclutamiento y el pacifismo se plantearon en el momento que otros decidieron, con plazos para las respuestas. Eleg\u00ed el Servicio P\u00fablico Civil. Esta era la vida, inmediata, en mi cara, ahora.    <\/p>\n<p>Al final de la guerra, una pregunta importante hab\u00eda sido respondida: estaba casado. Las dem\u00e1s se resolvieron con el tiempo en respuesta a las oportunidades que surgieron y a las decisiones que tomamos. Me convert\u00ed en ingeniero; tuvimos cuatro hijos; nos establecimos en Vale, una comunidad intencional en las afueras de Yellow Springs; y mir\u00e9 hacia la jubilaci\u00f3n. Esto era vivir.   <\/p>\n<p>Para cada una de estas etapas del camino hab\u00eda se\u00f1ales y un conjunto de expectativas sutiles. Hice lo que era necesario en el momento. Ahora, seis a\u00f1os y medio despu\u00e9s de la jubilaci\u00f3n, pregunto: \u00bfpara qu\u00e9 sirve la jubilaci\u00f3n? Las se\u00f1ales que me rodean son inadecuadas y las expectativas, en el mejor de los casos, est\u00e1n mal definidas. Los consejos disponibles son del tipo que dice: \u201cEmpieza a ahorrar pronto para tener suficiente dinero para lo que quieras\u00bb. \u201cCuida tu salud para poder hacer lo que quieras\u00bb. \u201cAqu\u00ed est\u00e1n los 20 mejores lugares para vivir si quieres jugar al golf, pescar o disfrutar del clima\u00bb. \u201cHaz esto o aquello para poder dejar a tus herederos lo que tanto te ha costado acumular\u00bb. \u201cNo seas una carga para tus hijos ni te entrometas en sus vidas\u00bb. \u201cBusca un pasatiempo\u00bb. \u201cHaz voluntariado\u00bb. Ninguna de estas cosas parec\u00eda acercarse a la respuesta a la pregunta que se me abri\u00f3: \u201c\u00bfPara qu\u00e9 sirve la jubilaci\u00f3n?\u00bb     <\/p>\n<p>A medida que la pregunta se hizo clara, la respuesta flot\u00f3 en mi conciencia. La jubilaci\u00f3n es para ser amable con los dem\u00e1s. Es tiempo, libre de expectativas, para ser bondadoso con los dem\u00e1s. La preparaci\u00f3n ha terminado; es hora de renunciar al juicio de amigos, vecinos y extra\u00f1os. Ahora es el momento de la alegr\u00eda, la generosidad, la honestidad, la ayuda, la aceptaci\u00f3n; para vivir.    <\/p>\n<p>Con esta respuesta, estoy en paz. Toda inseguridad se ha ido. Al reflexionar sobre esta respuesta, veo que tambi\u00e9n encaja en todas las etapas anteriores de la vida. La infancia, la adolescencia, el noviazgo, el matrimonio, la familia, el nido vac\u00edo, el trabajo, la jubilaci\u00f3n, todos proporcionan una oportunidad tras otra para ser amables y gentiles con los dem\u00e1s, para renunciar a juzgar a los dem\u00e1s o a uno mismo, para experimentar la generosidad y para compartir la alegr\u00eda.   <\/p>\n<p>Los recuerdos que atesoro evocan los momentos en que fui as\u00ed. Cada d\u00eda trae nuevas oportunidades, y estoy contento. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante un tiempo, en el verano de 2003, fui consciente de que hab\u00eda una pregunta sin respuesta esperando a ser&hellip;<\/p>\n","protected":false},"author":564,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9799],"tags":[11603,11536],"fpb_issue_category":[],"class_list":["post-3116657","post","type-post","status-publish","format-standard","hentry","category-cronicas","tag-autorrealizacion","tag-envejecimiento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPara qu\u00e9 sirve la jubilaci\u00f3n? - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/para-que-sirve-la-jubilacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPara qu\u00e9 sirve la jubilaci\u00f3n? - Friends Journal\" \/>\n<meta property=\"og:description\" content=\"Durante un tiempo, en el verano de 2003, fui consciente de que hab\u00eda una pregunta sin respuesta esperando a ser&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/para-que-sirve-la-jubilacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"2004-07-01T04:00:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"779\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RichardEastman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RichardEastman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/para-que-sirve-la-jubilacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/para-que-sirve-la-jubilacion\\\/\"},\"author\":{\"name\":\"RichardEastman\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/eb4af7dc2239d608987dfae1c0cf7ca9\"},\"headline\":\"\u00bfPara qu\u00e9 sirve la jubilaci\u00f3n?\",\"datePublished\":\"2004-07-01T04:00:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/para-que-sirve-la-jubilacion\\\/\"},\"wordCount\":714,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"keywords\":[\"Autorrealizaci\u00f3n\",\"Envejecimiento\"],\"articleSection\":[\"cr\u00f3nicas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/para-que-sirve-la-jubilacion\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/para-que-sirve-la-jubilacion\\\/\",\"name\":\"\u00bfPara qu\u00e9 sirve la jubilaci\u00f3n? - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"datePublished\":\"2004-07-01T04:00:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/para-que-sirve-la-jubilacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/para-que-sirve-la-jubilacion\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/para-que-sirve-la-jubilacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPara qu\u00e9 sirve la jubilaci\u00f3n?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/eb4af7dc2239d608987dfae1c0cf7ca9\",\"name\":\"RichardEastman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"RichardEastman\"},\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/author\\\/richardeastman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPara qu\u00e9 sirve la jubilaci\u00f3n? - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/para-que-sirve-la-jubilacion\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPara qu\u00e9 sirve la jubilaci\u00f3n? - Friends Journal","og_description":"Durante un tiempo, en el verano de 2003, fui consciente de que hab\u00eda una pregunta sin respuesta esperando a ser&hellip;","og_url":"https:\/\/www.friendsjournal.org\/es\/para-que-sirve-la-jubilacion\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"2004-07-01T04:00:51+00:00","og_image":[{"width":779,"height":438,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg","type":"image\/jpeg"}],"author":"RichardEastman","twitter_card":"summary_large_image","twitter_creator":"@friendsournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"RichardEastman","Est. reading time":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/es\/para-que-sirve-la-jubilacion\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/para-que-sirve-la-jubilacion\/"},"author":{"name":"RichardEastman","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/eb4af7dc2239d608987dfae1c0cf7ca9"},"headline":"\u00bfPara qu\u00e9 sirve la jubilaci\u00f3n?","datePublished":"2004-07-01T04:00:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/para-que-sirve-la-jubilacion\/"},"wordCount":714,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"keywords":["Autorrealizaci\u00f3n","Envejecimiento"],"articleSection":["cr\u00f3nicas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/para-que-sirve-la-jubilacion\/","url":"https:\/\/www.friendsjournal.org\/es\/para-que-sirve-la-jubilacion\/","name":"\u00bfPara qu\u00e9 sirve la jubilaci\u00f3n? - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"datePublished":"2004-07-01T04:00:51+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/para-que-sirve-la-jubilacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/para-que-sirve-la-jubilacion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/para-que-sirve-la-jubilacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"\u00bfPara qu\u00e9 sirve la jubilaci\u00f3n?"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/eb4af7dc2239d608987dfae1c0cf7ca9","name":"RichardEastman","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"RichardEastman"},"url":"https:\/\/www.friendsjournal.org\/es\/author\/richardeastman\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"author_name":"Richard Eastman","bio":"<p>Richard Eastman, miembro del Meeting de Yellow Springs (Ohio), se ha jubilado de su puesto como ingeniero del condado de Greene.<\/p>\n","issue":"Julio de 2004"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3116657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/564"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3116657"}],"version-history":[{"count":0,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3116657\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3116657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3116657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/tags?post=3116657"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3116657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}