{"id":3116854,"date":"2025-10-01T02:20:00","date_gmt":"2025-10-01T06:20:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/cruzando-puentes-siendo-puentes\/"},"modified":"2025-10-28T13:06:34","modified_gmt":"2025-10-28T17:06:34","slug":"cruzando-puentes-siendo-puentes","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/","title":{"rendered":"Cruzando puentes, siendo puentes"},"content":{"rendered":"\n<p class=\"has-drop-cap wp-block-paragraph\">Hace algunos a\u00f1os, cuando era secretario de mi Meeting, uno de nuestros miembros me escribi\u00f3 con una pregunta que no hab\u00eda considerado antes. Me cont\u00f3 que hab\u00eda estado participando en el culto en l\u00ednea con un grupo que se acababa de formalizar como Ujima Friends Meeting, una comunidad de culto cu\u00e1quera independiente de personas de ascendencia africana. Quer\u00eda unirse a Ujima como miembro, y quer\u00eda saber si pod\u00eda hacerlo manteniendo su membres\u00eda en Green Street Meeting en Filadelfia, Pensilvania. Ella escribi\u00f3:<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">He sido miembro de Green Street durante 30 a\u00f1os y durante ese tiempo nunca me he sentido impulsado a trasladar mi membres\u00eda. Dios me guio a Green Street sin que siquiera supiera lo extraordinario que es el Meeting de Green Street dentro de la Sociedad Religiosa de los Amigos. Mientras reflexionaba sobre lo que quiero decir a los miembros de mi Meeting, Green Street, me he encontrado asediado por la ansiedad.<\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\">Esta Amiga no quer\u00eda un simple \u201c\u00a1Claro, est\u00e1 bien!\u201d Deseaba involucrar nuestro proceso cu\u00e1quero con total transparencia, y que el Meeting considerara esta solicitud con la misma seriedad espiritual en la que ella confiaba para hacerla. Nuestro Comit\u00e9 de Cuidado y Consejo se reuni\u00f3 con ella y, en \u00faltima instancia, recomend\u00f3 que el Meeting aceptara esta solicitud de doble membres\u00eda. Quiero compartir algunas de sus palabras:<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Ujima Meeting tiene una misi\u00f3n espec\u00edfica para los Amigos de ascendencia africana y satisface las necesidades espirituales de algunas personas de herencia africana de una manera que nuestro Meeting no lo hace, en este momento. Nuestra Amiga quiere dejar muy claro que ama GSMM, no tiene ning\u00fan deseo de transferir o terminar su membres\u00eda. Pero siente que Ujima es un \u201cpuente que se siente impulsada a cruzar\u201d en este momento de su vida. Al reconocer su doble membres\u00eda en Ujima Friends Meeting, Green Street Monthly Meeting reconoce la importancia de su papel como puente entre nuestros Meetings.<\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\">Nuestro Meeting analiz\u00f3 esta recomendaci\u00f3n y, despu\u00e9s de mucha discusi\u00f3n, la acept\u00f3, aunque, si no recuerdo mal, un miembro opt\u00f3 por abstenerse. Algunos cu\u00e1queros abordan el concepto de espacios de afinidad con cautela. Soy un hombre blanco, cisg\u00e9nero y heterosexual, con estudios universitarios, una hipoteca y un trabajo estable. Puede ser dif\u00edcil reconocer, especialmente para personas como yo que poseen caracter\u00edsticas de privilegio, que las estructuras y los espacios de nuestra comunidad religiosa privilegiar\u00e1n las mismas cosas que nuestra sociedad, a menos que trabajemos activamente para cambiar esto.<\/p>\n\n<p class=\"wp-block-paragraph\">Demostramos un respeto espiritual fundamental cuando reconocemos y apoyamos los deseos de nuestros miembros de participar en espacios de afinidad bajo la carpa cu\u00e1quera. Nuestras comunidades son m\u00e1s fuertes cuando participan Amigos con diversas identidades. Los espacios de afinidad pueden facilitar que m\u00e1s personas permanezcan en la carpa cu\u00e1quera mientras todos los Amigos hacen el arduo trabajo para convertirse en la comunidad amada que buscamos ser.<\/p>\n\n<p class=\"wp-block-paragraph\">Este n\u00famero de <em>Friends Journal<\/em> incluye historias de espacios de afinidad y busca responder preguntas clave: \u00bfQui\u00e9n? \u00bfPor qu\u00e9? \u00bfC\u00f3mo? Sin duda, plantear\u00e1 tantas preguntas como respuestas, pero quiz\u00e1s las m\u00e1s importantes con las que podr\u00edamos marcharnos son: \u00bfA qui\u00e9n estamos excluyendo inconscientemente? \u00bfC\u00f3mo podemos apoyarlos? \u00bfY c\u00f3mo podemos ser transformados?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Introducci\u00f3n a nuestro n\u00famero de octubre.<\/p>\n","protected":false},"author":5090,"featured_media":3100401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9803],"tags":[],"fpb_issue_category":[10725],"class_list":["post-3116854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entre-amigos","fpb_issue_category-grupos-de-afinidad-y-adoracion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Espacios de afinidad cu\u00e1queros: c\u00f3mo los cu\u00e1queros construyen espacios espirituales inclusivos<\/title>\n<meta name=\"description\" content=\"\u00bfQu\u00e9 revelan los espacios de afinidad sobre la comunidad cu\u00e1quera? Explora c\u00f3mo la pertenencia, la diversidad y la fe transforman la vida espiritual en este n\u00famero de Friends Journal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cruzando puentes, siendo puentes\" \/>\n<meta property=\"og:description\" content=\"\u00bfQu\u00e9 revelan los espacios de afinidad sobre la comunidad cu\u00e1quera? Explora c\u00f3mo la pertenencia, la diversidad y la fe transforman la vida espiritual en este n\u00famero de Friends Journal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-01T06:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-28T17:06:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/10\/1025_Cover_banner_adj.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Friends Journal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Friends Journal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cruzando-puentes-siendo-puentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cruzando-puentes-siendo-puentes\\\/\"},\"author\":{\"name\":\"Friends Journal\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/315ffb22a36ecbabdf5dbdc09d7d1eb7\"},\"headline\":\"Cruzando puentes, siendo puentes\",\"datePublished\":\"2025-10-01T06:20:00+00:00\",\"dateModified\":\"2025-10-28T17:06:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cruzando-puentes-siendo-puentes\\\/\"},\"wordCount\":563,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cruzando-puentes-siendo-puentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/1025_Cover_banner_adj.jpg\",\"articleSection\":[\"Entre Amigos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cruzando-puentes-siendo-puentes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cruzando-puentes-siendo-puentes\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cruzando-puentes-siendo-puentes\\\/\",\"name\":\"Espacios de afinidad cu\u00e1queros: c\u00f3mo los cu\u00e1queros construyen espacios espirituales inclusivos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cruzando-puentes-siendo-puentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cruzando-puentes-siendo-puentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/1025_Cover_banner_adj.jpg\",\"datePublished\":\"2025-10-01T06:20:00+00:00\",\"dateModified\":\"2025-10-28T17:06:34+00:00\",\"description\":\"\u00bfQu\u00e9 revelan los espacios de afinidad sobre la comunidad cu\u00e1quera? Explora c\u00f3mo la pertenencia, la diversidad y la fe transforman la vida espiritual en este n\u00famero de Friends Journal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cruzando-puentes-siendo-puentes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cruzando-puentes-siendo-puentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cruzando-puentes-siendo-puentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/1025_Cover_banner_adj.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/1025_Cover_banner_adj.jpg\",\"width\":1000,\"height\":563,\"caption\":\"Banner de manos coloridas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cruzando-puentes-siendo-puentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cruzando puentes, siendo puentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/315ffb22a36ecbabdf5dbdc09d7d1eb7\",\"name\":\"Friends Journal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"caption\":\"Friends Journal\"},\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/author\\\/alla-podolsky\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Espacios de afinidad cu\u00e1queros: c\u00f3mo los cu\u00e1queros construyen espacios espirituales inclusivos","description":"\u00bfQu\u00e9 revelan los espacios de afinidad sobre la comunidad cu\u00e1quera? Explora c\u00f3mo la pertenencia, la diversidad y la fe transforman la vida espiritual en este n\u00famero de Friends Journal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/","og_locale":"es_ES","og_type":"article","og_title":"Cruzando puentes, siendo puentes","og_description":"\u00bfQu\u00e9 revelan los espacios de afinidad sobre la comunidad cu\u00e1quera? Explora c\u00f3mo la pertenencia, la diversidad y la fe transforman la vida espiritual en este n\u00famero de Friends Journal.","og_url":"https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"2025-10-01T06:20:00+00:00","article_modified_time":"2025-10-28T17:06:34+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/10\/1025_Cover_banner_adj.jpg","type":"image\/jpeg"}],"author":"Friends Journal","twitter_card":"summary_large_image","twitter_creator":"@friendsournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"Friends Journal","Est. reading time":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/"},"author":{"name":"Friends Journal","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/315ffb22a36ecbabdf5dbdc09d7d1eb7"},"headline":"Cruzando puentes, siendo puentes","datePublished":"2025-10-01T06:20:00+00:00","dateModified":"2025-10-28T17:06:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/"},"wordCount":563,"commentCount":0,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/10\/1025_Cover_banner_adj.jpg","articleSection":["Entre Amigos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/","url":"https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/","name":"Espacios de afinidad cu\u00e1queros: c\u00f3mo los cu\u00e1queros construyen espacios espirituales inclusivos","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/10\/1025_Cover_banner_adj.jpg","datePublished":"2025-10-01T06:20:00+00:00","dateModified":"2025-10-28T17:06:34+00:00","description":"\u00bfQu\u00e9 revelan los espacios de afinidad sobre la comunidad cu\u00e1quera? Explora c\u00f3mo la pertenencia, la diversidad y la fe transforman la vida espiritual en este n\u00famero de Friends Journal.","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/10\/1025_Cover_banner_adj.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/10\/1025_Cover_banner_adj.jpg","width":1000,"height":563,"caption":"Banner de manos coloridas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/cruzando-puentes-siendo-puentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Cruzando puentes, siendo puentes"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/315ffb22a36ecbabdf5dbdc09d7d1eb7","name":"Friends Journal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","caption":"Friends Journal"},"url":"https:\/\/www.friendsjournal.org\/es\/author\/alla-podolsky\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"author_name":"Gabriel Ehri","bio":"<p>Gabriel ehri es el Director Ejecutivo.<\/p>\n"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3116854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3116854"}],"version-history":[{"count":2,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3116854\/revisions"}],"predecessor-version":[{"id":3132323,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3116854\/revisions\/3132323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3100401"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3116854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3116854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/tags?post=3116854"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3116854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}