{"id":3117039,"date":"2025-05-01T03:00:00","date_gmt":"2025-05-01T07:00:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/honrando-a-dios-con-nuestros-bienes\/"},"modified":"2025-10-10T23:57:13","modified_gmt":"2025-10-11T03:57:13","slug":"honrando-a-dios-con-nuestros-bienes","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/","title":{"rendered":"Honrando a Dios con nuestros bienes"},"content":{"rendered":"\n<p class=\"has-drop-cap wp-block-paragraph\">En un mundo tan profundamente abundante como el nuestro, es un fracaso social de proporciones monumentales que alguien carezca de una vivienda segura y confortable. Y, sin embargo, aqu\u00ed estamos. Los cu\u00e1queros de todas partes, en las comunidades donde vivimos, trabajamos y viajamos, nos encontramos con personas que tienen inseguridad de vivienda. Algunos Amigos, ellos mismos, carecen de una vivienda estable. En este n\u00famero de <em>Friends Journal<\/em>, compartimos las historias de Amigos que no se conforman con apartar la vista de esta angustiosa realidad, sino que siguen las indicaciones del Esp\u00edritu para cuidar de nuestros vecinos, y al hacerlo emprenden un ciclo generativo de bondad.    <\/p>\n\n<p class=\"wp-block-paragraph\">Las palabras de Jes\u00fas en el Evangelio de Mateo, cap\u00edtulo 25, son citadas por m\u00faltiples autores como parte de lo que les impuls\u00f3 a actuar para combatir la falta de vivienda y proporcionar cuidados en las muchas formas en que lo han hecho.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Porque tuve hambre, y me disteis de comer; tuve sed, y me disteis de beber; fui forastero, y me invitasteis a entrar; estuve desnudo, y me cubristeis; enfermo, y me visitasteis; en la c\u00e1rcel, y fuisteis a verme.<\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\">Al leer las historias aqu\u00ed reunidas, me llama la atenci\u00f3n algunas cosas. En primer lugar, es notable lo mucho que la vivienda est\u00e1 interconectada con nuestras otras necesidades. Hablar abiertamente de ello y buscar soluciones a nuestro alcance como individuos, familias, comunidades y sociedades: estos pasos pueden ser claves que desbloqueen una mayor felicidad y realizaci\u00f3n humana, claves que permitan una expresi\u00f3n m\u00e1s plena de la luz de Dios a trav\u00e9s de las vidas de todos nuestros vecinos. La segunda constataci\u00f3n que tengo es esta: no importa d\u00f3nde estemos, ya sea en una peque\u00f1a comunidad rural o en una gran ciudad, hay maneras de usar lo que tenemos para ayudar a los dem\u00e1s. Las necesidades de las personas sin hogar en un centro urbano y las de un aparcamiento de Walmart pueden parecer diferentes, pero dondequiera que estemos, hay vecinos y, por lo tanto, una obligaci\u00f3n de cuidado.    <\/p>\n\n<p class=\"wp-block-paragraph\">Tenemos la suerte de contar con algunos excelentes modelos cu\u00e1queros de urgencia y claridad en la exhortaci\u00f3n a <em>hacer algo para ayudar<\/em>. Sentado con estas historias, me anim\u00e9 a hojear el <em>Journal<\/em> de John Woolman. En una entrada de 1759, recordando las actas de una reuni\u00f3n anual \u201cbajo el peso\u00bb de las deliberaciones de los Amigos con respecto a la posesi\u00f3n de esclavos, Woolman cita de la ep\u00edstola nacida de su fruct\u00edfero discernimiento:  <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Mantener una mirada atenta hacia los objetos reales de caridad, visitar a los pobres en sus solitarios lugares de morada, consolar a aquellos que a trav\u00e9s de las dispensaciones de la divina providencia se encuentran en circunstancias estrechas y dolorosas en esta vida, y esforzarse constantemente por honrar a Dios con nuestros bienes a partir de un sentido real del amor de Cristo que influye en nuestras mentes para ello, es m\u00e1s probable que traiga una bendici\u00f3n a nuestros hijos y proporcionar\u00e1 m\u00e1s satisfacci\u00f3n a un cristiano favorecido con la abundancia que un deseo ferviente de acumular mucha riqueza para dejarnos atr\u00e1s. . . .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, hermanos, todo lo que es verdadero&#8230; todo lo que es justo, todo lo que es puro, todo lo que es amable, todo lo que es de buen nombre; si hay alguna virtud, si hay alguna alabanza, pensad en estas cosas&#8230; y hacedlas, y el Dios de paz estar\u00e1 con vosotros.<\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\">\u201cPensad en estas cosas y hacedlas\u201d. Espero escuchar lo que los Amigos de hoy est\u00e1n llamados a hacer, y compartir sus historias con vosotros, lectores. <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Introducci\u00f3n a nuestro n\u00famero de mayo.<\/p>\n","protected":false},"author":5090,"featured_media":3098649,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9803],"tags":[],"fpb_issue_category":[9869],"class_list":["post-3117039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entre-amigos","fpb_issue_category-vivienda-y-personas-sin-hogar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Honrando a Dios con nuestros bienes - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Honrando a Dios con nuestros bienes\" \/>\n<meta property=\"og:description\" content=\"Introducci\u00f3n a nuestro n\u00famero de mayo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-01T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-11T03:57:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/05\/0525_Cover_banner_adj-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Friends Journal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Friends Journal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/honrando-a-dios-con-nuestros-bienes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/honrando-a-dios-con-nuestros-bienes\\\/\"},\"author\":{\"name\":\"Friends Journal\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/315ffb22a36ecbabdf5dbdc09d7d1eb7\"},\"headline\":\"Honrando a Dios con nuestros bienes\",\"datePublished\":\"2025-05-01T07:00:00+00:00\",\"dateModified\":\"2025-10-11T03:57:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/honrando-a-dios-con-nuestros-bienes\\\/\"},\"wordCount\":619,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/honrando-a-dios-con-nuestros-bienes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/0525_Cover_banner_adj-1.jpg\",\"articleSection\":[\"Entre Amigos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/honrando-a-dios-con-nuestros-bienes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/honrando-a-dios-con-nuestros-bienes\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/honrando-a-dios-con-nuestros-bienes\\\/\",\"name\":\"Honrando a Dios con nuestros bienes - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/honrando-a-dios-con-nuestros-bienes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/honrando-a-dios-con-nuestros-bienes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/0525_Cover_banner_adj-1.jpg\",\"datePublished\":\"2025-05-01T07:00:00+00:00\",\"dateModified\":\"2025-10-11T03:57:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/honrando-a-dios-con-nuestros-bienes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/honrando-a-dios-con-nuestros-bienes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/honrando-a-dios-con-nuestros-bienes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/0525_Cover_banner_adj-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/0525_Cover_banner_adj-1.jpg\",\"width\":1000,\"height\":563,\"caption\":\"Foto de portada de Nathan Dumlao en Unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/honrando-a-dios-con-nuestros-bienes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Honrando a Dios con nuestros bienes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/315ffb22a36ecbabdf5dbdc09d7d1eb7\",\"name\":\"Friends Journal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"caption\":\"Friends Journal\"},\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/author\\\/alla-podolsky\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Honrando a Dios con nuestros bienes - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/","og_locale":"es_ES","og_type":"article","og_title":"Honrando a Dios con nuestros bienes","og_description":"Introducci\u00f3n a nuestro n\u00famero de mayo.","og_url":"https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"2025-05-01T07:00:00+00:00","article_modified_time":"2025-10-11T03:57:13+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/05\/0525_Cover_banner_adj-1.jpg","type":"image\/jpeg"}],"author":"Friends Journal","twitter_card":"summary_large_image","twitter_creator":"@friendsournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"Friends Journal","Est. reading time":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/"},"author":{"name":"Friends Journal","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/315ffb22a36ecbabdf5dbdc09d7d1eb7"},"headline":"Honrando a Dios con nuestros bienes","datePublished":"2025-05-01T07:00:00+00:00","dateModified":"2025-10-11T03:57:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/"},"wordCount":619,"commentCount":0,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/05\/0525_Cover_banner_adj-1.jpg","articleSection":["Entre Amigos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/","url":"https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/","name":"Honrando a Dios con nuestros bienes - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/05\/0525_Cover_banner_adj-1.jpg","datePublished":"2025-05-01T07:00:00+00:00","dateModified":"2025-10-11T03:57:13+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/05\/0525_Cover_banner_adj-1.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/05\/0525_Cover_banner_adj-1.jpg","width":1000,"height":563,"caption":"Foto de portada de Nathan Dumlao en Unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/honrando-a-dios-con-nuestros-bienes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Honrando a Dios con nuestros bienes"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/315ffb22a36ecbabdf5dbdc09d7d1eb7","name":"Friends Journal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","caption":"Friends Journal"},"url":"https:\/\/www.friendsjournal.org\/es\/author\/alla-podolsky\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"author_name":"Gabriel Ehri","bio":"<p id=\"docs-internal-guid-41870a73-7fff-412e-69a5-5bf8faeb7d00\" dir=\"ltr\" style=\"caret-color: #000000; color: #000000; line-height: 1.8; text-align: justify; margin-top: 9pt; margin-bottom: 9pt;\"><span style=\"font-size: 11pt; font-family: Arial, sans-serif; font-variant-ligatures: normal; font-variant-alternates: normal; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-position: normal; vertical-align: baseline; white-space: pre-wrap;\">Gabriel ehri es <\/span><span style=\"font-size: 11pt; font-family: Arial, sans-serif; font-variant-ligatures: normal; font-variant-alternates: normal; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-position: normal; vertical-align: baseline; white-space: pre-wrap;\">Director Ejecutivo.<\/span><\/p>\n"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3117039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3117039"}],"version-history":[{"count":1,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3117039\/revisions"}],"predecessor-version":[{"id":3117042,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3117039\/revisions\/3117042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3098649"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3117039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3117039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/tags?post=3117039"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3117039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}