{"id":3117080,"date":"2025-09-01T01:30:00","date_gmt":"2025-09-01T05:30:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/29-de-septiembre\/"},"modified":"2026-06-25T14:22:33","modified_gmt":"2026-06-25T18:22:33","slug":"29-de-septiembre","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/","title":{"rendered":"29 de septiembre"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>(la fiesta de los arc\u00e1ngeles)<\/em><\/p>\n\n<p class=\"wp-block-paragraph\">Cada a\u00f1o, el 29 de septiembre<br\/>se re\u00fanen.<br\/>Rafael trae las bebidas,<br\/>mientras que Miguel y Gabriel<br\/>saquean la despensa en busca de caviar y totopos.<br\/>Se congregan en la sala de la chimenea,<br\/>extienden la comida sobre la mesa,<br\/>sacan el tablero de Parcheesi,<br\/>y se quitan los zapatos.<br\/>Entonces cantan.<br\/>Comienzan con las canciones antiguas<br\/>\u2014Salmo 100, el Magnificat\u2014<br\/>\u201cHe aqu\u00ed, os traigo buenas nuevas\u201d<br\/>(un favorito despu\u00e9s de todos estos a\u00f1os)\u2014<br\/>se abren camino a trav\u00e9s de cantos gregorianos<br\/>y Mart\u00edn Lutero al Nuevo Mundo<br\/>Yankee Doodle, gospel sure\u00f1o,<br\/>y en alg\u00fan momento del proceso<br\/>me cantan Cumplea\u00f1os feliz.<br\/>Con voces como ballenas<br\/>o lobos \u00e1rticos,<br\/>extra\u00f1os, lejanos y totalmente santos,<br\/>los arc\u00e1ngeles celebran.<br\/>\u201cNo tengas miedo\u201d, me dicen.<br\/>Los planetas se realinean.<br\/>El jugo del sol fluye libre.<br\/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada a\u00f1o, el 29 de septiembre \/ se re\u00fanen.<\/p>\n","protected":false},"author":5090,"featured_media":3099530,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10336],"tags":[],"fpb_issue_category":[9831],"class_list":["post-3117080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-poesia","fpb_issue_category-septiembre-de-2025"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>29 de septiembre - Friends Journal<\/title>\n<meta name=\"description\" content=\"29 de septiembre, un poema de Nancy Thomas. L\u00e9alo ahora en Friends Journal y explore otras hermosas reflexiones y poemas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"29 de septiembre\" \/>\n<meta property=\"og:description\" content=\"29 de septiembre, un poema de Nancy Thomas. L\u00e9alo ahora en Friends Journal y explore otras hermosas reflexiones y poemas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-01T05:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T18:22:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/Thomas_poem_featured.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"725\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Friends Journal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Friends Journal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/29-de-septiembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/29-de-septiembre\\\/\"},\"author\":{\"name\":\"Friends Journal\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/315ffb22a36ecbabdf5dbdc09d7d1eb7\"},\"headline\":\"29 de septiembre\",\"datePublished\":\"2025-09-01T05:30:00+00:00\",\"dateModified\":\"2026-06-25T18:22:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/29-de-septiembre\\\/\"},\"wordCount\":143,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/29-de-septiembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Thomas_poem_featured.jpg\",\"articleSection\":[\"Poes\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/29-de-septiembre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/29-de-septiembre\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/29-de-septiembre\\\/\",\"name\":\"29 de septiembre - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/29-de-septiembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/29-de-septiembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Thomas_poem_featured.jpg\",\"datePublished\":\"2025-09-01T05:30:00+00:00\",\"dateModified\":\"2026-06-25T18:22:33+00:00\",\"description\":\"29 de septiembre, un poema de Nancy Thomas. L\u00e9alo ahora en Friends Journal y explore otras hermosas reflexiones y poemas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/29-de-septiembre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/29-de-septiembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/29-de-septiembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Thomas_poem_featured.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Thomas_poem_featured.jpg\",\"width\":1400,\"height\":725,\"caption\":\"Foto de t0m15\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/29-de-septiembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"29 de septiembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/315ffb22a36ecbabdf5dbdc09d7d1eb7\",\"name\":\"Friends Journal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"caption\":\"Friends Journal\"},\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/author\\\/alla-podolsky\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"29 de septiembre - Friends Journal","description":"29 de septiembre, un poema de Nancy Thomas. L\u00e9alo ahora en Friends Journal y explore otras hermosas reflexiones y poemas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/","og_locale":"es_ES","og_type":"article","og_title":"29 de septiembre","og_description":"29 de septiembre, un poema de Nancy Thomas. L\u00e9alo ahora en Friends Journal y explore otras hermosas reflexiones y poemas.","og_url":"https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"2025-09-01T05:30:00+00:00","article_modified_time":"2026-06-25T18:22:33+00:00","og_image":[{"width":1400,"height":725,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/Thomas_poem_featured.jpg","type":"image\/jpeg"}],"author":"Friends Journal","twitter_card":"summary_large_image","twitter_creator":"@friendsournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"Friends Journal","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/"},"author":{"name":"Friends Journal","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/315ffb22a36ecbabdf5dbdc09d7d1eb7"},"headline":"29 de septiembre","datePublished":"2025-09-01T05:30:00+00:00","dateModified":"2026-06-25T18:22:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/"},"wordCount":143,"commentCount":0,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/Thomas_poem_featured.jpg","articleSection":["Poes\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/","url":"https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/","name":"29 de septiembre - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/Thomas_poem_featured.jpg","datePublished":"2025-09-01T05:30:00+00:00","dateModified":"2026-06-25T18:22:33+00:00","description":"29 de septiembre, un poema de Nancy Thomas. L\u00e9alo ahora en Friends Journal y explore otras hermosas reflexiones y poemas.","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/Thomas_poem_featured.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/Thomas_poem_featured.jpg","width":1400,"height":725,"caption":"Foto de t0m15"},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/29-de-septiembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"29 de septiembre"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/315ffb22a36ecbabdf5dbdc09d7d1eb7","name":"Friends Journal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","caption":"Friends Journal"},"url":"https:\/\/www.friendsjournal.org\/es\/author\/alla-podolsky\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"author_name":"Nancy Thomas","bio":"<p>Nancy Thomas, junto con su esposo, Hal, sirvi\u00f3 junto a la Iglesia de los Amigos Bolivianos durante m\u00e1s de 25 a\u00f1os. Sus \u00e1reas de ministerio mientras estaba en el campo fueron en la educaci\u00f3n teol\u00f3gica y la capacitaci\u00f3n de escritores locales. Hizo su trabajo de pregrado en George Fox College (especializaci\u00f3n en espa\u00f1ol) y tiene un doctorado en estudios interculturales del Seminario Teol\u00f3gico Fuller. Nancy actualmente vive en Oreg\u00f3n y es miembro de North Valley Friends Church.   <\/p>\n"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3117080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3117080"}],"version-history":[{"count":1,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3117080\/revisions"}],"predecessor-version":[{"id":3117083,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3117080\/revisions\/3117083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3099530"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3117080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3117080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/tags?post=3117080"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3117080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}