{"id":3117098,"date":"2004-06-01T00:00:43","date_gmt":"2004-06-01T04:00:43","guid":{"rendered":"https:\/\/www.friendsjournal.org\/cuaqueros-sexualidad-y-espiritualidad\/"},"modified":"2004-06-01T00:00:43","modified_gmt":"2004-06-01T04:00:43","slug":"cuaqueros-sexualidad-y-espiritualidad","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/es\/cuaqueros-sexualidad-y-espiritualidad\/","title":{"rendered":"Cu\u00e1queros, sexualidad y espiritualidad"},"content":{"rendered":"<p>Hablar de sexo en cualquier contexto, incluso en uno cu\u00e1quero, puede ser peligroso porque no todos usamos el mismo lenguaje. Tenemos diferentes experiencias. El sexo tiene diferentes prioridades en la vida de varias personas. As\u00ed que, solo quiero dejar claro que hablo solo desde mi propia experiencia. No hablo en nombre de los hombres gais, aunque soy miembro de ese c\u00edrculo. No hablo en nombre de los inmigrantes italoamericanos de primera generaci\u00f3n, aunque lo soy. Ni de los cu\u00e1queros que saben cantar a la tirolesa. Solo hablo desde mi propia experiencia.       <\/p>\n<p>Mi propia experiencia incluye varios niveles diferentes. En un nivel, fui violado y golpeado cuando era ni\u00f1o, as\u00ed que entiendo el sexo como un poder para herir. Tambi\u00e9n soy alguien que ha pasado los \u00faltimos 22 a\u00f1os dando masajes y trabajo energ\u00e9tico a personas que se est\u00e1n recuperando de experiencias traum\u00e1ticas. De esto entiendo el poder del tacto, la sensualidad y la intimidad para devolver a alguien a la plenitud, para devolver a alguien a la alegr\u00eda de la vida despu\u00e9s de quiz\u00e1s pensar que uno nunca podr\u00eda amar la vida de nuevo.   <\/p>\n<p>Tambi\u00e9n les hablo como alguien que tiene 50 a\u00f1os y sali\u00f3 del armario durante esa gloriosa \u00e9poca dorada de la sexualidad masculina gay despu\u00e9s de la penicilina pero antes del VIH. Quiero decirles que fue un buen momento para aprender a bailar, para salir y divertirse un poco. Durante este tiempo, la sexualidad masculina gay comenz\u00f3 a pasar de ser enfermiza e ilegal a ser algo que pod\u00eda ser maravilloso. Pod\u00eda ser una delicia. Pod\u00edas conocer gente nueva. Incluso pod\u00edas conocer a tu futuro c\u00f3nyuge en el lugar de ba\u00f1o gay como me pas\u00f3 a m\u00ed.     <\/p>\n<p>Otra parte de mi experiencia, despu\u00e9s de tener una agenda llena durante varios a\u00f1os, es que durante 15 a\u00f1os he sido felizmente mon\u00f3gamo, lo cual es una experiencia muy diferente. Estoy hablando desde todas estas perspectivas diferentes. <\/p>\n<p>Recientemente habl\u00e9 con una educadora sexual cu\u00e1quera, de las cuales hay muy pocas. Cuando le pregunt\u00e9 a Peggy Brick de Nueva Jersey: \u201c\u00bfEres la \u00fanica?\u00bb, ella dijo: \u201cBueno, en realidad los cu\u00e1queros han sido muy lentos en cuanto a la educaci\u00f3n sexual. Otras iglesias han hecho mucho m\u00e1s que nosotros\u00bb. Hubo algunos cu\u00e1queros que hab\u00edan hecho educaci\u00f3n sexual hace algunas d\u00e9cadas, pero dijo que en su mayor\u00eda estaban muertos.  <\/p>\n<p>Pr\u00e1cticamente he llegado a la conclusi\u00f3n de que es casi imposible para los cu\u00e1queros tener sexo. Siento informarles de esto, pero es cierto por un par de razones diferentes. <\/p>\n<p>Un obst\u00e1culo es la tradici\u00f3n de la sencillez. Existe un deseo entre los Amigos \u2014un testimonio, un testigo\u2014 de mantener la vida sencilla. Aquellos que se van a enamorar o tener una aventura van a arruinar su sencillez. Estamos hablando de un gran problema aqu\u00ed. \u00bfVan a devolver la llamada? \u00bfC\u00f3mo se ve mi cabello? Y eso es solo el principio. \u00a1Espera hasta que est\u00e9s en el s\u00e9ptimo a\u00f1o de matrimonio y te des cuenta de que todav\u00eda est\u00e1s al principio! Si realmente quieres sencillez, si est\u00e1s verdaderamente dedicado a eso como un testigo, te recomiendo que nunca tengas sexo con nadie y que nunca te enamores. No se puede hacer de forma sencilla. Se siente demasiado maravilloso. Se siente demasiado profundo.           <\/p>\n<p>Hay otro obst\u00e1culo. Este es, esencialmente, que a los cu\u00e1queros no les gusta el poder. Los cu\u00e1queros preferir\u00edan que nadie tuviera mucho poder. Nos gustar\u00eda dividirlo para que todos tengan solo un poco y nadie tenga mucho. Si est\u00e1s buscando retirarte de todo el concepto de poder, el sexo simplemente no va a funcionar porque es una fuerza tan poderosa. Es algo tan grande. Es un poder tan maravilloso.      <\/p>\n<p>Ten\u00eda una amiga llamada Mary. Cuando ten\u00eda casi 70 a\u00f1os, estaba cansada y ten\u00eda artritis y estaba cambiando su cuerpo y le dol\u00eda todo el tiempo. Bueno, Mary se enamor\u00f3 de un tipo que ten\u00eda unos 22 a\u00f1os. Entraron en su dormitorio, cerraron la puerta con llave y no salieron hasta unas tres semanas despu\u00e9s. Su artritis casi hab\u00eda desaparecido. Ella dijo: \u201cOjal\u00e1 mis m\u00e9dicos me hubieran explicado esto hace a\u00f1os\u00bb. Estaba de pie. Estaba sonriendo. El poder del amor verdadero, el poder de la atracci\u00f3n sexual es enorme. Si el poder te asusta, entonces va a haber alguna dificultad. Una de las cosas encantadoras de la sexualidad es descubrir ese poder dentro de ti mismo, sentir lo exuberante que es, sentir lo hermoso que es en otra persona y unir esas cosas. Es maravilloso.           <\/p>\n<p>Hay otro problema con que los cu\u00e1queros tengan sexo. Es que hay una tradici\u00f3n muy fuerte e impl\u00edcita entre los cu\u00e1queros: no debes llamar la atenci\u00f3n sobre ti mismo. Piensa en ese momento que tuviste hace un tiempo \u2014o tal vez que est\u00e1s esperando tener\u2014 cuando has estado con esa persona que simplemente te derrite, a quien miras y piensas: \u201c\u00a1Ooh-la-la!\u00bb. Qu\u00e9 maravilloso. Y empiezas a sentir ese hormigueo y dices lentamente, con una voz profunda y un aliento pesado: \u201cCari\u00f1o, me encanta lo que llevas puesto esta noche, y solo quiero decirte que te amo tanto y le doy gracias a Dios de que estemos juntos y solo me pregunto si podr\u00edas venir aqu\u00ed y estar a mi lado por un rato\u00bb. Ahora, si no quieres llamar la atenci\u00f3n sobre ti mismo, tienes que tomar todo ese sentimiento y dejarlo de lado. Vas a sonar como alguien con una voz aguda y quejumbrosa, como, \u201cCari\u00f1o, \u00bfte importar\u00eda si . . . oh no, no, no es tan importante\u00bb. Con la sexualidad quieres amar ese poder. Quieres sentirlo. Quieres conocerlo en ti mismo. Quieres encontrar una manera de trabajar con \u00e9l, vivir con \u00e9l y amarlo. Eso es muy importante.           <\/p>\n<p>Piensa en c\u00f3mo ser\u00eda si nosotros, los cu\u00e1queros, fu\u00e9ramos m\u00e1s honestos acerca de nuestras vidas sexuales. Piensa en algunos de nuestros encantadores ancianos despu\u00e9s del Meeting el domingo por la ma\u00f1ana, saliendo al porche y diciendo: \u201cOh, gracias a Dios. \u00a1Anoche hicimos el amor! Todo mi cuerpo se siente mejor. Gracias a Dios por darme estos sentimientos. Amo m\u00e1s mi vida ahora. Me gusta m\u00e1s estar en el mundo. Puedo pasar m\u00e1s tiempo con el dolor del mundo ahora porque he sentido su belleza profundamente. \u00a1Gracias a Dios! Puedo volver a casa a mi cuerpo y sentir esta maravillosa inclusi\u00f3n\u00bb. \u00bfNo es genial? Pero, si no puedes llamar la atenci\u00f3n sobre ti mismo, eso va a ser un problema.   <\/p>\n<p>Hay algunos paralelos maravillosos entre una vida espiritual y una vida sexual. Estas son partes de nuestras vidas que no siempre conectamos. Vivimos en un mundo muy ruidoso que en muchos sentidos es contrario a una vida espiritual profunda, trabajando en contra de ella. Esto es especialmente as\u00ed en la cultura estadounidense. La cultura popular es ruidosa y le dice a todo el mundo que salga y compre todo todo el tiempo.    <\/p>\n<p>En cierto modo, una vida sexual es lo mismo. Hay tanto ruido en la cultura popular sobre lo que la sexualidad deber\u00eda ser o podr\u00eda ser, con nuestra costumbre de comprar y vender cosas y personas. En cierto modo, no tocamos las partes m\u00e1s profundas de la espiritualidad o la sexualidad a menos que realmente las busquemos, nos preguntemos sobre ellas conscientemente e intentemos aprender sobre ellas dentro de nuestras propias vidas. Si observas los detalles externos de la vida sexual o espiritual de las personas, todos nos vemos muy diferentes. Es un mosaico incre\u00edble. Pero luego, si observas los detalles esenciales en el interior, las necesidades de cada uno de nosotros, el anhelo que cada persona tiene, estas esencias son notablemente similares, tanto de persona a persona como de la sexualidad a la espiritualidad.     <\/p>\n<p>Otra forma en que hay una similitud entre la sexualidad y la espiritualidad es que es una especie de gran cita a ciegas a la que todo el mundo va porque tenemos este hambre dentro de nosotros. Hay un deseo y un hambre de gracia, de sentir ese aspecto de lo Divino dentro de nosotros mismos, de sentir cierta familiaridad con un poder mayor que nosotros. Tambi\u00e9n existe ese anhelo de romance y de tacto, el tacto justo para nosotros. Es muy individual y \u00fanico.   <\/p>\n<p>Estaba hablando con un joven amigo gay en M\u00e9xico. Acababa de tener una cita y se preguntaba si era amor verdadero o simplemente diversi\u00f3n apasionada. Al describirlo, se puso triste. Despu\u00e9s de hablar de ello durante un rato, se dio cuenta de que en realidad no era la tristeza de lo que hab\u00eda sucedido en esta cita, sino una tristeza que puede venir porque existe este gran anhelo de dejar de buscar. Todos tenemos una gran esperanza de que vaya a haber amor verdadero: alguien con quien no vamos a tener que traducir mucho porque lo saben todo sobre nosotros. Este gran anhelo dentro de cada uno de nosotros est\u00e1 presente tanto en el reino de lo Divino como en el reino del sexo.     <\/p>\n<p>Hay otro paralelo. Esto es dif\u00edcil de hablar porque es un concepto con el que mucha gente est\u00e1 golpeada. Es la idea del pecado. Estoy pensando en el pecado como las cosas que nos alejan de lo Divino, cosas que nos alejan de conocer la vida espiritual m\u00e1s profundamente. El paralelo para la sexualidad \u2014no estoy seguro de que esta sea la palabra correcta, pero es una palabra que se puede usar\u2014 es la prostituci\u00f3n. Con eso, no me refiero a la prostituci\u00f3n. Me refiero al sexo que te aleja de honrarte a ti mismo; el sexo que te aleja de sentir profundamente, de una hermosa intimidad; el sexo que te aleja del poder personal. Lo interesante de la prostituci\u00f3n del sexo y el pecado en la vida espiritual es que no hay trabajo a tiempo parcial. Si te est\u00e1s apuntando a una de esas dos actividades destructivas, es a tiempo completo y te alejar\u00e1 de tu mejor yo. Pero estos conceptos tienen que aplicarse individualmente porque todos van a significar cosas diferentes en nuestras vidas y experiencias individuales. No va a haber alguien que te diga la manera correcta de tener una vida con Dios o tener una vida con sexo. Es una b\u00fasqueda tan \u00edntima que tiene que hacerse individualmente, encontrando el lenguaje adecuado para contarnos unos a otros lo que hemos visto y sentido en el camino.           <\/p>\n<p>Creo que la similitud m\u00e1s importante entre estos dos reinos es el concepto de rendici\u00f3n. Con esto, no me refiero a rendirse. Tenemos aspectos de nosotros mismos que anhelan algo m\u00e1s grande y mayor que nosotros. Si aprendes a rendirte en un reino, puedes transferir esa sabidur\u00eda a otros reinos. Si sabes sobre rendirte al amor verdadero, entonces existe la posibilidad de que puedas usar ese aprendizaje para rendirte a una experiencia espiritual m\u00e1s profunda.    <\/p>\n<p>Si has hecho la rendici\u00f3n a una experiencia espiritual m\u00e1s profunda, puedes usar ese aprendizaje para rendirte al amor verdadero. Esto \u00faltimo nunca es una rendici\u00f3n f\u00e1cil porque la vida duele mucho. A veces el amor verdadero llega \u2014si es que llega, y a veces parece que hemos estado esperando mucho tiempo, demasiado tiempo\u2014 pero cuando llega, tienes que preguntarte: \u201c\u00bfPuedo deshacer las maletas? \u00bfSacar todas mis decepciones, toda mi ansiedad, y dejarlas de lado y realmente unirme a esta otra persona?\u00bb  <\/p>\n<p>Esto es cierto para el amor rom\u00e1ntico, pero tambi\u00e9n es cierto para las relaciones m\u00e1s casuales. Hay muchos tipos diferentes de rendici\u00f3n, muchas maneras de aprender sobre este concepto tan importante. Cuando aprendemos la rendici\u00f3n en un lugar, podemos usarla para rendirnos en otro lugar.  <\/p>\n<p>Quiero concluir con una descripci\u00f3n. Es esta: Tomo una parte muy tierna de m\u00ed mismo y la relajo por completo. Descubro que soy capaz de rendirme a algo m\u00e1s grande que solo yo. Hay muchos sentimientos diferentes e incre\u00edbles y mucha sensaci\u00f3n. Puede volverse muy emocionante y agotador. Concluye, experimento la separaci\u00f3n, y soy solo yo de nuevo. Intento entender todo lo que ha sucedido. Ahora, mi pregunta para ustedes es: \u00bfestoy describiendo la rendici\u00f3n al Esp\u00edritu Santo en el Meeting para la adoraci\u00f3n, o estoy describiendo el acto de hacer el amor? Podr\u00eda ser que sean notablemente similares.<br \/>\n&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<br \/>\n<em>Este art\u00edculo es una adaptaci\u00f3n de un discurso a una conferencia sobre cu\u00e1queros y sexualidad en Guilford College el 22 de febrero de 2002.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hablar de sexo en cualquier contexto, incluso en uno cu\u00e1quero, puede ser peligroso porque no todos usamos el mismo lenguaje.&hellip;<\/p>\n","protected":false},"author":557,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9799],"tags":[11479,11877,10875],"fpb_issue_category":[],"class_list":["post-3117098","post","type-post","status-publish","format-standard","hentry","category-cronicas","tag-crecimiento-espiritual","tag-expresion-sexual","tag-sexualidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cu\u00e1queros, sexualidad y espiritualidad - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/cuaqueros-sexualidad-y-espiritualidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cu\u00e1queros, sexualidad y espiritualidad - Friends Journal\" \/>\n<meta property=\"og:description\" content=\"Hablar de sexo en cualquier contexto, incluso en uno cu\u00e1quero, puede ser peligroso porque no todos usamos el mismo lenguaje.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/cuaqueros-sexualidad-y-espiritualidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"2004-06-01T04:00:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"779\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"JohnCalvi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"JohnCalvi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cuaqueros-sexualidad-y-espiritualidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cuaqueros-sexualidad-y-espiritualidad\\\/\"},\"author\":{\"name\":\"JohnCalvi\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/dfc793da08cce0ffb1388c07b226d721\"},\"headline\":\"Cu\u00e1queros, sexualidad y espiritualidad\",\"datePublished\":\"2004-06-01T04:00:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cuaqueros-sexualidad-y-espiritualidad\\\/\"},\"wordCount\":2158,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"keywords\":[\"Crecimiento espiritual\",\"Expresi\u00f3n sexual\",\"Sexualidad\"],\"articleSection\":[\"cr\u00f3nicas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cuaqueros-sexualidad-y-espiritualidad\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cuaqueros-sexualidad-y-espiritualidad\\\/\",\"name\":\"Cu\u00e1queros, sexualidad y espiritualidad - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"datePublished\":\"2004-06-01T04:00:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cuaqueros-sexualidad-y-espiritualidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cuaqueros-sexualidad-y-espiritualidad\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/cuaqueros-sexualidad-y-espiritualidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cu\u00e1queros, sexualidad y espiritualidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/dfc793da08cce0ffb1388c07b226d721\",\"name\":\"JohnCalvi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"JohnCalvi\"},\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/author\\\/johncalvi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cu\u00e1queros, sexualidad y espiritualidad - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/cuaqueros-sexualidad-y-espiritualidad\/","og_locale":"es_ES","og_type":"article","og_title":"Cu\u00e1queros, sexualidad y espiritualidad - Friends Journal","og_description":"Hablar de sexo en cualquier contexto, incluso en uno cu\u00e1quero, puede ser peligroso porque no todos usamos el mismo lenguaje.&hellip;","og_url":"https:\/\/www.friendsjournal.org\/es\/cuaqueros-sexualidad-y-espiritualidad\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"2004-06-01T04:00:43+00:00","og_image":[{"width":779,"height":438,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg","type":"image\/jpeg"}],"author":"JohnCalvi","twitter_card":"summary_large_image","twitter_creator":"@friendsournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"JohnCalvi","Est. reading time":"11 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/es\/cuaqueros-sexualidad-y-espiritualidad\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/cuaqueros-sexualidad-y-espiritualidad\/"},"author":{"name":"JohnCalvi","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/dfc793da08cce0ffb1388c07b226d721"},"headline":"Cu\u00e1queros, sexualidad y espiritualidad","datePublished":"2004-06-01T04:00:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/cuaqueros-sexualidad-y-espiritualidad\/"},"wordCount":2158,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"keywords":["Crecimiento espiritual","Expresi\u00f3n sexual","Sexualidad"],"articleSection":["cr\u00f3nicas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/cuaqueros-sexualidad-y-espiritualidad\/","url":"https:\/\/www.friendsjournal.org\/es\/cuaqueros-sexualidad-y-espiritualidad\/","name":"Cu\u00e1queros, sexualidad y espiritualidad - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"datePublished":"2004-06-01T04:00:43+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/cuaqueros-sexualidad-y-espiritualidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/cuaqueros-sexualidad-y-espiritualidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/cuaqueros-sexualidad-y-espiritualidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Cu\u00e1queros, sexualidad y espiritualidad"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/dfc793da08cce0ffb1388c07b226d721","name":"JohnCalvi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"JohnCalvi"},"url":"https:\/\/www.friendsjournal.org\/es\/author\/johncalvi\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"author_name":"John Calvi","bio":"<p>John Calvi, miembro del Meeting de Putney (Vt.), ha trabajado con supervivientes de traumas durante 22 a\u00f1os. Su libro sobre la curaci\u00f3n de traumas, <em>The Dance between Hope and Fear: The Soft Touch Journals<\/em>, estar\u00e1 disponible a finales de este a\u00f1o. <\/p>\n","issue":"Junio de 2004"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3117098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/557"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3117098"}],"version-history":[{"count":0,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3117098\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3117098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3117098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/tags?post=3117098"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3117098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}