{"id":3117236,"date":"2006-01-01T00:00:27","date_gmt":"2006-01-01T05:00:27","guid":{"rendered":"https:\/\/www.friendsjournal.org\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\/"},"modified":"2006-01-01T00:00:27","modified_gmt":"2006-01-01T05:00:27","slug":"sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/es\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\/","title":{"rendered":"Sanaci\u00f3n en el Meeting for Worship en el encuentro de FGC de 1995"},"content":{"rendered":"<blockquote><p>\u00bfCu\u00e1l es el fundamento y la base del Meeting reunido? En \u00faltimo an\u00e1lisis, estoy convencido de que es la Presencia Real de Dios.<br \/>\n\u2014Thomas R. Kelly, 1940<\/p><\/blockquote>\n<p>Llegu\u00e9 al Encuentro de la Conferencia General de los Amigos ese a\u00f1o, 1995, en Kalamazoo, Michigan, sin ninguna expectativa de lo que suceder\u00eda: un milagro de sanaci\u00f3n durante la adoraci\u00f3n. Hab\u00eda estado teniendo recuerdos repentinos del accidente automovil\u00edstico de mi esposa, probablemente s\u00edndrome de estr\u00e9s postraum\u00e1tico. Pens\u00e9 que cuando llegu\u00e9 los recuerdos repentinos estaban disminuyendo, pero el s\u00e1bado por la noche en la ceremonia de apertura volvieron con fuerza, v\u00edvidos y dolorosos. El d\u00eda siguiente fue dif\u00edcil; los tuve todo el d\u00eda. Fui ese domingo por la tarde al Meeting for Worship bajo el cuidado de Friends for Lesbian and Gay Concerns<em> [FLGC; ahora llamado Friends for Lesbian, Gay, Bisexual, Transgender, and Queer Concerns, FLGBTQC\u2014eds.]<\/em>. Hab\u00eda estado asistiendo a esta adoraci\u00f3n cada a\u00f1o en el Encuentro desde 1986. La adoraci\u00f3n estaba en marcha solo unos minutos cuando comenzaron las l\u00e1grimas. Llor\u00e9 toda la hora. Sab\u00eda que era seguro llorar all\u00ed. Es asombroso en s\u00ed mismo que uno pueda llorar con seguridad en el Meeting for Worship cu\u00e1quero.         <\/p>\n<p>A la ma\u00f1ana siguiente, en la media hora de la Biblia, el texto fueron las palabras de Jes\u00fas desde la Cruz: \u201cDios m\u00edo, Dios m\u00edo, \u00bfpor qu\u00e9 me has abandonado?\u00bb Las palabras cortaron mi alma. \u00bfPor qu\u00e9, Dios, me hab\u00edas abandonado? \u00bfD\u00f3nde estabas para m\u00ed ahora?   <\/p>\n<p>El accidente de Marian fue el 8 de enero de 1991. Ella qued\u00f3 tetrapl\u00e9jica al llegar al hospital por una lesi\u00f3n de la m\u00e9dula espinal debido a una fractura de cuello. Ten\u00eda otras lesiones, incluyendo m\u00faltiples fracturas de su pierna derecha y lesiones pulmonares. Despu\u00e9s de una cirug\u00eda mayor, dos semanas en la UCI y luego fisioterapia, mejor\u00f3 lentamente. Despu\u00e9s de cuatro meses, sali\u00f3 del hospital en una silla de ruedas. Todav\u00eda no pod\u00eda soportar peso sobre su pierna derecha. Debatimos si ir al Encuentro ese a\u00f1o y, despu\u00e9s de llamadas telef\u00f3nicas a la oficina de FGC para ver si el sitio era accesible para sillas de ruedas, decidimos ir. Cuando llegamos, Marian estaba dando algunos pasos con muletas, as\u00ed que nos las arreglamos bastante bien. En noviembre de ese a\u00f1o caminaba con un bast\u00f3n, y en enero del a\u00f1o siguiente caminaba sin ninguna ayuda. Hab\u00eda logrado una recuperaci\u00f3n notable y milagrosa de aproximadamente el 95 por ciento de su funci\u00f3n. Seguimos agradecidos.          <\/p>\n<p>Me fue bien a trav\u00e9s de todo esto. Regres\u00e9 al trabajo tres semanas despu\u00e9s del accidente. Pude atender las necesidades de Marian, visitarla dos veces al d\u00eda en el hospital, trabajar a tiempo completo y manejar las cosas en casa. Luego, unos tres a\u00f1os despu\u00e9s, comenzaron los recuerdos repentinos: la llamada telef\u00f3nica: \u201cSu esposa ha tenido un accidente automovil\u00edstico grave y est\u00e1 en cirug\u00eda. Ser\u00e1 mejor que venga\u00bb. Luego, el viaje de p\u00e1nico a un hospital a dos horas de distancia; verla por primera vez paralizada; las transfusiones de sangre; verla esforzarse por respirar y luego ponerle un respirador; enfrentar a los manifestantes antiaborto que iban al hospital la ma\u00f1ana despu\u00e9s del accidente con carteles que dec\u00edan: \u201cEste hospital mata\u00bb; y muchos m\u00e1s.    <\/p>\n<p>Estos recuerdos repentinos aumentaron gradualmente en frecuencia e intensidad y se apoderaron de mi vida. Pod\u00eda trabajar, y mientras me mantuviera ocupado pod\u00eda funcionar, pero durante cualquier momento de tranquilidad estaban all\u00ed. Sab\u00eda que necesitaba ayuda profesional y comenc\u00e9 a recibir asesoramiento. Decidimos no usar medicamentos, pero no obstante los recuerdos repentinos disminuyeron gradualmente. Estaba mejorando cuando llegu\u00e9 al Encuentro y pens\u00e9 que se hab\u00edan ido en su mayor parte, pero no fue as\u00ed. Regresaron de nuevo: intensos, angustiantes, como si estuviera all\u00ed de nuevo.     <\/p>\n<p>Un recuerdo repentino recurrente esa semana fue precipitado por una sesi\u00f3n plenaria temprana. Harvey Gilman, un Amigo de Gran Breta\u00f1a, habl\u00f3 sobre \u00e1ngeles. Probablemente dijo otras cosas, pero solo recuerdo la parte sobre \u00e1ngeles. Sugiri\u00f3 que deber\u00edamos funcionar m\u00e1s como \u00e1ngeles, mensajeros de Dios, el uno para el otro. El d\u00eda del accidente, una vez que llegu\u00e9 al hospital y me hab\u00eda ocupado de las cosas que uno necesita hacer en estas crisis, comenz\u00f3 la espera. Me sent\u00ed terriblemente solo, deseando desesperadamente que alguien estuviera conmigo. Hab\u00eda hecho m\u00faltiples intentos infructuosos de comunicarme con mi hijo que viv\u00eda a unas dos horas de distancia. Estaba sentado solo en la sala de espera de cuidados intensivos con la cabeza entre las manos, llorando. La se\u00f1ora de la limpieza entr\u00f3. Despu\u00e9s de unos minutos de limpieza superficial, se acerc\u00f3 a m\u00ed, se sent\u00f3, me rode\u00f3 con su brazo y me pregunt\u00f3 qu\u00e9 pasaba. Despu\u00e9s de que le expliqu\u00e9, sugiri\u00f3 que llamara a la polic\u00eda en la ciudad donde viv\u00eda mi hijo, se levant\u00f3 y se fue. Nunca hab\u00eda pensado en eso, lo hice, y pronto Paul estaba al tel\u00e9fono y en camino para unirse a m\u00ed. \u00bfUn \u00e1ngel? No, una se\u00f1ora de la limpieza; pero \u00bfpor qu\u00e9 no termin\u00f3 su limpieza?            <\/p>\n<p>Continu\u00e9 asistiendo a la adoraci\u00f3n de FLGC cada tarde. Los mensajes comenzaron a llegarme. Algunos mensajes hablaban de dolor y angustia. El dolor era diferente al m\u00edo, pero me toc\u00f3. Del dolor surgieron otros mensajes de consuelo, perd\u00f3n, agradecimiento, esperanza, amor y alegr\u00eda. Los mensajes me hablaron directamente. No le hab\u00eda dicho a nadie lo que estaba pasando, a nadie. Sin embargo, los mensajes estaban claramente destinados a m\u00ed. La sanaci\u00f3n comenz\u00f3. Las l\u00e1grimas disminuyeron. Los recuerdos repentinos perdieron su intensidad y luego se detuvieron por completo. Fue el milagro del Meeting for Worship reunido. Estoy convencido de que fue la presencia real de Dios.           <\/p>\n<p>No he tenido ning\u00fan recuerdo repentino grave desde entonces. Cuando el Encuentro regres\u00f3 a Kalamazoo en 1999, me hab\u00eda olvidado de toda la experiencia anterior. En mi taller en la segunda ma\u00f1ana, una mujer mencion\u00f3 a un amigo cuyo hijo hab\u00eda tenido un accidente automovil\u00edstico grave. Los recuerdos volvieron junto con algunos de los recuerdos repentinos, pero fueron breves. Ese a\u00f1o pude compartir por primera vez lo que hab\u00eda sucedido cuatro a\u00f1os antes en la adoraci\u00f3n de FLGC, y agradecer a la comunidad de FLGC por su contribuci\u00f3n a mi sanaci\u00f3n. Y sigo agradecido.     <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfCu\u00e1l es el fundamento y la base del Meeting reunido? En \u00faltimo an\u00e1lisis, estoy convencido de que es la Presencia&hellip;<\/p>\n","protected":false},"author":679,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9799],"tags":[11411,12048,11494],"fpb_issue_category":[],"class_list":["post-3117236","post","type-post","status-publish","format-standard","hentry","category-cronicas","tag-homosexualidad","tag-meeting-for-worship","tag-sanacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sanaci\u00f3n en el Meeting for Worship en el encuentro de FGC de 1995 - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sanaci\u00f3n en el Meeting for Worship en el encuentro de FGC de 1995 - Friends Journal\" \/>\n<meta property=\"og:description\" content=\"\u00bfCu\u00e1l es el fundamento y la base del Meeting reunido? En \u00faltimo an\u00e1lisis, estoy convencido de que es la Presencia&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"2006-01-01T05:00:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"779\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RichVanDellen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RichVanDellen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\\\/\"},\"author\":{\"name\":\"RichVanDellen\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/db388d5322a6e5cd8d6779e91722f26c\"},\"headline\":\"Sanaci\u00f3n en el Meeting for Worship en el encuentro de FGC de 1995\",\"datePublished\":\"2006-01-01T05:00:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\\\/\"},\"wordCount\":1126,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"keywords\":[\"homosexualidad\",\"Meeting for Worship\",\"Sanaci\u00f3n\"],\"articleSection\":[\"cr\u00f3nicas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\\\/\",\"name\":\"Sanaci\u00f3n en el Meeting for Worship en el encuentro de FGC de 1995 - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"datePublished\":\"2006-01-01T05:00:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sanaci\u00f3n en el Meeting for Worship en el encuentro de FGC de 1995\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/db388d5322a6e5cd8d6779e91722f26c\",\"name\":\"RichVanDellen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"RichVanDellen\"},\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/author\\\/richvandellen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sanaci\u00f3n en el Meeting for Worship en el encuentro de FGC de 1995 - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\/","og_locale":"es_ES","og_type":"article","og_title":"Sanaci\u00f3n en el Meeting for Worship en el encuentro de FGC de 1995 - Friends Journal","og_description":"\u00bfCu\u00e1l es el fundamento y la base del Meeting reunido? En \u00faltimo an\u00e1lisis, estoy convencido de que es la Presencia&hellip;","og_url":"https:\/\/www.friendsjournal.org\/es\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"2006-01-01T05:00:27+00:00","og_image":[{"width":779,"height":438,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg","type":"image\/jpeg"}],"author":"RichVanDellen","twitter_card":"summary_large_image","twitter_creator":"@friendsournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"RichVanDellen","Est. reading time":"6 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/es\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\/"},"author":{"name":"RichVanDellen","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/db388d5322a6e5cd8d6779e91722f26c"},"headline":"Sanaci\u00f3n en el Meeting for Worship en el encuentro de FGC de 1995","datePublished":"2006-01-01T05:00:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\/"},"wordCount":1126,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"keywords":["homosexualidad","Meeting for Worship","Sanaci\u00f3n"],"articleSection":["cr\u00f3nicas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\/","url":"https:\/\/www.friendsjournal.org\/es\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\/","name":"Sanaci\u00f3n en el Meeting for Worship en el encuentro de FGC de 1995 - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"datePublished":"2006-01-01T05:00:27+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/sanacion-en-el-meeting-for-worship-en-el-encuentro-de-fgc-de-1995\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Sanaci\u00f3n en el Meeting for Worship en el encuentro de FGC de 1995"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/db388d5322a6e5cd8d6779e91722f26c","name":"RichVanDellen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"RichVanDellen"},"url":"https:\/\/www.friendsjournal.org\/es\/author\/richvandellen\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"author_name":"Rich Van Dellen","bio":"<p>Rich Van Dellen es miembro del Meeting de Rochester (Minnesota). Escribe esto en agradecimiento a FLGBTQC, y expresa su empat\u00eda por los veteranos de guerra que regresan y otras personas que tienen s\u00edndrome de estr\u00e9s postraum\u00e1tico. <\/p>\n","issue":"Enero de 2006"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3117236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/679"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3117236"}],"version-history":[{"count":0,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3117236\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3117236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3117236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/tags?post=3117236"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3117236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}