{"id":3118353,"date":"2009-07-01T00:00:42","date_gmt":"2009-07-01T04:00:42","guid":{"rendered":"https:\/\/www.friendsjournal.org\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\/"},"modified":"2009-07-01T00:00:42","modified_gmt":"2009-07-01T04:00:42","slug":"el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/es\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\/","title":{"rendered":"El debate sobre la energ\u00eda nuclear entre Amigos: otra ronda"},"content":{"rendered":"<p>El 11 de diciembre de 2008, se public\u00f3 en https:\/\/www.change.gov un informe firmado por diez directores de laboratorios nacionales, <em>Sustainable Energy Future: The Essential Role of Nuclear Energy<\/em>. Su aparici\u00f3n confirm\u00f3 de nuevo lo que las comunidades cient\u00edfica y pol\u00edtica hab\u00edan concluido hace tiempo: existe la necesidad de ampliar la energ\u00eda nuclear, y Yucca Mountain es adecuado para el almacenamiento de residuos a largo plazo. Entre estos expertos, este consenso establecido sobre la necesidad de la energ\u00eda nuclear est\u00e1 estrechamente relacionado con otro consenso establecido desde hace mucho tiempo: la enorme gravedad del cambio clim\u00e1tico. <\/p>\n<p>Me perturba escuchar a Amigos expresar menos temor al cambio clim\u00e1tico que a utilizar la energ\u00eda nuclear para ayudar a evitarlo. Los Amigos cuyo amor por el medio ambiente encuentra su principal v\u00eda de escape en la lucha contra la energ\u00eda nuclear pueden estar robando a la verdadera lucha su energ\u00eda y activismo, y ayudando a reducir nuestras ya de por s\u00ed inadecuadas opciones. <\/p>\n<p>En mi art\u00edculo \u201cEl camino de un Amigo hacia la energ\u00eda nuclear\u00bb (<em>FJ<\/em> Oct. 2008), compart\u00ed los sentimientos que surgieron cuando le\u00ed los \u00faltimos informes sobre el cambio clim\u00e1tico: dolor por los efectos que ya no podemos evitar, y temor a que nos falte la voluntad y la claridad para salvarnos de los cambios que a\u00fan son evitables. Las respuestas que aparecieron en n\u00fameros posteriores de <em>FJ<\/em> me aseguran que mi dolor es compartido, al igual que mi dedicaci\u00f3n a hacer todo lo posible para ralentizar o detener nuestro movimiento hacia efectos cada vez m\u00e1s desastrosos del cambio clim\u00e1tico. Agradezco el elocuente llamamiento de Carolyn Treadway a mayores esfuerzos en materia de conservaci\u00f3n (\u201cLos peligros de la energ\u00eda nuclear\u00bb, <em>FJ<\/em> Feb. 2009), una parte esencial de cualquier soluci\u00f3n. En mis talleres, los participantes aprenden a medir y reducir su huella de carbono e inspiran a otros a hacer lo mismo. (Un Amigo me culpa por las duchas que se da en el barco incluso en las ma\u00f1anas fr\u00edas, otro por la decisi\u00f3n de reducir a la mitad sus viajes en avi\u00f3n. Ambos encuentran alegr\u00eda en estas decisiones, al igual que aquellos que ahora controlan anualmente sus emisiones de gases de efecto invernadero (GEI), compartiendo entre s\u00ed c\u00f3mo lograr reducciones a\u00fan mayores).     <\/p>\n<p>A Treadway y a otros les gustar\u00eda creer que una combinaci\u00f3n de conservaci\u00f3n individual, mejora de la eficiencia energ\u00e9tica y la ampliaci\u00f3n del uso de recursos renovables \u2014tres partes importantes de cualquier soluci\u00f3n, todos est\u00e1n de acuerdo\u2014 nos permitir\u00e1 sustituir los combustibles f\u00f3siles sin ninguna ayuda de la energ\u00eda nuclear. Sin embargo, percibo una insidiosa relajaci\u00f3n de la voluntad en aquellos que expresan un optimismo prematuro basado en soluciones t\u00e9cnicas y en algunos cambios de comportamiento f\u00e1cilmente alcanzables. Lo percibo en cartas y art\u00edculos que dicen que tenemos tantas soluciones que podemos permitirnos desechar algunas.  <\/p>\n<p>Mientras tanto, los informes del Grupo Intergubernamental de Expertos sobre el Cambio Clim\u00e1tico (IPCC) y de otros lugares no apoyan el optimismo. En los \u00faltimos meses, los cient\u00edficos han informado de una aceleraci\u00f3n de los cambios causados por el calentamiento global: los \u00e1rboles mueren m\u00e1s r\u00e1pido, las zonas muertas oce\u00e1nicas se expanden y los corales y otros animales oce\u00e1nicos se ven estresados debido al aumento de la acidez de los oc\u00e9anos. Los ping\u00fcinos ant\u00e1rticos acaban de ser a\u00f1adidos a la lista de extinciones previstas para este siglo. Aunque a la mayor\u00eda de los climat\u00f3logos les gustar\u00eda que los niveles atmosf\u00e9ricos de CO2 se mantuvieran por debajo de 450 partes por mill\u00f3n (ppm), estamos en camino de alcanzar las 550 ppm en 2035. Mantener las emisiones de carbono por debajo de las 600 ppm se hace cada vez m\u00e1s dif\u00edcil. Entre 450 y 600 ppm, se esperan cuencas de polvo en gran parte de la Tierra, incluyendo el suroeste de Norteam\u00e9rica, este siglo. El Secretario de Energ\u00eda, Steven Chu, advierte que tanto las ciudades como la agricultura en California (m\u00e1s de una sexta parte de la naci\u00f3n) pueden desaparecer a finales de siglo.      <\/p>\n<p>Estas proyecciones se basan en supuestos que muchos prefieren no hacer: que la poblaci\u00f3n aumentar\u00e1 y no disminuir\u00e1; que el consumo de energ\u00eda aumentar\u00e1 en los pa\u00edses menos desarrollados m\u00e1s r\u00e1pido de lo que puede disminuir en los EE.UU. (si es que puede disminuir aqu\u00ed); y que la tecnolog\u00eda para la energ\u00eda e\u00f3lica, hidroel\u00e9ctrica y de biomasa puede ofrecer de forma asequible, en el mejor de los casos, el 30-35 por ciento de la electricidad para 2030, y no se espera que la energ\u00eda solar entre en juego de forma significativa, seg\u00fan el IPCC, hasta 2030 y despu\u00e9s.<\/p>\n<p><em>Asumir<\/em> \u2014como hacen los cient\u00edficos con fines de predicci\u00f3n\u2014 no es lo mismo que aceptar. La conclusi\u00f3n inevitable que sacan los responsables pol\u00edticos de la investigaci\u00f3n citada en los informes del IPCC es que aproximadamente dos tercios de las necesidades de electricidad proyectadas para 2030 (necesidades que se espera que sean mucho mayores que los niveles actuales) deben ser cubiertas por alguna combinaci\u00f3n de combustibles f\u00f3siles y energ\u00eda nuclear. Hasta ahora, las predicciones de los cient\u00edficos, basadas en los c\u00e1lculos m\u00e1s sofisticados que pueden hacer, han tendido a <em>subestimar<\/em> la tasa y el alcance de los da\u00f1os causados por el cambio clim\u00e1tico. Su objetivo no es alarmar, sino evaluar de forma realista lo que se necesitar\u00e1 para ralentizar los cambios que se avecinan. Reconocer nuestras realidades actuales no significa que relajemos nuestros esfuerzos o nuestras oraciones. Significa que estamos en una mejor posici\u00f3n para ver hacia d\u00f3nde deben dirigirse nuestros esfuerzos. En este contexto, me solidarizo con los Amigos que apoyan la conservaci\u00f3n, la eficiencia y las subvenciones para las renovaciones. Pero me pregunto por aquellos que siguen oponi\u00e9ndose a la energ\u00eda nuclear por sus riesgos reales e imaginarios, a pesar de los riesgos mucho mayores de no aprovechar este fuerte caballo para nuestro carro.       <\/p>\n<h3>Fuentes<\/h3>\n<p>\u00bfQu\u00e9 estamos pensando cuando ignoramos las conclusiones de la comunidad cient\u00edfica? \u00bfC\u00f3mo estamos eligiendo a qu\u00e9 \u201ccient\u00edficos\u00bb creer? Es importante examinar las fuentes que elegimos y por qu\u00e9 depositamos nuestra fe en ellas, ya que las diferencias fundamentales en lo que leemos y en qui\u00e9n confiamos afectan al lugar donde plantamos la bandera de nuestro activismo. Para los encuestados que citan referencias, pregunto: \u00bfQu\u00e9 les anima a depositar su confianza en sus fuentes? Por ejemplo, Ace Hoffman y Janette Sherman, en \u201cOtra visi\u00f3n sobre la energ\u00eda nuclear\u00bb (<em>FJ <\/em>Ene. 2009) conf\u00edan en \u201ccient\u00edficos que fueron testigos de primera mano de la cat\u00e1strofe (de Chern\u00f3bil)\u00bb, como si las impresiones de los individuos in situ fueran un mejor camino hacia el conocimiento que los datos y las pruebas cuidadosamente recogidos a lo largo del tiempo.    <\/p>\n<p>Robert Anderson, en \u201cLa energ\u00eda nuclear no es la respuesta\u00bb (<em>FJ<\/em> Ene. 2009), acusa a una organizaci\u00f3n de la ONU, el Organismo Internacional de Energ\u00eda At\u00f3mica (OIEA), de hacer afirmaciones sospechosas, al tiempo que considera que Greenpeace y la Liga Internacional de Mujeres por la Paz y la Libertad son fuentes fiables de datos cient\u00edficos. John Wright Daschke, en \u201cLas &#8216;ventajas&#8217; de la energ\u00eda nuclear son ilusorias\u00bb (<em>FJ<\/em> Ene. 2009), se basa en Amory Lovins, que estudi\u00f3 f\u00edsica, trabaj\u00f3 para Amigos de la Tierra y ahora es un icono cultural. Carolyn Treadway conf\u00eda en el Servicio de Informaci\u00f3n y Recursos Nucleares, Helen Caldicott, Joseph Mangano y otros para su comprensi\u00f3n de la ciencia, y en Arjun Makhijani y Lester Brown para la pol\u00edtica, aunque ninguno de ellos es citado por el Grupo Intergubernamental de Expertos sobre el Cambio Clim\u00e1tico, creado por la ONU y la Organizaci\u00f3n Meteorol\u00f3gica Mundial para \u201cproporcionar . . . una fuente objetiva de informaci\u00f3n sobre el cambio clim\u00e1tico\u00bb.  <\/p>\n<p>Treadway tambi\u00e9n describe a la Comisi\u00f3n Reguladora Nuclear de EE.UU. (NRC) como \u201cen el bolsillo\u00bb de la industria, y Hoffman y Sherman dicen que la NRC nos est\u00e1 mintiendo porque es \u201cresponsable de promover\u00bb la energ\u00eda nuclear. En realidad, la NRC recibi\u00f3 las responsabilidades reguladoras de la Comisi\u00f3n de Energ\u00eda At\u00f3mica, mientras que el Departamento de Energ\u00eda recibi\u00f3 la responsabilidad de promoci\u00f3n; estas se separaron cuando se cre\u00f3 la NRC. Tal vez la cita de Hoffman y Sherman provenga de una antigua descripci\u00f3n de la AEC. A nivel internacional, la NRC es muy respetada por los cient\u00edficos y los gobiernos que conf\u00edan en la integridad de su investigaci\u00f3n.   <\/p>\n<p>Me siento a\u00fan m\u00e1s consternado cuando los Amigos se alinean con aquellos que tienen la costumbre de desconfiar de la ONU como fuente de informaci\u00f3n. Hoffman y Sherman califican al OIEA de \u201csesgado\u00bb, y Robert Anderson acusa al OIEA de desinformaci\u00f3n flagrante, incluso de negar que \u201cninguno de los efectos catastr\u00f3ficos para la salud\u00bb de Chern\u00f3bil se debiera a la radiaci\u00f3n porque su objetivo principal es \u201cpromover la energ\u00eda nuclear\u00bb. Sin embargo, en virtud del Tratado de No Proliferaci\u00f3n Nuclear (TNP), la responsabilidad del OIEA es aplicar salvaguardias internacionales mediante inspecciones invasivas para garantizar que los Estados parte del tratado no adquieran ni desarrollen armas nucleares. El OIEA tambi\u00e9n tiene la obligaci\u00f3n expl\u00edcita de ayudar a los Estados no poseedores de armas que firman el TNP a adquirir tecnolog\u00eda nuclear pac\u00edfica, principalmente para usos m\u00e9dicos y agr\u00edcolas. El OIEA no tiene ning\u00fan conflicto de intereses concebible que le incline a negar los efectos documentados para la salud de un accidente nuclear.    <\/p>\n<p>Creo que entre las fuentes m\u00e1s fiables disponibles se encuentran el OIEA, el Grupo Intergubernamental de Expertos sobre el Cambio Clim\u00e1tico (IPCC) y la Academia Nacional de Ciencias de EE.UU. (NAS). La informaci\u00f3n que publican es rigurosamente revisada por pares, ampliamente respetada por cient\u00edficos y expertos en pol\u00edtica, y utilizada por gobiernos e industrias. Cuando un informe suscita desacuerdo en las comunidades cient\u00edfica y pol\u00edtica, lo que ocurre, se cubre en revistas como <em>Science<\/em>. Aquellos que se especializan en an\u00e1lisis alternativos que entran en conflicto con el OIEA, el IPCC o la NAS, a menudo presentan argumentos que no tienen sentido para las personas formadas en ciencia. (Por ejemplo, Lovins celebra que en 2006 se construy\u00f3 m\u00e1s micropotencia que energ\u00eda nuclear, ignorando que la micropotencia suele ser energ\u00eda de combustibles f\u00f3siles).    <\/p>\n<p>Para aquellos que deseen m\u00e1s informaci\u00f3n sobre la energ\u00eda nuclear, recomiendo encarecidamente <em>Nuclear Energy, 2nd edition<\/em> de David Bodanasky. Este libro est\u00e1 escrito para f\u00edsicos e ingenieros y se conf\u00eda en que caracterice con precisi\u00f3n lo que se conoce y lo que no se conoce en el campo. Grandes partes son accesibles a personas sin ninguna formaci\u00f3n en el campo.  <\/p>\n<h3>\u00bfInvestigadores de la radiaci\u00f3n que mienten?<\/h3>\n<p>A veces me desconcierta el grado de desconfianza hacia la comunidad cient\u00edfica dominante entre los Amigos. Parte de esto proviene de historias de los medios de comunicaci\u00f3n de cient\u00edficos \u201ccomprados\u00bb e investigaciones controladas por la industria en las que se suprimen los resultados desfavorables, sobre todo en lo que respecta a las pruebas de medicamentos, y el raro art\u00edculo \u201cel tabaco est\u00e1 bien\u00bb en revistas revisadas por pares. Hoffman y Sherman parecen implicar que la mayor parte de la investigaci\u00f3n sobre la radiactividad est\u00e1 pagada por la industria, y que la financiaci\u00f3n se detiene si los datos parecen mostrar un problema, como afirman que ocurri\u00f3 con el tabaco. Creo que lo contrario es cierto: esencialmente todos los art\u00edculos publicados en las revistas cient\u00edficas revisadas por pares conten\u00edan resultados perjudiciales relacionados con el tabaco, y ciertamente el discernimiento general de la comunidad cient\u00edfica, basado en los art\u00edculos publicados, es que el tabaco es peligroso, raz\u00f3n por la cual el gobierno pudo actuar para controlar el consumo de tabaco. Del mismo modo, el mayor inter\u00e9s de la comunidad cient\u00edfica es descubrir lo m\u00e1ximo posible sobre los efectos reales de la radiaci\u00f3n en la salud humana. Demasiados cient\u00edficos est\u00e1n trabajando en este problema para que su trabajo sea f\u00e1cilmente suprimido por la industria o la pol\u00edtica. (A pesar de los intentos de la administraci\u00f3n de George W. Bush de suprimir los informes cient\u00edficos sobre una variedad de temas, la investigaci\u00f3n sali\u00f3 a la luz).      <\/p>\n<p>La investigaci\u00f3n cient\u00edfica sobre los efectos de la radiaci\u00f3n es la \u00fanica forma fiable de establecer l\u00edmites seguros de exposici\u00f3n; el problema se convierte en la aplicaci\u00f3n de estos l\u00edmites. La preocupaci\u00f3n p\u00fablica podr\u00eda centrarse \u00fatilmente en la supervisi\u00f3n de los peligros conocidos en lugar de en la desconfianza hacia la investigaci\u00f3n validada, que a veces nos dice que los peligros que m\u00e1s tememos no son reales. Adem\u00e1s, es importante centrarse en la reducci\u00f3n de los grandes riesgos. Estos incluyen los peligros de las alternativas a la energ\u00eda nuclear y las posibles consecuencias de la falta de energ\u00eda en los pa\u00edses pobres. Seg\u00fan todas las mediciones, los riesgos de las pr\u00e1cticas actuales con la energ\u00eda nuclear son muy peque\u00f1os en comparaci\u00f3n.    <\/p>\n<h3>\u00bfIncompetencia en todos los niveles?<\/h3>\n<p>Anderson dice que estamos a punto de quedarnos sin uranio, y Treadway dice que si se considera todo el ciclo del combustible, la energ\u00eda nuclear contribuye al calentamiento global. Adem\u00e1s de las acusaciones de conspiraci\u00f3n masiva sin una motivaci\u00f3n clara, estas son acusaciones de pura incompetencia: que decenas de gobiernos, cientos de gestores de emplazamientos, decenas de miles de cient\u00edficos y analistas de pol\u00edticas hicieron planes para expandir la energ\u00eda nuclear, y nadie se molest\u00f3 en comprobar las emisiones del ciclo de vida y el suministro de uranio? <\/p>\n<p>Las afirmaciones sobre las bajas cantidades de uranio probablemente se refieren a la categor\u00eda relativamente peque\u00f1a, las reservas de uranio \u201crazonablemente aseguradas\u00bb. Un aumento temporal de los precios del uranio con la expansi\u00f3n real y propuesta de la energ\u00eda nuclear condujo a una exploraci\u00f3n a peque\u00f1a escala, que aument\u00f3 la cantidad de reservas de uranio conocidas en un 15 por ciento entre 2005 y 2007, pero todav\u00eda hay poca motivaci\u00f3n para una b\u00fasqueda exhaustiva. Esto se debe a que hay uranio m\u00e1s que suficiente para la energ\u00eda nuclear actual y planificada en las minas ya localizadas y f\u00e1cilmente encontradas. Los precios del uranio tienen s\u00f3lo un peque\u00f1o efecto en el precio de la energ\u00eda nuclear porque, a diferencia de las plantas de combustibles f\u00f3siles y biomasa, el precio del combustible es peque\u00f1o en comparaci\u00f3n con el coste de la planta. Ciertamente, hay suficiente uranio terrestre (sin contar el uranio en el agua de mar) para aumentar el n\u00famero de reactores actuales en 2-4 veces para las vidas \u00fatiles previstas de las plantas de m\u00e1s de 50-75 a\u00f1os. Los dise\u00f1os para los reactores posteriores ser\u00e1n de Generaci\u00f3n IV: operar\u00e1n a temperaturas m\u00e1s altas (por lo que proporcionar\u00e1n m\u00e1s electricidad por entrada), o\/y utilizar\u00e1n otros combustibles como el U-238 (m\u00e1s de 100 veces m\u00e1s com\u00fan que el U-235), el plutonio y el torio (m\u00e1s de 3 veces m\u00e1s com\u00fan que el uranio).     <\/p>\n<p>Las afirmaciones sobre los altos costes de GEI de la energ\u00eda nuclear, como las proporcionadas por el trabajo a menudo citado de Jan Willem Storm van Leeuwen y Philip Smith, se basan en n\u00fameros dudosos. En la Parte F de <g id=\"gid_0\">Nuclear Power\u2014The Energy Balance<\/g>, los autores ignoran los datos, y en su lugar asumen que el coste energ\u00e9tico de la construcci\u00f3n es (coste de la construcci\u00f3n) multiplicado por (energ\u00eda\/unidad de producto interior bruto), en un momento de enormes costes debido a los largos retrasos y los altos tipos de inter\u00e9s, sin ninguna justificaci\u00f3n para esta f\u00f3rmula. El coste energ\u00e9tico de la miner\u00eda tambi\u00e9n se obtuvo sin recurrir a los datos: la predicci\u00f3n para una mina de Namibia fue 60 veces el uso real de energ\u00eda, y mayor que el uso de energ\u00eda de todo el pa\u00eds.  <\/p>\n<p><em>A guide to life-cycle greenhouse gas (GHG) emissions from electric supply technologies<\/em> del OIEA proporciona un rango de emisiones de GEI (g\/kWh) para el ciclo de vida completo de las principales fuentes de electricidad basado en los resultados de una serie de estudios de una variedad de pa\u00edses. En resumen, la energ\u00eda nuclear (2,8-24 g\/kWh, con valores mayores para el m\u00e9todo m\u00e1s antiguo de enriquecimiento de uranio) es comparable a la energ\u00eda e\u00f3lica (8-30 g\/kWh, ignorando el respaldo de combustibles f\u00f3siles), algo m\u00e1s limpia que la biomasa (35-99 g\/kWh) y la fotovoltaica (paneles solares, <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 11 de diciembre de 2008, se public\u00f3 en https:\/\/www.change.gov un informe firmado por diez directores de laboratorios nacionales, Sustainable&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9799],"tags":[11475,11067],"fpb_issue_category":[],"class_list":["post-3118353","post","type-post","status-publish","format-standard","hentry","category-cronicas","tag-comentario","tag-medio-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El debate sobre la energ\u00eda nuclear entre Amigos: otra ronda - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El debate sobre la energ\u00eda nuclear entre Amigos: otra ronda - Friends Journal\" \/>\n<meta property=\"og:description\" content=\"El 11 de diciembre de 2008, se public\u00f3 en https:\/\/www.change.gov un informe firmado por diez directores de laboratorios nacionales, Sustainable&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-07-01T04:00:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"779\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/02ede88796a9d1611a21f82931b1e7eb\"},\"headline\":\"El debate sobre la energ\u00eda nuclear entre Amigos: otra ronda\",\"datePublished\":\"2009-07-01T04:00:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\\\/\"},\"wordCount\":2917,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"keywords\":[\"Comentario\",\"Medio ambiente\"],\"articleSection\":[\"cr\u00f3nicas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\\\/\",\"name\":\"El debate sobre la energ\u00eda nuclear entre Amigos: otra ronda - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"datePublished\":\"2009-07-01T04:00:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El debate sobre la energ\u00eda nuclear entre Amigos: otra ronda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/02ede88796a9d1611a21f82931b1e7eb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6513f6a937ed019d97e442698edbd3b2009216c76f15ed16e2d04e3118a33da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6513f6a937ed019d97e442698edbd3b2009216c76f15ed16e2d04e3118a33da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6513f6a937ed019d97e442698edbd3b2009216c76f15ed16e2d04e3118a33da?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El debate sobre la energ\u00eda nuclear entre Amigos: otra ronda - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\/","og_locale":"es_ES","og_type":"article","og_title":"El debate sobre la energ\u00eda nuclear entre Amigos: otra ronda - Friends Journal","og_description":"El 11 de diciembre de 2008, se public\u00f3 en https:\/\/www.change.gov un informe firmado por diez directores de laboratorios nacionales, Sustainable&hellip;","og_url":"https:\/\/www.friendsjournal.org\/es\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"2009-07-01T04:00:42+00:00","og_image":[{"width":779,"height":438,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@friendsournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"admin","Est. reading time":"15 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/es\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\/"},"author":{"name":"admin","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/02ede88796a9d1611a21f82931b1e7eb"},"headline":"El debate sobre la energ\u00eda nuclear entre Amigos: otra ronda","datePublished":"2009-07-01T04:00:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\/"},"wordCount":2917,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"keywords":["Comentario","Medio ambiente"],"articleSection":["cr\u00f3nicas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\/","url":"https:\/\/www.friendsjournal.org\/es\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\/","name":"El debate sobre la energ\u00eda nuclear entre Amigos: otra ronda - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"datePublished":"2009-07-01T04:00:42+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/el-debate-sobre-la-energia-nuclear-entre-amigos-otra-ronda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"El debate sobre la energ\u00eda nuclear entre Amigos: otra ronda"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/02ede88796a9d1611a21f82931b1e7eb","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6513f6a937ed019d97e442698edbd3b2009216c76f15ed16e2d04e3118a33da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6513f6a937ed019d97e442698edbd3b2009216c76f15ed16e2d04e3118a33da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6513f6a937ed019d97e442698edbd3b2009216c76f15ed16e2d04e3118a33da?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.friendsjournal.org\/es\/author\/admin\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"author_name":"Karen Street","bio":"<p>Karen Street, miembro del Meeting de Berkeley (California), sigue trabajando en el cambio clim\u00e1tico. Para consultar las referencias y notas a pie de p\u00e1gina de este art\u00edculo, visite el blog de Karen, A Musing Environment: https:\/\/pathsoflight.us\/musing. <\/p>\n","issue":"Julio de 2009"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3118353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3118353"}],"version-history":[{"count":0,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3118353\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3118353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3118353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/tags?post=3118353"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3118353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}