{"id":3119279,"date":"2013-03-27T06:00:05","date_gmt":"2013-03-27T10:00:05","guid":{"rendered":"https:\/\/www.friendsjournal.org\/guerra-con-drones\/"},"modified":"2013-03-27T06:00:05","modified_gmt":"2013-03-27T10:00:05","slug":"guerra-con-drones","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/","title":{"rendered":"Guerra con drones"},"content":{"rendered":"<figure id=\"attachment_3013505\" aria-describedby=\"caption-attachment-3013505\" style=\"width: 300px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3013505\" alt=\"Foto de la Fuerza A\u00e9rea de EE. UU.\/Tte. Col. Leslie Pratt\" src=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2013\/03\/drone-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2013\/03\/drone-300x199.jpg 300w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2013\/03\/drone.jpg 735w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-3013505\" class=\"wp-caption-text\">{%CAPTION%}<\/figcaption><\/figure>\n<p>Form\u00e9 parte de una delegaci\u00f3n a Pakist\u00e1n en octubre de 2012 para abordar el tema de la guerra con drones de Estados Unidos. Varios miles de paquistan\u00edes, incluidos ni\u00f1os peque\u00f1os, han muerto a causa de los drones estadounidenses y muchos otros han resultado gravemente heridos. Durante solo un d\u00eda de nuestra visita, 18 personas murieron por drones.  <\/p>\n<p>Escuchamos a personas cuyos familiares hab\u00edan sido asesinados. Uno de ellos, un periodista paquistan\u00ed en duelo, resumi\u00f3 su visi\u00f3n de la situaci\u00f3n diciendo: \u201cLa sangre derramada [ <i>sic<\/i>] del pueblo musulm\u00e1n no tiene valor\u201d. Nos cont\u00f3 sobre el ataque con drones que destruy\u00f3 su casa, matando a su hijo de 18 a\u00f1os, a su hermano menor y a un cantero que estaba en el pueblo para trabajar en la mezquita. Su hijo, un reci\u00e9n graduado de la escuela secundaria, estaba trabajando en su escuela porque quer\u00eda alentar a la comunidad a valorar la educaci\u00f3n. Su hermano ten\u00eda una maestr\u00eda en literatura inglesa y hab\u00eda ense\u00f1ado durante ocho a\u00f1os, tratando de transmitir a los estudiantes que la educaci\u00f3n era m\u00e1s poderosa que las armas. Dej\u00f3 una esposa afligida y un hijo de dos a\u00f1os.<\/p>\n<p>Escuchamos sobre el terror causado por la constante presencia de drones en algunas \u00e1reas. Los paquistan\u00edes tienen miedo de asistir a reuniones como bodas, funerales o Meetings de negocios. Saben que probablemente todos morir\u00e1n si sus casas son atacadas, y creen que la Agencia Central de Inteligencia de EE. UU. considera a todos los hombres j\u00f3venes y de mediana edad como objetivos potenciales. (Un nuevo manual de lucha contra el terrorismo para operaciones de asesinatos selectivos exime expl\u00edcitamente a la CIA de tener que seguir las reglas en su campa\u00f1a de ataques con drones en Pakist\u00e1n durante al menos un a\u00f1o).   <\/p>\n<p>Cuando el Jefe Adjunto de la Misi\u00f3n de EE. UU., Richard Hoagland, habl\u00f3 con nosotros, mantuvo que muy pocos civiles hab\u00edan muerto por drones. Cuando se le pregunt\u00f3 sobre la segunda ola e incluso los m\u00faltiples ataques que han estado matando e hiriendo a muchos rescatistas, afirm\u00f3 que en los \u00faltimos a\u00f1os nunca ha habido ataques deliberados contra rescatistas. Le instamos a investigar y proporcionar un informe p\u00fablico.  <\/p>\n<p>El d\u00eda despu\u00e9s de una vigilia con velas con j\u00f3venes, viajamos hacia las \u00e1reas objetivo de Wazirist\u00e1n con la gran caravana de paz de Imran Khan. Pasamos a muchas personas que expresaron su apoyo saludando y haciendo el signo de la paz. En una manifestaci\u00f3n, nos paramos en el escenario con nuestra pancarta \u201cStop Killer Drones\u201d. Medea Benjamin de Code Pink habl\u00f3; la multitud grit\u00f3 repetidamente: \u201c\u00a1Bienvenidos! \u00a1Queremos la paz!\u201d   <\/p>\n<p>Antes del viaje, el Departamento de Estado de EE. UU. hab\u00eda emitido una advertencia de que los ciudadanos estadounidenses estar\u00edan en peligro si viajaban a Pakist\u00e1n. Nuestra delegaci\u00f3n recibi\u00f3 una c\u00e1lida bienvenida. Nos ducharon con p\u00e9talos de rosa y nos dieron ramos de flores en el aeropuerto. A lo largo del viaje, fuimos recibidos calurosamente y se nos mostr\u00f3 una generosa hospitalidad a pesar de la pobreza del pa\u00eds. La gente entendi\u00f3 que creemos que sus vidas son sagradas y que estamos comprometidos a trabajar por la paz y el fin del mal de la guerra con drones. Puede ser una lucha larga y dif\u00edcil, ya que el gobierno de EE. UU. parece tener la intenci\u00f3n de continuar con el uso de la guerra con drones para ayudar a controlar su acceso a los recursos naturales.     <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Form\u00e9 parte de una delegaci\u00f3n a Pakist\u00e1n en octubre de 2012 para abordar el tema de la guerra con drones&hellip;<\/p>\n","protected":false},"author":3,"featured_media":3074673,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10330],"tags":[],"fpb_issue_category":[10573],"class_list":["post-3119279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-testimonio","fpb_issue_category-abril-de-2013-conflicto-y-acompanamiento-de-ancianos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guerra con drones - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guerra con drones - Friends Journal\" \/>\n<meta property=\"og:description\" content=\"Form\u00e9 parte de una delegaci\u00f3n a Pakist\u00e1n en octubre de 2012 para abordar el tema de la guerra con drones&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-03-27T10:00:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2013\/03\/drone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"735\" \/>\n\t<meta property=\"og:image:height\" content=\"488\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Kelley\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsjournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Kelley\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/guerra-con-drones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/guerra-con-drones\\\/\"},\"author\":{\"name\":\"Martin Kelley\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/7ed35dbed87f6eb86c60eeb3e20e078e\"},\"headline\":\"Guerra con drones\",\"datePublished\":\"2013-03-27T10:00:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/guerra-con-drones\\\/\"},\"wordCount\":620,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/guerra-con-drones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/drone.jpg\",\"articleSection\":[\"Testimonio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/guerra-con-drones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/guerra-con-drones\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/guerra-con-drones\\\/\",\"name\":\"Guerra con drones - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/guerra-con-drones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/guerra-con-drones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/drone.jpg\",\"datePublished\":\"2013-03-27T10:00:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/guerra-con-drones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/guerra-con-drones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/guerra-con-drones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/drone.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/drone.jpg\",\"width\":735,\"height\":488,\"caption\":\"Foto de la Fuerza A\u00e9rea de EE. UU.\\\/Tte. Col. Leslie Pratt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/guerra-con-drones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guerra con drones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/7ed35dbed87f6eb86c60eeb3e20e078e\",\"name\":\"Martin Kelley\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73c5649dadaf46c4891d23d2368860a1c1117699ed6a4fa439414de35b8da588?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73c5649dadaf46c4891d23d2368860a1c1117699ed6a4fa439414de35b8da588?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73c5649dadaf46c4891d23d2368860a1c1117699ed6a4fa439414de35b8da588?s=96&d=mm&r=g\",\"caption\":\"Martin Kelley\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/friendsjournal\"],\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/author\\\/martink\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guerra con drones - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/","og_locale":"es_ES","og_type":"article","og_title":"Guerra con drones - Friends Journal","og_description":"Form\u00e9 parte de una delegaci\u00f3n a Pakist\u00e1n en octubre de 2012 para abordar el tema de la guerra con drones&hellip;","og_url":"https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"2013-03-27T10:00:05+00:00","og_image":[{"width":735,"height":488,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2013\/03\/drone.jpg","type":"image\/jpeg"}],"author":"Martin Kelley","twitter_card":"summary_large_image","twitter_creator":"@friendsjournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"Martin Kelley","Est. reading time":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/"},"author":{"name":"Martin Kelley","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/7ed35dbed87f6eb86c60eeb3e20e078e"},"headline":"Guerra con drones","datePublished":"2013-03-27T10:00:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/"},"wordCount":620,"commentCount":0,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2013\/03\/drone.jpg","articleSection":["Testimonio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/","url":"https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/","name":"Guerra con drones - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2013\/03\/drone.jpg","datePublished":"2013-03-27T10:00:05+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2013\/03\/drone.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2013\/03\/drone.jpg","width":735,"height":488,"caption":"Foto de la Fuerza A\u00e9rea de EE. UU.\/Tte. Col. Leslie Pratt"},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/guerra-con-drones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Guerra con drones"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/7ed35dbed87f6eb86c60eeb3e20e078e","name":"Martin Kelley","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/73c5649dadaf46c4891d23d2368860a1c1117699ed6a4fa439414de35b8da588?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/73c5649dadaf46c4891d23d2368860a1c1117699ed6a4fa439414de35b8da588?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/73c5649dadaf46c4891d23d2368860a1c1117699ed6a4fa439414de35b8da588?s=96&d=mm&r=g","caption":"Martin Kelley"},"sameAs":["https:\/\/x.com\/friendsjournal"],"url":"https:\/\/www.friendsjournal.org\/es\/author\/martink\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"author_name":"Joan Nicholson","bio":"<p>Joan Nicholson form\u00f3 parte de una delegaci\u00f3n a Pakist\u00e1n en octubre de 2012 patrocinada por Code Pink y la Foundation for Fundamental Rights. Los 32 delegados inclu\u00edan a otro participante cu\u00e1quero. Fue con fondos de Philadelphia Yearly Meeting y contribuciones de Friends.  <\/p>\n"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3119279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3119279"}],"version-history":[{"count":0,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3119279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3074673"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3119279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3119279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/tags?post=3119279"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3119279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}