{"id":3124802,"date":"2022-12-01T02:40:00","date_gmt":"2022-12-01T07:40:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/enfrentarse-al-mal-encontrar-la-libertad\/"},"modified":"2025-10-12T05:19:58","modified_gmt":"2025-10-12T09:19:58","slug":"enfrentarse-al-mal-encontrar-la-libertad","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/","title":{"rendered":"Enfrentarse al mal, encontrar la libertad"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>C\u00f3mo la victoria de Cristo sobre el pecado es nuestra para compartir hoy<\/strong><\/h3>\n\n<figure class=\"wp-block-audio\"><audio controls=\"\" src=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/12\/Adria_and_Peterson_Sideapaou.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Peterson Toscano habl\u00f3 con Adria para el <a href=\"https:\/\/www.friendsjournal.org\/es\/podcast\/cuaqueros-y-redencion\/\">podcast de diciembre de Quakers Today<\/a>.<\/figcaption><\/figure>\n\n<p class=\"has-drop-cap wp-block-paragraph\">Mientras reflexiono sobre los acontecimientos que nos rodean, a menudo mis pensamientos se dirigen a la Guerra del Cordero, como los Amigos tradicionalmente llaman a la lucha por resistir el pecado y permanecer fieles a la llamada de Dios en un mundo a menudo hostil. Sin embargo, hablar de esta batalla espiritual entre el bien y el mal con otros Amigos liberales puede ser dif\u00edcil. Muchos de nosotros existimos en un mundo donde conceptos como \u201cpecado\u201d y \u201cmal\u201d parecen anacr\u00f3nicos. En este mundo, las necesidades b\u00e1sicas est\u00e1n incuestionablemente cubiertas, las adicciones son discretas y la violencia es impensable. En este mundo, la gente puede estar confundida o desorientada o ser disfuncional, pero \u00bf\u201cpecadora\u201d? \u00a1Qu\u00e9 concepto tan anticuado! \u00bfNo es suficiente, podr\u00edan decir esos Amigos, tratar de ser buenos y reconocer que hay algo de Dios en cada persona, sin dejarse atrapar por tonter\u00edas supersticiosas?      <\/p>\n\n<p class=\"wp-block-paragraph\">Ese podr\u00eda ser el caso, si la gran mayor\u00eda de la humanidad no habitara otro mundo completamente diferente: uno menos privilegiado y mucho m\u00e1s peligroso. En ese mundo, no \u201cponer la otra mejilla\u201d no solo conduce a chismes o al distanciamiento, sino a tiroteos desde coches en represalia. En ese mundo, la decisi\u00f3n de un hombre de abandonar a su familia no solo conduce a la compleja log\u00edstica de la custodia compartida, sino al hambre, la falta de vivienda y la ira generacional en los ni\u00f1os que quedan atr\u00e1s. En ese mundo, la adicci\u00f3n no significa una afici\u00f3n excesiva a los c\u00f3cteles despu\u00e9s de la cena, sino que los ni\u00f1os vuelven a casa y descubren que pap\u00e1 ha vendido sus preciados juguetes por un coloc\u00f3n o que mam\u00e1 est\u00e1 demasiado ocupada entreteniendo a sus \u201camigos\u201d para darles un ba\u00f1o o prepararles la comida. En ese mundo, las decisiones que tomamos no son opciones de estilo de vida neutrales, sino choques s\u00edsmicos que repercuten en la vida de nuestros seres m\u00e1s cercanos para bien o para mal.     <\/p>\n\n<p class=\"wp-block-paragraph\">En ese mundo, las muchas maneras en que da\u00f1amos a los dem\u00e1s, ya sea poniendo deliberadamente nuestros deseos por encima de nuestros deberes o como prisioneros de compulsiones, como la ira, la atracci\u00f3n y la adicci\u00f3n, pueden tener efectos inmediatos y devastadores. Para la persona cuya vida est\u00e1 hecha jirones despu\u00e9s del abandono o el abuso, simplemente decir \u201chay algo de Dios en todos\u201d no explica c\u00f3mo alguien con \u201calgo de Dios\u201d en \u00e9l podr\u00eda comportarse de una manera tan devastadora o c\u00f3mo un Dios bueno y amoroso podr\u00eda permitirlo. Para la persona que es torturada por los efectos de sus acciones pero no parece poder tomar decisiones diferentes, simplemente decir \u201ctrata de ser bueno y recuerda que hay algo de Dios en todos\u201d no explica c\u00f3mo puede relacionarse con Dios cuando sabe en su coraz\u00f3n que no es, de hecho, bueno. Tampoco explica c\u00f3mo, si hay algo de Dios en ellos, hay abundante evidencia de que tambi\u00e9n hay algo de mal en ellos.   <\/p>\n\n<p class=\"wp-block-paragraph\">Esta es la enfermedad del alma que los primeros Amigos llamaron pecado: la debilidad, la enfermedad y la destrucci\u00f3n que desordenan nuestras vidas y nos llevan a hacernos da\u00f1o a nosotros mismos y a los dem\u00e1s.<\/p>\n\n<h6 class=\"has-text-align-center has-pale-cyan-blue-color has-quaker-speak-blue-background-color has-text-color has-background wp-block-heading\"><strong>Y si consideramos honestamente nuestras propias vidas (c\u00f3mo a menudo justificamos nuestro orgullo, nuestros prejuicios y los actos y omisiones cotidianos que equivalen a violencia espiritual o indiferencia insensible), es probable que nos demos cuenta de que el pecado no est\u00e1 solo \u201cah\u00ed fuera\u201d en el mundo, sino tambi\u00e9n en nuestros propios corazones, por muy \u201cbuenos\u201d o respetables que seamos convencionalmente.<\/strong><\/h6>\n\n<p class=\"has-drop-cap wp-block-paragraph\">A veces, el pecado es una elecci\u00f3n: el supervisor da una mala cr\u00edtica no debido a la mala calidad del trabajo, sino porque encuentra un placer perverso en infligir da\u00f1o a alguien que no le gusta. A veces, el pecado es compulsi\u00f3n: la tortura que enfrenta el marido concienzudo que no parece poder poner fin a sus sesiones de pornograf\u00eda nocturnas, aunque sabe que su matrimonio, su paternidad y su rendimiento laboral est\u00e1n sufriendo como resultado. A veces, el pecado es el resultado de perspectivas distorsionadas transmitidas de generaci\u00f3n en generaci\u00f3n: la madre devota que reprende y humilla a sus queridos hijos porque, en su experiencia, eso es lo que hacen las madres amorosas. Aunque la palabra suene anticuada, la realidad del pecado nos confronta cada vez que abrimos nuestros peri\u00f3dicos para leer historias de un grupo \u00e9tnico que oprime a otro, de l\u00edderes religiosos que se aprovechan de sus reba\u00f1os, de entrenadores que abusan de sus jugadores o de funcionarios p\u00fablicos que traicionan la confianza de sus electores. Y si consideramos honestamente nuestras propias vidas (c\u00f3mo a menudo justificamos nuestro orgullo, nuestros prejuicios y los actos y omisiones cotidianos que equivalen a violencia espiritual o indiferencia insensible), es probable que nos demos cuenta de que el pecado no est\u00e1 solo ah\u00ed fuera en el mundo, sino tambi\u00e9n en nuestros propios corazones, por muy buenos o respetables que seamos convencionalmente.    <\/p>\n\n<p class=\"wp-block-paragraph\">Ante las cat\u00e1strofes provocadas por el hombre, que van desde los horrores legalmente sancionados de la esclavitud de bienes muebles hasta los sangrientos genocidios de los siglos XIX y XX, pasando por la epidemia de opioides c\u00ednicamente dise\u00f1ada, las frases que a veces se utilizan en los c\u00edrculos cu\u00e1queros liberales para hablar de las malas acciones (<em>la gente no puede ser malvada, solo est\u00e1 confundida<\/em>; o <em>si eres bueno m\u00e1s a menudo de lo que eres malo, est\u00e1s bien<\/em>; o <em>no creo en el pecado, porque hay algo de Dios en todos<\/em>) pueden parecer lamentablemente inadecuadas. En el mejor de los casos, parecen poco realistas e ingenuas. En el peor de los casos, son evidencia de un tipo de magnanimidad privilegiada que solo es posible para las personas cuyas vidas nunca han sido destrozadas por las acciones devastadoras de otros. Al minimizar la corrupci\u00f3n espiritual muy real que marca a tantos de nosotros en cuerpo y alma, este enfoque puede dejarnos tambale\u00e1ndonos cuando inevitablemente encontramos hipocres\u00eda, agresi\u00f3n y ego\u00edsmo en nosotros mismos o en los dem\u00e1s. Tambi\u00e9n contrasta fuertemente con la cosmovisi\u00f3n cu\u00e1quera tradicional, que es simult\u00e1neamente inflexible en su reconocimiento de la fealdad del mal e inquebrantable en su fe de que Dios es lo suficientemente amoroso y poderoso como para superar ese mal de una vez por todas.    <\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<p class=\"has-drop-cap wp-block-paragraph\">Esta creencia es com\u00fan a muchas comprensiones cristianas de la \u201cexpiaci\u00f3n\u201d, la palabra tradicional para la forma en que Cristo tiende un puente sobre la brecha entre Dios y la humanidad. Los primeros Amigos y otros vieron la \u201cuni\u00f3n\u201d, o reconciliaci\u00f3n, como necesaria debido a la divisi\u00f3n fundamental entre la perfecci\u00f3n de Dios y la imperfecci\u00f3n de la humanidad, entre la bondad constante de Dios y la inconsistencia constante y el fracaso moral confiable de la humanidad. Pero hab\u00eda una diferencia clave entre estos primeros cu\u00e1queros y el resto de la iglesia: los Amigos cre\u00edan que la expiaci\u00f3n realmente funcionaba.  <\/p>\n\n<p class=\"wp-block-paragraph\">El estribillo com\u00fan en la \u00e9poca de los or\u00edgenes del cuaquerismo era que nadie es capaz de verdadera bondad en un mundo ca\u00eddo. En esta visi\u00f3n, mientras seamos criaturas de carne y hueso, las malas acciones y la debilidad espiritual son inevitables. Los Amigos rechazaron esta concesi\u00f3n al mal de todo coraz\u00f3n, ridiculiz\u00e1ndola como \u201cpredicaci\u00f3n del pecado\u201d y conden\u00e1ndola como un rechazo de la promesa de Dios e incluso un truco del Diablo. Aludiendo a la pr\u00e1ctica de la esclavitud en el Imperio Otomano, George Fox escribi\u00f3 en la Ep\u00edstola 222:   <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Ahora, qu\u00e9 valor, precio y m\u00e9rito le han dado a la sangre de Cristo, que limpia del pecado y de la muerte; y sin embargo, le dijeron a la gente que los llevar\u00edan al conocimiento del hijo de Dios, y a un hombre perfecto, y ahora les dicen que no deben ser perfectos en la tierra, sino llevar un cuerpo de pecado con ellos a la tumba? . . . Esto es tanto como si uno estuviera en Turqu\u00eda como esclavo, encadenado a un barco, y uno viniera a redimirlo para ir a su propio pa\u00eds; pero dicen los turcos, est\u00e1s redimido, pero mientras est\u00e9s en la tierra, no debes salir de Turqu\u00eda, ni quitarte la cadena. . . . Pero yo digo que sois redimidos por Cristo; le cost\u00f3 su sangre comprar al hombre fuera de este estado en el que se encuentra, en la ca\u00edda, y llevarlo al estado en el que estaba el hombre antes de caer; as\u00ed que Cristo se convirti\u00f3 en una maldici\u00f3n, para sacar al hombre de la maldici\u00f3n, y soport\u00f3 la ira, para llevar al hombre a la paz de Dios, para que pudiera llegar al estado bendito, y al estado de Ad\u00e1n en el que estaba antes de caer; y no solo all\u00ed, sino a un estado en Cristo que nunca caer\u00e1. Y este es mi testimonio para vosotros, y para toda la gente sobre la tierra. Y as\u00ed los maestros del mundo clamaron, los hombres son redimidos, pero mientras est\u00e9n en la tierra deben tener el pecado original en ellos.   . . . \u00a1Qu\u00e9 triste noticia! \u00bfSon estos mensajeros de Dios, o mensajeros de Satan\u00e1s? <\/p>\n<\/blockquote>\n\n<h6 class=\"has-text-align-center has-pale-cyan-blue-color has-quaker-speak-blue-background-color has-text-color has-background wp-block-heading\"><strong>Esta es, fundamentalmente, la raz\u00f3n por la que nuestras creencias sobre la expiaci\u00f3n importan. Si creemos que la expiaci\u00f3n es innecesaria porque las personas son esencialmente buenas, las acciones malvadas se ver\u00e1n como un error o una aberraci\u00f3n, en lugar de como una caracter\u00edstica predecible de la condici\u00f3n humana.  <\/strong><\/h6>\n\n<p class=\"has-drop-cap wp-block-paragraph\">En opini\u00f3n de los primeros Amigos, Cristo hab\u00eda redimido a la humanidad (nos hab\u00eda sacado de la esclavitud) al derramar su sangre en la Cruz. \u00bfPor qu\u00e9 \u00edbamos a dejar que los sacerdotes y los \u201cprofesores\u201d nos volvieran a encadenar? <\/p>\n\n<p class=\"wp-block-paragraph\">Los primeros Amigos se mantuvieron firmes en la fe de que la victoria de Cristo sobre el pecado y sus consecuencias mortales era completa y eterna y que es nuestra para compartir (1 Cor. 15:55\u201357). La humanidad ya no est\u00e1 condenada a vivir como prisioneros de nuestras propias hambres desordenadas, incapaces de seguir la Luz porque somos tan adictos a la comodidad, al placer y al poder. En lugar de ser siervos abusados y maltratados del pecado, somos hijos amados y apreciados de Dios (G\u00e1l. 4:3\u20137). En lugar de la esclavitud a la carne y a los deseos de nuestros egos, tenemos libertad en el Esp\u00edritu. Esta libertad no es metaf\u00f3rica o abstracta, sino real, concreta e inmediata. Puedes dejar de perseguir compulsivamente el prestigio, ahora. Puedes dejar de recurrir a los placeres sensuales para la satisfacci\u00f3n emocional, ahora. Puedes dejar de ceder a la rabia, ahora. Puedes dejar de dejar que la ansiedad te vuelva ego\u00edsta, ahora. Puedes dejar de refugiarte en el privilegio de clase o en el privilegio racial para sentirte seguro, ahora. Dios te ha dado, y a todos nosotros, esa libertad, si nos atrevemos a aceptarla.          <\/p>\n\n<p class=\"wp-block-paragraph\">Esta audaz y atrevida afirmaci\u00f3n, uno de los elementos m\u00e1s controvertidos de la fe cu\u00e1quera tradicional, parece casi incre\u00edble para aquellos de nosotros que tratamos de hacer lo correcto pero a\u00fan as\u00ed fracasamos regularmente. \u00bfQui\u00e9n no querr\u00eda liberarse de las voces y presiones que nos alejan de la bondad que amamos para actuar en cambio de maneras que odiamos? \u00bfNo estamos ya haciendo todo lo posible? Pero ah\u00ed, podr\u00edan decir los primeros Amigos, est\u00e1 la ra\u00edz del problema: seguimos confiando en nuestro propio esfuerzo, en nuestros propios intentos, para reformar nuestro comportamiento. En cambio, debemos recurrir a la Luz. Fox hace este punto enf\u00e1ticamente en un pasaje de la Ep\u00edstola 46 que puede ser parafraseado de la siguiente manera:     <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Aquellos que siguen su propio juicio, en lugar de buscar la voluntad de Dios, est\u00e1n condenados. Su gloria y su corona es el orgullo, que los conducir\u00e1 a la destrucci\u00f3n, el desorden y la desobediencia a la Luz. Pero aquellos que aman y siguen la Luz son gobernados por Cristo, cuyo camino es una buena noticia para toda la creaci\u00f3n.  <\/p>\n<\/blockquote>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<p class=\"has-drop-cap wp-block-paragraph\">En la visi\u00f3n cu\u00e1quera tradicional, la libertad de la confusi\u00f3n y la corrupci\u00f3n espiritual est\u00e1 disponible gratuitamente para nosotros, pero esa libertad est\u00e1 disponible solo en la medida en que estemos dispuestos a dejar de lado nuestra propia experiencia, nuestras propias prioridades y nuestros propios deseos, y esperar a ser guiados por el Esp\u00edritu.<\/p>\n\n<p class=\"wp-block-paragraph\">Los primeros Amigos cre\u00edan que ser llevados a una nueva forma de vida a trav\u00e9s del poder del Esp\u00edritu es inmediato cuando empezamos a escuchar la voz de Dios y a obedecerla.<\/p>\n\n<p class=\"wp-block-paragraph\">Esta creencia, tradicionalmente conocida como \u201cperfecci\u00f3n\u201d, no pretend\u00eda implicar que no hab\u00eda espacio para un mayor crecimiento en la bondad. Despu\u00e9s de todo, como Robert Barclay escribi\u00f3 en su <em>Apolog\u00eda de la verdadera divinidad cristiana<\/em>, \u201cun ni\u00f1o tiene un cuerpo perfecto al igual que un hombre, aunque diariamente crezca m\u00e1s y m\u00e1s\u201d (\u201cSobre la perfecci\u00f3n\u201d, Secci\u00f3n 2). Nuestra perfecci\u00f3n reside en la obediencia a los mensajes que el Esp\u00edritu nos da. A medida que atendemos a la gu\u00eda de Dios en nuestros corazones, se nos da gradualmente m\u00e1s y m\u00e1s gu\u00eda para ser fieles. Nuestras vidas se transforman como resultado, con el poder del pecado sobre nosotros debilit\u00e1ndose a medida que nuestras vidas muestran los frutos externos de nuestra relaci\u00f3n continua con el Cristo Interior.    <\/p>\n\n<p class=\"wp-block-paragraph\">Esta es, fundamentalmente, la raz\u00f3n por la que nuestras creencias sobre la expiaci\u00f3n importan. Si creemos que la expiaci\u00f3n es innecesaria porque las personas son esencialmente buenas, las acciones malvadas se ver\u00e1n como un error o una aberraci\u00f3n, en lugar de como una caracter\u00edstica predecible de la condici\u00f3n humana. Para aquellos de nosotros que abrazamos esta perspectiva, puede que nos resulte un desaf\u00edo considerar humilde y realistamente nuestras propias deficiencias o participar proactivamente en las pr\u00e1cticas que mantienen seguras a nuestras comunidades, porque realmente creemos que todos actuar\u00e1n por el bien de todos los dem\u00e1s, a pesar de la evidencia a menudo tr\u00e1gica de lo contrario. En el otro extremo del espectro, si creemos que el prop\u00f3sito de la expiaci\u00f3n era perdonar nuestras malas acciones, pero que nuestra naturaleza humana fundamental permanece sin cambios, nos veremos tentados a racionalizar y minimizar los fracasos de la virtud y las din\u00e1micas abusivas como la evidencia inevitable del pecado en un mundo ca\u00eddo.   <\/p>\n\n<p class=\"wp-block-paragraph\">Como resultado, podemos reconocer que es parte de nuestro llamado como Amigos ejercer el perd\u00f3n amoroso, pero no ver que, como Amigos fieles, tambi\u00e9n estamos llamados a ayudarnos mutuamente a resistir el mal en primer lugar, y a desarraigarlo de entre nosotros con ternura, coraje y humildad.<\/p>\n\n<h6 class=\"has-text-align-center has-pale-cyan-blue-color has-quaker-speak-blue-background-color has-text-color has-background wp-block-heading\"><strong>Si esperamos abordar los problemas que enfrentamos . . . debemos reconocer que el mal es real y devastador, pero que puede, con la ayuda divina, ser superado. Debemos enfrentarnos al oc\u00e9ano de oscuridad que Fox reconoci\u00f3 en su famosa visi\u00f3n, si queremos ver que en el oc\u00e9ano de luz que fluye sobre \u00e9l est\u00e1 el infinito amor de Dios. <\/strong><\/h6>\n\n<p class=\"has-drop-cap wp-block-paragraph\">La visi\u00f3n cu\u00e1quera tradicional de la expiaci\u00f3n puede ayudarnos a evitar estos extremos. La perspectiva cu\u00e1quera tradicional crea un espacio en el que podemos reconocer las innumerables maneras en que nuestras actitudes y acciones nos hieren a nosotros mismos y a los dem\u00e1s, sabiendo que ya tenemos el perd\u00f3n de Dios. Podemos examinar los aspectos de nosotros mismos y de nuestras comunidades que preferir\u00edamos evitar con la confianza de que nuestras deficiencias no nos separan del amor de Dios. Podemos confrontar el mal con esperanza en lugar de miedo, sabiendo que Dios nos dar\u00e1 la perspicacia necesaria para caminar en fidelidad a trav\u00e9s de situaciones desafiantes, as\u00ed como el coraje para hacerlo. Muchas de nuestras pr\u00e1cticas tradicionales crecen a partir de esta visi\u00f3n, y funcionan maravillosamente en la medida en que las practicamos con integridad. Nuestra creencia en la capacidad del individuo para ser guiado por el Esp\u00edritu es m\u00e1s recompensada cuando esos individuos son apoyados por ancianos fuertes y amorosos comprometidos a proteger la seguridad y la salud espiritual del Meeting en su conjunto. Nuestro ejercicio fiel del Orden del Evangelio (la armon\u00eda y el cuidado de una comunidad gobernada por el Cristo Interior) no puede realizarse plenamente en ausencia de una voluntad compartida de ser buscados y disciplinados por la Luz.      <\/p>\n\n<p class=\"wp-block-paragraph\">Lejos de ser sofismas teol\u00f3gicos, nuestra comprensi\u00f3n de la expiaci\u00f3n es esencial, dando forma a c\u00f3mo nos vemos a nosotros mismos, c\u00f3mo vemos a nuestras comunidades y c\u00f3mo vemos a Dios. Si esperamos abordar los problemas que enfrentamos, incluyendo la supremac\u00eda blanca, la polarizaci\u00f3n pol\u00edtica, los conflictos en nuestros Meetings y lo que significa vivir fielmente en una sociedad que cambia r\u00e1pidamente, debemos reconocer que el mal es real y devastador, pero que puede, con la ayuda divina, ser superado. Debemos enfrentarnos al oc\u00e9ano de oscuridad que Fox reconoci\u00f3 en su famosa visi\u00f3n, si queremos ver que en el oc\u00e9ano de luz que fluye sobre \u00e9l est\u00e1 el infinito amor de Dios.  <\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<h2 class=\"wp-block-heading\">Extra web<\/h2>\n\n<p class=\"wp-block-paragraph\">El autor aparece en el episodio de diciembre del podcast de Quakers Today.<\/p>\n\n<iframe loading=\"lazy\" style=\"border: none; min-width: min(100%, 430px);\" title=\"Cu\u00e1queros y redenci\u00f3n\" src=\"https:\/\/www.podbean.com\/player-v2\/?i=rw74a-1338614-pb&#038;from=pb6admin&#038;share=1&#038;download=1&#038;rtl=0&#038;fonts=Arial&#038;skin=1&#038;font-color=auto&#038;logo_link=episode_page&#038;btn-skin=fb0584\" width=\"100%\" height=\"150\" scrolling=\"no\" data-name=\"pb-iframe-player\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>C\u00f3mo la victoria de Cristo sobre el pecado es nuestra para<br \/>\ncompartir hoy.<\/p>\n","protected":false},"author":5090,"featured_media":3089654,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9799],"tags":[10764,10876,11447,11243],"fpb_issue_category":[10697],"class_list":["post-3124802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronicas","tag-cuaqueros","tag-dios","tag-espiritu-santo-2","tag-estado","fpb_issue_category-expiacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enfrentarse al mal, encontrar la libertad - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enfrentarse al mal, encontrar la libertad\" \/>\n<meta property=\"og:description\" content=\"C\u00f3mo la victoria de Cristo sobre el pecado es nuestra para compartir hoy.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-01T07:40:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-12T09:19:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/11\/Gulizia_featured.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"725\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Friends Journal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Enfrentarse al mal, encontrar la libertad\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Friends Journal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/enfrentarse-al-mal-encontrar-la-libertad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/enfrentarse-al-mal-encontrar-la-libertad\\\/\"},\"author\":{\"name\":\"Friends Journal\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/315ffb22a36ecbabdf5dbdc09d7d1eb7\"},\"headline\":\"Enfrentarse al mal, encontrar la libertad\",\"datePublished\":\"2022-12-01T07:40:00+00:00\",\"dateModified\":\"2025-10-12T09:19:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/enfrentarse-al-mal-encontrar-la-libertad\\\/\"},\"wordCount\":2996,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/enfrentarse-al-mal-encontrar-la-libertad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Gulizia_featured.jpg\",\"keywords\":[\"Cu\u00e1queros\",\"Dios\",\"Esp\u00edritu (Santo)\",\"Estado\"],\"articleSection\":[\"cr\u00f3nicas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/enfrentarse-al-mal-encontrar-la-libertad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/enfrentarse-al-mal-encontrar-la-libertad\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/enfrentarse-al-mal-encontrar-la-libertad\\\/\",\"name\":\"Enfrentarse al mal, encontrar la libertad - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/enfrentarse-al-mal-encontrar-la-libertad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/enfrentarse-al-mal-encontrar-la-libertad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Gulizia_featured.jpg\",\"datePublished\":\"2022-12-01T07:40:00+00:00\",\"dateModified\":\"2025-10-12T09:19:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/enfrentarse-al-mal-encontrar-la-libertad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/enfrentarse-al-mal-encontrar-la-libertad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/enfrentarse-al-mal-encontrar-la-libertad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Gulizia_featured.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Gulizia_featured.jpg\",\"width\":1400,\"height\":725},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/enfrentarse-al-mal-encontrar-la-libertad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enfrentarse al mal, encontrar la libertad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/315ffb22a36ecbabdf5dbdc09d7d1eb7\",\"name\":\"Friends Journal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"caption\":\"Friends Journal\"},\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/author\\\/alla-podolsky\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enfrentarse al mal, encontrar la libertad - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/","og_locale":"es_ES","og_type":"article","og_title":"Enfrentarse al mal, encontrar la libertad","og_description":"C\u00f3mo la victoria de Cristo sobre el pecado es nuestra para compartir hoy.","og_url":"https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"2022-12-01T07:40:00+00:00","article_modified_time":"2025-10-12T09:19:58+00:00","og_image":[{"width":1400,"height":725,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/11\/Gulizia_featured.jpg","type":"image\/jpeg"}],"author":"Friends Journal","twitter_card":"summary_large_image","twitter_title":"Enfrentarse al mal, encontrar la libertad","twitter_creator":"@friendsournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"Friends Journal","Est. reading time":"15 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/"},"author":{"name":"Friends Journal","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/315ffb22a36ecbabdf5dbdc09d7d1eb7"},"headline":"Enfrentarse al mal, encontrar la libertad","datePublished":"2022-12-01T07:40:00+00:00","dateModified":"2025-10-12T09:19:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/"},"wordCount":2996,"commentCount":0,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/11\/Gulizia_featured.jpg","keywords":["Cu\u00e1queros","Dios","Esp\u00edritu (Santo)","Estado"],"articleSection":["cr\u00f3nicas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/","url":"https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/","name":"Enfrentarse al mal, encontrar la libertad - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/11\/Gulizia_featured.jpg","datePublished":"2022-12-01T07:40:00+00:00","dateModified":"2025-10-12T09:19:58+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/11\/Gulizia_featured.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2022\/11\/Gulizia_featured.jpg","width":1400,"height":725},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/enfrentarse-al-mal-encontrar-la-libertad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Enfrentarse al mal, encontrar la libertad"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/315ffb22a36ecbabdf5dbdc09d7d1eb7","name":"Friends Journal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","caption":"Friends Journal"},"url":"https:\/\/www.friendsjournal.org\/es\/author\/alla-podolsky\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"author_name":"Adria Gulizia","bio":"<p>Adria Gulizia es abogada, mediadora, facilitadora y coach. Su preocupaci\u00f3n por la formaci\u00f3n espiritual de los Amigos de todas las edades la ha llevado a desempe\u00f1ar funciones que van desde la educaci\u00f3n religiosa infantil hasta el consejo de administraci\u00f3n de la Escuela de Religi\u00f3n de Earlham. Adria es miembro del Meeting de Chatham-Summit (NYYM) en Chatham, N.J. Contacto: <em>shadowofbabylon.com<\/em>.  <\/p>\n"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3124802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3124802"}],"version-history":[{"count":1,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3124802\/revisions"}],"predecessor-version":[{"id":3124804,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3124802\/revisions\/3124804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3089654"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3124802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3124802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/tags?post=3124802"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3124802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}