{"id":3128722,"date":"2021-05-01T01:35:00","date_gmt":"2021-05-01T05:35:00","guid":{"rendered":"https:\/\/www.friendsjournal.org\/preservar-una-presencia-cuaquera-en-detroit\/"},"modified":"2025-10-12T09:49:17","modified_gmt":"2025-10-12T13:49:17","slug":"preservar-una-presencia-cuaquera-en-detroit","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/","title":{"rendered":"Preservar una presencia cu\u00e1quera en Detroit"},"content":{"rendered":"\n<p class=\"has-drop-cap wp-block-paragraph\">Durante los primeros 60 a\u00f1os de su existencia, el Meeting de Detroit (Michigan) no tuvo una casa de Meeting permanente, y celebr\u00f3 sus cultos principalmente en edificios propiedad de varias organizaciones sin \u00e1nimo de lucro, en una universidad e incluso en las casas de varios miembros. En la d\u00e9cada de 1980, tomando una posici\u00f3n en contra de la huida de la poblaci\u00f3n blanca, el Meeting compr\u00f3 y renov\u00f3 una antigua joyer\u00eda situada en una calle muy transitada de una zona industrial. El nuevo espacio ten\u00eda una rica sencillez, pero convertirlo en una casa de Meeting implic\u00f3 la instalaci\u00f3n de estanter\u00edas de madera, bancos enfrentados y mucho esfuerzo. Aunque el Meeting era peque\u00f1o, hab\u00eda un fuerte compromiso y entusiasmo por poseer un hogar espiritual que fuera de apoyo y acogedor para todas las personas en una comunidad predominantemente hispana.   <\/p>\n\n<p class=\"wp-block-paragraph\">Aunque era un lugar especial para el culto, la ubicaci\u00f3n presentaba retos \u00fanicos, as\u00ed como ricas oportunidades. El barrio circundante se deterior\u00f3 gradualmente y muchos negocios locales cerraron. Despu\u00e9s de que la tienda de tatuajes Pitbull Tattoo Parlor de al lado cerrara definitivamente, las tablas de sus ventanas y puertas fueron desalojadas por personas sin hogar de la zona que buscaban un refugio seguro.  <\/p>\n\n<p class=\"wp-block-paragraph\">Un fr\u00edo d\u00eda de invierno, un gran incendio destruy\u00f3 todo ese edificio de dos plantas. Al o\u00edr las noticias del incendio, los miembros pensaron en quienes se hab\u00edan refugiado all\u00ed. Nos sentimos aliviados al saber que no hubo v\u00edctimas. Solo la vieja pared de ladrillo de la casa de Meeting la separaba de la pared de la tienda de tatuajes. \u00a1Fue incre\u00edble que la casa de Meeting sobreviviera al incendio sin da\u00f1os!    <\/p>\n\n<p class=\"wp-block-paragraph\">Con la estructura vecina desaparecida, la pared de ladrillo rojo expuesta se convirti\u00f3 r\u00e1pidamente en un atractivo lienzo en blanco para varios grafiteros. Los miembros volvieron a pintar la pared dos veces para evitar pagar multas a la ciudad. El Meeting tambi\u00e9n contempl\u00f3 la posibilidad de encargar a un grafitero del barrio que pintara la pared, sabiendo que una obra firmada ser\u00eda respetada por los dem\u00e1s. Tras mucho discernimiento, reconocimos que la ciudad no aprobar\u00eda esto como soluci\u00f3n.   <\/p>\n\n<p class=\"wp-block-paragraph\">En numerosas ocasiones, la casa de Meeting fue asaltada y se robaron objetos: un aparato de aire acondicionado, escaleras, un reproductor de CD, ventiladores, cableado de cobre, peque\u00f1os electrodom\u00e9sticos de cocina e incluso las macetas del exterior. Un Primer D\u00eda, los miembros descubrieron que no hab\u00eda electricidad porque nuestro contador el\u00e9ctrico hab\u00eda sido robado esa semana. Tuvimos un memorable servicio de culto rodeados de oscuridad y un profundo silencio apacible. Durante este periodo, \u00a1nos dimos cuenta de que los \u00fanicos objetos que nunca desaparecieron fueron nuestra extensa colecci\u00f3n de preciados libros!   <\/p>\n\n<p class=\"wp-block-paragraph\">Cada a\u00f1o, el Meeting pagaba 450 d\u00f3lares por la recogida semanal de basura, pero los miembros a menudo transportaban y eliminaban la basura del Meeting en sus casas porque los contenedores de basura eran robados repetidamente. Los pagos por la recogida de basura llegaron a ser vistos como nuestra donaci\u00f3n a la ciudad. El Meeting no pod\u00eda permitirse un sistema de alarma, as\u00ed que intentamos instalar una c\u00e1mara falsa para disuadir futuros robos. Durante la instalaci\u00f3n, uno de nuestros miembros se cay\u00f3 de una escalera y se lesion\u00f3 el tobillo. Terminamos el proyecto ah\u00ed mismo.    <\/p>\n\n<p class=\"wp-block-paragraph\">Incluso con estos retos, la puerta principal siempre permaneci\u00f3 abierta, y los miembros desarrollaron un cari\u00f1o especial por esta antigua casa de Meeting. Apreci\u00e1bamos la comunidad que se hab\u00eda establecido a lo largo de los a\u00f1os y encontr\u00e1bamos humor al compartir estas experiencias juntos. Nunca propusimos mudarnos a otro lugar o fuera de la ciudad. Como Meeting, est\u00e1bamos y seguimos estando comprometidos con la ciudad de Detroit. A lo largo de la historia de Detroit, los cu\u00e1queros han sido una presencia comprometida con la justicia social. Detroit era \u201cMedianoche\u00bb en el Ferrocarril Subterr\u00e1neo, la \u00faltima parada en la huida hacia la libertad apoyada por los abolicionistas cu\u00e1queros que ayudaron a las personas que escapaban de la esclavitud a llegar a Detroit antes de cruzar a Canad\u00e1. Esta ciudad es nuestro hogar hist\u00f3rico y espiritual.      <\/p>\n\n<p class=\"wp-block-paragraph\">Hace casi una d\u00e9cada, el Meeting se dio cuenta de que el Estado de Michigan iba a tomar la propiedad de nuestra casa de Meeting por medio de un dominio eminente para construir un nuevo puente internacional entre Estados Unidos y Canad\u00e1. Aunque lamentamos esta p\u00e9rdida, el Estado nos asegur\u00f3 que la compensaci\u00f3n nos permitir\u00eda comprar un nuevo edificio y seguir siendo una fuerza para el cambio y la justicia social en esta ciudad tan castigada. <\/p>\n\n<p class=\"wp-block-paragraph\">El Meeting contrat\u00f3 a un conocido abogado de expropiaciones, que finalmente nos abandon\u00f3 como clientes tras sentirse frustrado con el proceso de toma de decisiones cu\u00e1quero. Durante las negociaciones, se nos dijo que a nuestra casa de Meeting no se le daba el mismo valor y estatus legal que a otras iglesias vecinas porque carec\u00eda de un altar y no se exhib\u00edan s\u00edmbolos religiosos. Esto fue extremadamente decepcionante de o\u00edr, y la norma fue vigorosamente impugnada por aquellos de nosotros presentes durante las negociaciones.  <\/p>\n\n<p class=\"wp-block-paragraph\">Finalmente, tras agotar todos los recursos, nos vimos obligados a aceptar la oferta del Estado por nuestra propiedad, d\u00e1ndonos cuenta de que esos fondos no nos permitir\u00edan trasladarnos a una estructura similar en la ciudad. Durante el largo proceso, los valores de las propiedades hab\u00edan aumentado sustancialmente a medida que inversores de todo el mundo llegaban a Detroit. <\/p>\n\n<p class=\"wp-block-paragraph\">El Meeting de Detroit simplemente ped\u00eda que se le resarciera de nuevo. En la \u00faltima d\u00e9cada, hab\u00edamos perdido tanto nuestra casa de Meeting como nuestra escuela. Fundada en 1965, la Friends School de Detroit fue una de las primeras escuelas privadas integradas de Detroit y hab\u00eda sido un signo visible de los valores cu\u00e1queros en la regi\u00f3n hasta su cierre en 2015. Su auge y ca\u00edda nos dieron la oportunidad de hablar m\u00e1s sobre los retos a los que nos hemos enfrentado y de afrontar el hecho de que ahora no hab\u00eda ninguna presencia f\u00edsica cu\u00e1quera permanente en la ciudad. Adem\u00e1s, \u00e9ramos dolorosamente conscientes de que el proceso de reubicaci\u00f3n se hab\u00eda convertido en una distracci\u00f3n espiritual para muchos de los asistentes.    <\/p>\n\n<hr class=\"wp-block-separator\"\/>\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_1-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"567\" src=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_1-2-1024x567.jpg\" alt=\"\" data-id=\"3055768\" data-full-url=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_1-2.jpg\" data-link=\"https:\/\/www.friendsjournal.org\/?attachment_id=3055768\" class=\"wp-image-3055768\" srcset=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_1-2-1024x567.jpg 1024w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_1-2-300x166.jpg 300w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_1-2-768x425.jpg 768w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_1-2-600x332.jpg 600w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_1-2.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_2-1024x566.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"566\" src=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_2-1024x566.jpg\" alt=\"\" data-id=\"3055763\" data-link=\"https:\/\/www.friendsjournal.org\/?attachment_id=3055763\" class=\"wp-image-3055763\" srcset=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_2-1024x566.jpg 1024w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_2-300x166.jpg 300w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_2-768x424.jpg 768w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_2-600x332.jpg 600w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_2.jpg 1055w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n<p class=\"has-text-align-center wp-block-paragraph\">Representaciones de la nueva casa de Meeting por la dise\u00f1adora Cassandra Keil; exterior (izquierda) e interior.<\/p>\n\n<hr class=\"wp-block-separator\"\/>\n\n<p class=\"wp-block-paragraph\">Mientras consideraba las posibilidades de reubicaci\u00f3n, el Meeting alquil\u00f3 un edificio propiedad de una iglesia metodista unida vecina durante dos a\u00f1os. En este lugar, \u00e9ramos m\u00e1s visibles y empezamos a atraer a nuevos asistentes de todas las edades cada mes. Pero una vez m\u00e1s, se nos pidi\u00f3 que nos mud\u00e1ramos: el edificio se iba a vender. Entonces lleg\u00f3 la pandemia y empezamos a celebrar el culto virtualmente, lo que ha aumentado la asistencia semanal en un 25 por ciento. Nuestro Meeting es un Meeting mensual internacional \u00fanico, con miembros y asistentes de Estados Unidos y Canad\u00e1.    <\/p>\n\n<p class=\"wp-block-paragraph\">Tras a\u00f1os de discernimiento e incertidumbre sobre el camino a seguir, nuestro Meeting ha decidido redoblar su compromiso con Detroit. Estamos en proceso de comprar terrenos a trav\u00e9s de la Autoridad del Banco de Tierras de Detroit en un barrio predominantemente negro, un reflejo de nuestra decisi\u00f3n de operar como una comunidad de fe antirracista. Prevemos que nuestra casa de Meeting de nueva construcci\u00f3n, energ\u00e9ticamente eficiente y de 232 metros cuadrados, sea un faro de Luz en la ciudad y un espacio compartido para los socios de la comunidad. Nos sorprendi\u00f3 gratamente saber que el representante del Banco de Tierras asignado a nuestro caso es un antiguo estudiante de la Friends School familiarizado con los cu\u00e1queros.   <\/p>\n\n<p class=\"wp-block-paragraph\">Nuestros 24 miembros, junto con un grupo fiel de asistentes, se han esforzado y seguir\u00e1n esforz\u00e1ndose para que una presencia cu\u00e1quera activa y empoderada pueda permanecer en Detroit. Con determinaci\u00f3n y fe, el Meeting de Detroit se compromete a garantizar que nuestra Luz colectiva siga brillando. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Meeting de Amigos de Detroit mira hacia el futuro en la nueva casa de Meeting.<\/p>\n","protected":false},"author":5090,"featured_media":3085507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9860],"tags":[12383,10915,10764,10756],"fpb_issue_category":[10680],"class_list":["post-3128722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-vida-en-la-junta","tag-canada","tag-comunidad","tag-cuaqueros","tag-proceso","fpb_issue_category-generaciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Preservar una presencia cu\u00e1quera en Detroit - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preservar una presencia cu\u00e1quera en Detroit\" \/>\n<meta property=\"og:description\" content=\"El Meeting de Amigos de Detroit mira hacia el futuro en la nueva casa de Meeting.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-01T05:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-12T13:49:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_featured.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"725\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Friends Journal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Preservar una presencia cu\u00e1quera en Detroit\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Friends Journal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/preservar-una-presencia-cuaquera-en-detroit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/preservar-una-presencia-cuaquera-en-detroit\\\/\"},\"author\":{\"name\":\"Friends Journal\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/315ffb22a36ecbabdf5dbdc09d7d1eb7\"},\"headline\":\"Preservar una presencia cu\u00e1quera en Detroit\",\"datePublished\":\"2021-05-01T05:35:00+00:00\",\"dateModified\":\"2025-10-12T13:49:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/preservar-una-presencia-cuaquera-en-detroit\\\/\"},\"wordCount\":1376,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/preservar-una-presencia-cuaquera-en-detroit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/LifeInMeeting_featured.jpg\",\"keywords\":[\"Canad\u00e1\",\"comunidad\",\"Cu\u00e1queros\",\"Proceso\"],\"articleSection\":[\"La vida en la junta\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/preservar-una-presencia-cuaquera-en-detroit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/preservar-una-presencia-cuaquera-en-detroit\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/preservar-una-presencia-cuaquera-en-detroit\\\/\",\"name\":\"Preservar una presencia cu\u00e1quera en Detroit - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/preservar-una-presencia-cuaquera-en-detroit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/preservar-una-presencia-cuaquera-en-detroit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/LifeInMeeting_featured.jpg\",\"datePublished\":\"2021-05-01T05:35:00+00:00\",\"dateModified\":\"2025-10-12T13:49:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/preservar-una-presencia-cuaquera-en-detroit\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/preservar-una-presencia-cuaquera-en-detroit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/preservar-una-presencia-cuaquera-en-detroit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/LifeInMeeting_featured.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/LifeInMeeting_featured.jpg\",\"width\":1400,\"height\":725,\"caption\":\"Antigua casa de Meeting en Fort Street en Detroit. Foto de Leslie Walden.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/preservar-una-presencia-cuaquera-en-detroit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Preservar una presencia cu\u00e1quera en Detroit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/315ffb22a36ecbabdf5dbdc09d7d1eb7\",\"name\":\"Friends Journal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g\",\"caption\":\"Friends Journal\"},\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/author\\\/alla-podolsky\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Preservar una presencia cu\u00e1quera en Detroit - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/","og_locale":"es_ES","og_type":"article","og_title":"Preservar una presencia cu\u00e1quera en Detroit","og_description":"El Meeting de Amigos de Detroit mira hacia el futuro en la nueva casa de Meeting.","og_url":"https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"2021-05-01T05:35:00+00:00","article_modified_time":"2025-10-12T13:49:17+00:00","og_image":[{"width":1400,"height":725,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_featured.jpg","type":"image\/jpeg"}],"author":"Friends Journal","twitter_card":"summary_large_image","twitter_title":"Preservar una presencia cu\u00e1quera en Detroit","twitter_creator":"@friendsournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"Friends Journal","Est. reading time":"7 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/"},"author":{"name":"Friends Journal","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/315ffb22a36ecbabdf5dbdc09d7d1eb7"},"headline":"Preservar una presencia cu\u00e1quera en Detroit","datePublished":"2021-05-01T05:35:00+00:00","dateModified":"2025-10-12T13:49:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/"},"wordCount":1376,"commentCount":0,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_featured.jpg","keywords":["Canad\u00e1","comunidad","Cu\u00e1queros","Proceso"],"articleSection":["La vida en la junta"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/","url":"https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/","name":"Preservar una presencia cu\u00e1quera en Detroit - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_featured.jpg","datePublished":"2021-05-01T05:35:00+00:00","dateModified":"2025-10-12T13:49:17+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_featured.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2021\/04\/LifeInMeeting_featured.jpg","width":1400,"height":725,"caption":"Antigua casa de Meeting en Fort Street en Detroit. Foto de Leslie Walden."},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/preservar-una-presencia-cuaquera-en-detroit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Preservar una presencia cu\u00e1quera en Detroit"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/315ffb22a36ecbabdf5dbdc09d7d1eb7","name":"Friends Journal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d068a76f0e4cdb5e89a047c27adb947f34ce284fc0a7d0bf77b0eb450771ae46?s=96&d=mm&r=g","caption":"Friends Journal"},"url":"https:\/\/www.friendsjournal.org\/es\/author\/alla-podolsky\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"author_name":"Sharon Ottenbreit y Kelsey Ronan","bio":"<p>Sharon Ottenbreit y Kelsey Ronan son miembros del Meeting de Detroit (Michigan). Sharon es co-secretaria del Meeting y antigua educadora. Kelsey es una nueva miembro, coordinadora del grupo de trabajo antirracista del Meeting y educadora en las escuelas p\u00fablicas de Detroit. Obt\u00e9n m\u00e1s informaci\u00f3n sobre la nueva casa de Meeting en <em>detroitfriendsmeeting.org<\/em>.   <\/p>\n"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3128722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/5090"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3128722"}],"version-history":[{"count":1,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3128722\/revisions"}],"predecessor-version":[{"id":3128724,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3128722\/revisions\/3128724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3085507"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3128722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3128722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/tags?post=3128722"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3128722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}