{"id":3130675,"date":"2018-05-01T02:25:50","date_gmt":"2018-05-01T06:25:50","guid":{"rendered":"https:\/\/www.friendsjournal.org\/vendiendo-el-cuaquerismo\/"},"modified":"2018-05-01T02:25:50","modified_gmt":"2018-05-01T06:25:50","slug":"vendiendo-el-cuaquerismo","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/","title":{"rendered":"Vendiendo el cuaquerismo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3029173\" src=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2018\/04\/hoopes.jpg\" alt=\"\" width=\"779\" height=\"438\" srcset=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2018\/04\/hoopes.jpg 779w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2018\/04\/hoopes-300x169.jpg 300w, https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2018\/04\/hoopes-768x432.jpg 768w\" sizes=\"auto, (max-width: 779px) 100vw, 779px\" \/><\/p>\n<h2><span style=\"font-weight: 400;\">La tensi\u00f3n misi\u00f3n-mercado inherente a los \u201cvalores cu\u00e1queros\u201d<\/span><\/h2>\n<p><span style=\"font-weight: 400;\"><span class=\"dropcap\">E<\/span><!--\/.dropcap-->n la Conferencia de Liderazgo Juvenil Cu\u00e1quero de este a\u00f1o, celebrada en Carolina Friends School, una docena de profesores de estudios religiosos de escuelas secundarias Friends nos reunimos para conversar sobre los significados de \u201cvalores cu\u00e1queros\u201d. Como grupo, afirmamos la tensi\u00f3n generativa entre las misiones de nuestras instituciones, con base espiritual, y las exigencias de sus mercados competitivos. \u00bfC\u00f3mo vendemos la \u201cmarca\u201d cu\u00e1quera sin vendernos?  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Considero que la tensi\u00f3n misi\u00f3n-mercado de la educaci\u00f3n Friends es bastante valiosa, ya que nos obliga continuamente a analizar detenidamente lo que estamos haciendo y a basarlo en las realidades de lo que las familias realmente quieren y est\u00e1n dispuestas a pagar. En las escuelas Friends, la misi\u00f3n y el mercado se informan y se desaf\u00edan mutuamente. Si no somos fieles a nuestra misi\u00f3n de dar testimonio de lo Divino en cada persona, \u00bfpor qu\u00e9 molestarnos siquiera en llamarnos \u201ccu\u00e1queros\u201d? Y, al mismo tiempo, si estamos tan absortos en nuestras propias interpretaciones parroquiales de la fidelidad, sin sensibilidad a las necesidades y deseos de nuestras familias, r\u00e1pidamente quebraremos.   <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><span class=\"dropcap\">L<\/span><!--\/.dropcap-->a Sociedad Religiosa de los Amigos se enfrenta a un dilema similar. Muchos cu\u00e1queros no programados, sin embargo, no han entendido que su religi\u00f3n debe responder a ning\u00fan tipo de mercado. En consecuencia, el n\u00famero de personas en los Meetings afiliados a la Friends General Conference (FGC) en los Estados Unidos disminuy\u00f3 constantemente a lo largo del siglo XX, y esa tendencia contin\u00faa en la actualidad. Amigos: estamos a punto de quebrar. Creo que har\u00edamos bien en explorar los \u201cvalores cu\u00e1queros\u201d y preguntarnos si esta es una de las formas en que queremos describirnos, o no.    <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Trabajo y ense\u00f1o en las cercan\u00edas de Filadelfia, donde la \u201cmarca\u201d cu\u00e1quera sigue siendo relativamente fuerte y se asocia ampliamente con juicios positivos. En otras partes de nuestro pa\u00eds, las escuelas Friends a menudo necesitan trabajar m\u00e1s duro para diferenciarse de sus otros competidores de base religiosa y de las escuelas p\u00fablicas locales. Es comprensible que los \u201cvalores cu\u00e1queros\u201d se hayan convertido en una abreviatura de marketing. Esta abreviatura transmite r\u00e1pidamente las ideas de lo sagrado en cada persona, el respeto por todas las personas, la resoluci\u00f3n pac\u00edfica de conflictos, la b\u00fasqueda de la verdad, la sencillez y el compromiso con el servicio y la administraci\u00f3n. Esta es una lista hermosa, y me siento atra\u00eddo por ella. Pero me preocupa la implicaci\u00f3n de que este paquete de valores es exclusivamente competencia del cuaquerismo. Mi propia experiencia me lleva a creer que puedo encontrar esos mismos valores entre muchos grupos relacionados con el juda\u00edsmo reformado, el islamismo suf\u00ed, el catolicismo jesuita, el budismo vipassana, etc., por no mencionar el Morris dancing, el ultimate frisbee y el activismo loc\u00e1voro. En consecuencia, llamar a estos \u201cvalores cu\u00e1queros\u201d plantea algunas preguntas para m\u00ed.       <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><span class=\"dropcap\">A<\/span><!--\/.dropcap-->l decir \u201cvalores cu\u00e1queros\u201d, estamos aprovechando lo que creemos que es una asociaci\u00f3n positiva con el nombre de nuestra sociedad religiosa experimental, precisamente de la misma manera que lo hizo el fundador de Quaker Oats en 1877. Hoy en d\u00eda, hay muchas empresas que utilizan la palabra \u201cQuaker\u201d en sus t\u00edtulos como una forma de comerciar con nuestra reputaci\u00f3n: Quaker State Motor Oil, Quaker Steak &amp; Lube, Quaker Taxi, Quaker Towing, etc. Esto es una selecci\u00f3n selectiva, sin duda, pero \u00bfen qu\u00e9 se diferencia de nuestro dicho \u201cvalores cu\u00e1queros\u201d? Sospecho que cuando dicen \u201cvalores cu\u00e1queros\u201d, los anunciantes no se refieren a nuestros m\u00e1s de 100 a\u00f1os de esclavitud, ni a la participaci\u00f3n activa de los cu\u00e1queros en el genocidio europeo de los pueblos nativos de Am\u00e9rica, ni en la perpetuaci\u00f3n de la supremac\u00eda blanca que sigue plagando los Meetings cu\u00e1queros en los Estados Unidos.   <\/span><\/p>\n<p><span style=\"font-weight: 400;\">De hecho, me pregunto c\u00f3mo se sienten otros Amigos cuando escuchan frases como \u201cvalores cristianos\u201d, \u201cvalores cat\u00f3licos\u201d, \u201cvalores musulmanes\u201d, \u201cvalores jud\u00edos\u201d, \u201cvalores estadounidenses\u201d, y as\u00ed sucesivamente. Me resisto a esas frases hechas, porque parecen implicar que cada una de esas tradiciones puede reclamar alg\u00fan tipo de propiedad monop\u00f3lica sobre un conjunto de valores humanos. No solo esas afirmaciones se falsifican f\u00e1cilmente, sino que sugieren la existencia de un conjunto normativo de preceptos que hacen que su particular identidad tribal sea excepcional.  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00bfRealmente queremos los Amigos acorralarnos en esa esquina? Una implicaci\u00f3n particularmente problem\u00e1tica de esta construcci\u00f3n es que impone una din\u00e1mica de poder a expensas de aquellos que no se sienten bienvenidos en el club. Por ejemplo, reflexiono sobre el n\u00famero de veces que he estado en una reuni\u00f3n cu\u00e1quera y personas blancas bien intencionadas han estado hablando sobre el racismo dentro de la Sociedad de los Amigos. Cuando una persona blanca usa el pronombre \u201cnosotros\u201d para denotar a todos los Amigos, en contraste con \u201cellos\u201d en referencia a los Amigos afroamericanos, sin darse cuenta, est\u00e1n reificando la supremac\u00eda blanca incluso cuando piensan que la est\u00e1n criticando. Esto ilustra la creencia impl\u00edcita del hablante sobre qui\u00e9nes somos \u201cnosotros\u201d, a saber, una religi\u00f3n blanca. Ay. \u00bfNo estamos cometiendo un error similar cuando usamos la frase \u201cvalores cu\u00e1queros\u201d y pensamos que estamos implicando solo los valores que nos gustan, no los que preferir\u00edamos no pensar? Por ejemplo, la rigidez, la represi\u00f3n sexual, la afici\u00f3n a la observaci\u00f3n de aves y una relaci\u00f3n profundamente ansiosa con la m\u00fasica con ritmo fueron una parte fundamental de mi educaci\u00f3n cu\u00e1quera. \u00bfEstamos incluyendo esos en los \u201cvalores cu\u00e1queros\u201d? Sospecho que no.         <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">\u00bf<span class=\"dropcap\">C<\/span><!--\/.dropcap-->\u00f3mo, entonces, nos diferenciaremos y comunicaremos con aquellos que no est\u00e1n familiarizados con el cuaquerismo? En primer lugar, creo que debemos aferrarnos a la palabra \u201ccu\u00e1quero\u201d y esforzarnos continuamente por comportarnos de una manera que nos haga dignos de nuestro todav\u00eda buen nombre. Desde ese lugar, podemos usar cualquier n\u00famero de descriptores que no suenen tan altivos y miopes. Creo que deber\u00edamos levantar continuamente algunas piezas clave de vocabulario que realmente hacen que el camino cu\u00e1quero sea distintivo. Aqu\u00ed hay una breve lista, a la que estoy seguro de que los Amigos pueden agregar otros: \u201clo de Dios en cada persona\u201d; \u201cla Luz Interior\u201d; \u201crevelaci\u00f3n continua\u201d; \u201cdiscernimiento\u201d; \u201csentido del Meeting\u201d; \u201cbien guiado y bien ordenado\u201d; \u201cFriend dice lo que pienso\u201d; \u201cla voz suave y apacible interior\u201d; \u201ccamino que se abre\u201d; \u201csecretar\u00eda\u201d; \u201cconsulta\u201d; \u201ccompartir la adoraci\u00f3n\u201d; \u201cespera expectante\u201d; \u201ccentrarse\u201d; \u201ctoma de decisiones cu\u00e1quera\u201d; \u201ctradici\u00f3n cu\u00e1quera\u201d; \u201cfe y pr\u00e1ctica\u201d; \u201cb\u00fasqueda de claridad\u201d; \u201ctestimonios cu\u00e1queros\u201d; y, por supuesto, \u201cMeeting de adoraci\u00f3n\u201d. Cada una de estas piezas de terminolog\u00eda tiene un lugar especial en el discurso cu\u00e1quero, y abre una conversaci\u00f3n que deber\u00edamos acoger con satisfacci\u00f3n.     <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cuando concluimos nuestra conversaci\u00f3n en la Conferencia de Liderazgo Juvenil Cu\u00e1quero, desarrollamos algunas consultas para enmarcar este discurso. Una que se relaciona especialmente con este tema es: \u201c\u00bfA qui\u00e9nes queremos que se unan a nuestras escuelas y c\u00f3mo honramos la Luz en ellos\u201d? A eso agregar\u00eda: \u201c\u00bfHasta qu\u00e9 punto estamos preparados para cambiar, para reflejar la revelaci\u00f3n continua de nuestra comunidad en constante cambio\u201d? Cada uno de nosotros, los maestros, se comprometi\u00f3 a continuar esta conversaci\u00f3n en nuestras respectivas comunidades escolares. En algunas, el t\u00e9rmino \u201cvalores cu\u00e1queros\u201d ya est\u00e1 consagrado en las declaraciones de misi\u00f3n, los planes estrat\u00e9gicos, los sitios web y los elaborados esquemas de marketing. No obstante, la conversaci\u00f3n sigue siendo crucial para nuestra identidad en este momento de la historia. As\u00ed como los primeros Amigos se ve\u00edan a s\u00ed mismos como \u201chijos de la Luz\u201d y \u201cbuscadores\u201d en busca de la obediencia sagrada, en nuestro mejor momento estamos en un viaje de descubrimiento. Para citar a Irene McHenry, la ex directora ejecutiva del Friends Council on Education:       <\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">La educaci\u00f3n Friends proporciona un contenedor seguro para la exploraci\u00f3n. Pienso en este contenedor como un esp\u00edritu de amor feroz. La base es el Amor Infinito en el que todos podemos ser renovados. La \u201cferocidad\u201d es evidente a trav\u00e9s del poder de la intenci\u00f3n, el poder de abrazar la tensi\u00f3n, de tomar una posici\u00f3n moral, de no rendirse.   <\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">No nos rindamos, Amigos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tensi\u00f3n misi\u00f3n-mercado inherente a los valores cu\u00e1queros<\/p>\n","protected":false},"author":3,"featured_media":3080306,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9799],"tags":[22542,22666,22665,10865,10764,10988,10768,10854,10920,9783,22667],"fpb_issue_category":[10648],"class_list":["post-3130675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronicas","tag-amigos-afroamericanos","tag-catolicismo-jesuita","tag-conferencia-de-liderazgo-juvenil-cuaquero","tag-cuaquerismo","tag-cuaqueros","tag-estados-unidos","tag-marketing","tag-numero","tag-persona","tag-uso","tag-vendiendo-el-cuaquerismo","fpb_issue_category-cuales-son-los-valores-cuaqueros-de-todos-modos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vendiendo el cuaquerismo - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vendiendo el cuaquerismo - Friends Journal\" \/>\n<meta property=\"og:description\" content=\"La tensi\u00f3n misi\u00f3n-mercado inherente a los valores cu\u00e1queros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-01T06:25:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2018\/04\/hoopes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"779\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Kelley\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsjournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Kelley\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/vendiendo-el-cuaquerismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/vendiendo-el-cuaquerismo\\\/\"},\"author\":{\"name\":\"Martin Kelley\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/7ed35dbed87f6eb86c60eeb3e20e078e\"},\"headline\":\"Vendiendo el cuaquerismo\",\"datePublished\":\"2018-05-01T06:25:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/vendiendo-el-cuaquerismo\\\/\"},\"wordCount\":1443,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/vendiendo-el-cuaquerismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/hoopes.jpg\",\"keywords\":[\"Amigos afroamericanos\",\"Catolicismo jesuita\",\"Conferencia de liderazgo juvenil cu\u00e1quero\",\"Cuaquerismo\",\"Cu\u00e1queros\",\"Estados Unidos\",\"marketing\",\"n\u00famero\",\"persona\",\"uso\",\"Vendiendo el cuaquerismo\"],\"articleSection\":[\"cr\u00f3nicas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/vendiendo-el-cuaquerismo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/vendiendo-el-cuaquerismo\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/vendiendo-el-cuaquerismo\\\/\",\"name\":\"Vendiendo el cuaquerismo - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/vendiendo-el-cuaquerismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/vendiendo-el-cuaquerismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/hoopes.jpg\",\"datePublished\":\"2018-05-01T06:25:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/vendiendo-el-cuaquerismo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/vendiendo-el-cuaquerismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/vendiendo-el-cuaquerismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/hoopes.jpg\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/hoopes.jpg\",\"width\":779,\"height\":438},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/vendiendo-el-cuaquerismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vendiendo el cuaquerismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"name\":\"Friends Journal\",\"description\":\"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/#\\\/schema\\\/person\\\/7ed35dbed87f6eb86c60eeb3e20e078e\",\"name\":\"Martin Kelley\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73c5649dadaf46c4891d23d2368860a1c1117699ed6a4fa439414de35b8da588?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73c5649dadaf46c4891d23d2368860a1c1117699ed6a4fa439414de35b8da588?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73c5649dadaf46c4891d23d2368860a1c1117699ed6a4fa439414de35b8da588?s=96&d=mm&r=g\",\"caption\":\"Martin Kelley\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/friendsjournal\"],\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/es\\\/author\\\/martink\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vendiendo el cuaquerismo - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/","og_locale":"es_ES","og_type":"article","og_title":"Vendiendo el cuaquerismo - Friends Journal","og_description":"La tensi\u00f3n misi\u00f3n-mercado inherente a los valores cu\u00e1queros","og_url":"https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"2018-05-01T06:25:50+00:00","og_image":[{"width":779,"height":438,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2018\/04\/hoopes.jpg","type":"image\/jpeg"}],"author":"Martin Kelley","twitter_card":"summary_large_image","twitter_creator":"@friendsjournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"Martin Kelley","Est. reading time":"7 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/"},"author":{"name":"Martin Kelley","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/7ed35dbed87f6eb86c60eeb3e20e078e"},"headline":"Vendiendo el cuaquerismo","datePublished":"2018-05-01T06:25:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/"},"wordCount":1443,"commentCount":0,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2018\/04\/hoopes.jpg","keywords":["Amigos afroamericanos","Catolicismo jesuita","Conferencia de liderazgo juvenil cu\u00e1quero","Cuaquerismo","Cu\u00e1queros","Estados Unidos","marketing","n\u00famero","persona","uso","Vendiendo el cuaquerismo"],"articleSection":["cr\u00f3nicas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/","url":"https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/","name":"Vendiendo el cuaquerismo - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/#primaryimage"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2018\/04\/hoopes.jpg","datePublished":"2018-05-01T06:25:50+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/#primaryimage","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2018\/04\/hoopes.jpg","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2018\/04\/hoopes.jpg","width":779,"height":438},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/es\/vendiendo-el-cuaquerismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Vendiendo el cuaquerismo"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/es\/#website","url":"https:\/\/www.friendsjournal.org\/es\/","name":"Friends Journal","description":"Comunicar la experiencia cu\u00e1quera para conectar y profundizar en la vida espiritual","publisher":{"@id":"https:\/\/www.friendsjournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/es\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/es\/#\/schema\/person\/7ed35dbed87f6eb86c60eeb3e20e078e","name":"Martin Kelley","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/73c5649dadaf46c4891d23d2368860a1c1117699ed6a4fa439414de35b8da588?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/73c5649dadaf46c4891d23d2368860a1c1117699ed6a4fa439414de35b8da588?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/73c5649dadaf46c4891d23d2368860a1c1117699ed6a4fa439414de35b8da588?s=96&d=mm&r=g","caption":"Martin Kelley"},"sameAs":["https:\/\/x.com\/friendsjournal"],"url":"https:\/\/www.friendsjournal.org\/es\/author\/martink\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/es\/","push-errors":false,"acf":{"author_name":"Tom Hoopes","bio":"<p>Tom Hoopes es miembro del Valley Meeting en Valley Forge, Pensilvania, y secretario suplente del Philadelphia Yearly Meeting. Trabaja como jefe del departamento de religiones en George School y es secretario del comit\u00e9 escolar de Plymouth Meeting Friends School. <\/p>\n"},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3130675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/comments?post=3130675"}],"version-history":[{"count":0,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/posts\/3130675\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media\/3080306"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/media?parent=3130675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/categories?post=3130675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/tags?post=3130675"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/es\/wp-json\/wp\/v2\/fpb_issue_category?post=3130675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}