{"id":3112209,"date":"1989-11-01T00:00:46","date_gmt":"1989-11-01T05:00:46","guid":{"rendered":"https:\/\/www.friendsjournal.org\/pacifist-kama-raia\/"},"modified":"1989-11-01T00:00:46","modified_gmt":"1989-11-01T05:00:46","slug":"pacifist-kama-raia","status":"publish","type":"post","link":"https:\/\/www.friendsjournal.org\/sw\/pacifist-kama-raia\/","title":{"rendered":"Pacifist kama Raia"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":409,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"fpb_issue_category":[],"class_list":["post-3112209","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pacifist kama Raia - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/sw\/pacifist-kama-raia\/\" \/>\n<meta property=\"og:locale\" content=\"sw_KE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pacifist kama Raia - Friends Journal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/sw\/pacifist-kama-raia\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/friendsjournal\/\" \/>\n<meta property=\"article:published_time\" content=\"1989-11-01T05:00:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"779\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DougStern\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"DougStern\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/pacifist-kama-raia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/pacifist-kama-raia\\\/\"},\"author\":{\"name\":\"DougStern\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/#\\\/schema\\\/person\\\/eb05ac8f0a7d61514db317f1bbdf1b5b\"},\"headline\":\"Pacifist kama Raia\",\"datePublished\":\"1989-11-01T05:00:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/pacifist-kama-raia\\\/\"},\"wordCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/#organization\"},\"inLanguage\":\"sw-KE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/pacifist-kama-raia\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/pacifist-kama-raia\\\/\",\"name\":\"Pacifist kama Raia - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/#website\"},\"datePublished\":\"1989-11-01T05:00:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/pacifist-kama-raia\\\/#breadcrumb\"},\"inLanguage\":\"sw-KE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/pacifist-kama-raia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/pacifist-kama-raia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/nyumbani\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pacifist kama Raia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/\",\"name\":\"Friends Journal\",\"description\":\"Kuwasiliana na uzoefu wa Quaker ili kuunganisha na kuimarisha maisha ya kiroho\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sw-KE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sw-KE\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/#\\\/schema\\\/person\\\/eb05ac8f0a7d61514db317f1bbdf1b5b\",\"name\":\"DougStern\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sw-KE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"DougStern\"},\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/author\\\/dougstern\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pacifist kama Raia - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/sw\/pacifist-kama-raia\/","og_locale":"sw_KE","og_type":"article","og_title":"Pacifist kama Raia - Friends Journal","og_url":"https:\/\/www.friendsjournal.org\/sw\/pacifist-kama-raia\/","og_site_name":"Friends Journal","article_publisher":"https:\/\/www.facebook.com\/friendsjournal\/","article_published_time":"1989-11-01T05:00:46+00:00","og_image":[{"width":779,"height":438,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg","type":"image\/jpeg"}],"author":"DougStern","twitter_card":"summary_large_image","twitter_creator":"@friendsournal","twitter_site":"@friendsournal","twitter_misc":{"Written by":"DougStern"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.friendsjournal.org\/sw\/pacifist-kama-raia\/#article","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/sw\/pacifist-kama-raia\/"},"author":{"name":"DougStern","@id":"https:\/\/www.friendsjournal.org\/sw\/#\/schema\/person\/eb05ac8f0a7d61514db317f1bbdf1b5b"},"headline":"Pacifist kama Raia","datePublished":"1989-11-01T05:00:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.friendsjournal.org\/sw\/pacifist-kama-raia\/"},"wordCount":3,"publisher":{"@id":"https:\/\/www.friendsjournal.org\/sw\/#organization"},"inLanguage":"sw-KE"},{"@type":"WebPage","@id":"https:\/\/www.friendsjournal.org\/sw\/pacifist-kama-raia\/","url":"https:\/\/www.friendsjournal.org\/sw\/pacifist-kama-raia\/","name":"Pacifist kama Raia - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/sw\/#website"},"datePublished":"1989-11-01T05:00:46+00:00","breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/sw\/pacifist-kama-raia\/#breadcrumb"},"inLanguage":"sw-KE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.friendsjournal.org\/sw\/pacifist-kama-raia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/sw\/pacifist-kama-raia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/sw\/nyumbani\/"},{"@type":"ListItem","position":2,"name":"Pacifist kama Raia"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/sw\/#website","url":"https:\/\/www.friendsjournal.org\/sw\/","name":"Friends Journal","description":"Kuwasiliana na uzoefu wa Quaker ili kuunganisha na kuimarisha maisha ya kiroho","publisher":{"@id":"https:\/\/www.friendsjournal.org\/sw\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/sw\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sw-KE"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/sw\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/sw\/","logo":{"@type":"ImageObject","inLanguage":"sw-KE","@id":"https:\/\/www.friendsjournal.org\/sw\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/sw\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]},{"@type":"Person","@id":"https:\/\/www.friendsjournal.org\/sw\/#\/schema\/person\/eb05ac8f0a7d61514db317f1bbdf1b5b","name":"DougStern","image":{"@type":"ImageObject","inLanguage":"sw-KE","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"DougStern"},"url":"https:\/\/www.friendsjournal.org\/sw\/author\/dougstern\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Friends Journal","distributor_original_site_url":"https:\/\/www.friendsjournal.org\/sw\/","push-errors":false,"acf":{"fpb_author_profile_picture":null,"author_name":"Elise Boulding","bio":null,"issue":null,"issue_path":null,"page_number":null,"fpb_display_featured_image":null,"fj_schema_markup":null},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/sw\/wp-json\/wp\/v2\/posts\/3112209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/sw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/sw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/sw\/wp-json\/wp\/v2\/users\/409"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friendsjournal.org\/sw\/wp-json\/wp\/v2\/comments?post=3112209"}],"version-history":[{"count":0,"href":"https:\/\/www.friendsjournal.org\/sw\/wp-json\/wp\/v2\/posts\/3112209\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.friendsjournal.org\/sw\/wp-json\/wp\/v2\/media?parent=3112209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/sw\/wp-json\/wp\/v2\/categories?post=3112209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/sw\/wp-json\/wp\/v2\/tags?post=3112209"},{"taxonomy":"fpb_issue_category","embeddable":true,"href":"https:\/\/www.friendsjournal.org\/sw\/wp-json\/wp\/v2\/fpb_issue_category?post=3112209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}