{"id":13973,"count":1,"description":"","link":"https:\/\/www.friendsjournal.org\/sw\/tag\/glenn-ravdin\/","name":"Glenn Ravdin","slug":"glenn-ravdin","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Glenn Ravdin Archives - Friends Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.friendsjournal.org\/sw\/tag\/glenn-ravdin\/\" \/>\n<meta property=\"og:locale\" content=\"sw_KE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Glenn Ravdin Archives - Friends Journal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.friendsjournal.org\/sw\/tag\/glenn-ravdin\/\" \/>\n<meta property=\"og:site_name\" content=\"Friends Journal\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"779\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@friendsournal\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/tag\\\/glenn-ravdin\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/tag\\\/glenn-ravdin\\\/\",\"name\":\"Glenn Ravdin Archives - Friends Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/tag\\\/glenn-ravdin\\\/#breadcrumb\"},\"inLanguage\":\"sw-KE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/tag\\\/glenn-ravdin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/nyumbani\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glenn Ravdin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/#website\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/\",\"name\":\"Friends Journal\",\"description\":\"Kuwasiliana na uzoefu wa Quaker ili kuunganisha na kuimarisha maisha ya kiroho\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sw-KE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/#organization\",\"name\":\"Friends Journal\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sw-KE\",\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/www.friendsjournal.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fj-logo-white.png\",\"width\":617,\"height\":74,\"caption\":\"Friends Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.friendsjournal.org\\\/sw\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/friendsjournal\\\/\",\"https:\\\/\\\/x.com\\\/friendsournal\",\"https:\\\/\\\/instagram.com\\\/friendsjournal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3154709\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/friendsjournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Glenn Ravdin Archives - Friends Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.friendsjournal.org\/sw\/tag\/glenn-ravdin\/","og_locale":"sw_KE","og_type":"article","og_title":"Glenn Ravdin Archives - Friends Journal","og_url":"https:\/\/www.friendsjournal.org\/sw\/tag\/glenn-ravdin\/","og_site_name":"Friends Journal","og_image":[{"width":779,"height":438,"url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2020\/07\/FJ_generic_featured_FINAL.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@friendsournal","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.friendsjournal.org\/sw\/tag\/glenn-ravdin\/","url":"https:\/\/www.friendsjournal.org\/sw\/tag\/glenn-ravdin\/","name":"Glenn Ravdin Archives - Friends Journal","isPartOf":{"@id":"https:\/\/www.friendsjournal.org\/sw\/#website"},"breadcrumb":{"@id":"https:\/\/www.friendsjournal.org\/sw\/tag\/glenn-ravdin\/#breadcrumb"},"inLanguage":"sw-KE"},{"@type":"BreadcrumbList","@id":"https:\/\/www.friendsjournal.org\/sw\/tag\/glenn-ravdin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.friendsjournal.org\/sw\/nyumbani\/"},{"@type":"ListItem","position":2,"name":"Glenn Ravdin"}]},{"@type":"WebSite","@id":"https:\/\/www.friendsjournal.org\/sw\/#website","url":"https:\/\/www.friendsjournal.org\/sw\/","name":"Friends Journal","description":"Kuwasiliana na uzoefu wa Quaker ili kuunganisha na kuimarisha maisha ya kiroho","publisher":{"@id":"https:\/\/www.friendsjournal.org\/sw\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.friendsjournal.org\/sw\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sw-KE"},{"@type":"Organization","@id":"https:\/\/www.friendsjournal.org\/sw\/#organization","name":"Friends Journal","url":"https:\/\/www.friendsjournal.org\/sw\/","logo":{"@type":"ImageObject","inLanguage":"sw-KE","@id":"https:\/\/www.friendsjournal.org\/sw\/#\/schema\/logo\/image\/","url":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","contentUrl":"https:\/\/www.friendsjournal.org\/wp-content\/uploads\/2025\/08\/fj-logo-white.png","width":617,"height":74,"caption":"Friends Journal"},"image":{"@id":"https:\/\/www.friendsjournal.org\/sw\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/friendsjournal\/","https:\/\/x.com\/friendsournal","https:\/\/instagram.com\/friendsjournal","https:\/\/www.linkedin.com\/company\/3154709","https:\/\/www.youtube.com\/user\/friendsjournal"]}]}},"_links":{"self":[{"href":"https:\/\/www.friendsjournal.org\/sw\/wp-json\/wp\/v2\/tags\/13973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friendsjournal.org\/sw\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.friendsjournal.org\/sw\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.friendsjournal.org\/sw\/wp-json\/wp\/v2\/posts?tags=13973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}